{"id":85140,"date":"2026-05-13T00:01:00","date_gmt":"2026-05-13T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=85140"},"modified":"2026-05-12T16:26:02","modified_gmt":"2026-05-12T22:26:02","slug":"efemerides-13-de-mayo-un-dia-como-hoy-en-la-historia","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/efemerides-13-de-mayo-un-dia-como-hoy-en-la-historia\/","title":{"rendered":"Efem\u00e9rides 13 de mayo | Un d\u00eda como hoy en la historia&#8230;"},"content":{"rendered":"\n<p><em>Un d\u00eda 13 de mayo como hoy, pero de 1917, tres pastorcillos portugueses confiesan haber visto a la Virgen en una cueva de la Sierra de la Estrella, origen de la devoci\u00f3n a Nuestra Se\u00f1ora de F\u00e1tima. Cien a\u00f1os despu\u00e9s, en 2017, el Papa Francisco proclam\u00f3 santos en F\u00e1tima a los pastorcillos Jacinta y Francisco<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/05\/1917-tres-pastorcillos-portugueses-confiesan-haber-visto-a-la-Virgen-en-una-cueva-de-la-Sierra-de-la-Estrella-origen-de-la-devocion-a-Nuestra-Senora-de-Fatima.avif\" alt=\"1917, tres pastorcillos portugueses confiesan haber visto a la virgen en una cueva de la sierra de la estrella, origen de la devocio\u0301n a nuestra sen\u0303ora de fa\u0301tima\" class=\"wp-image-85142\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/05\/1917-tres-pastorcillos-portugueses-confiesan-haber-visto-a-la-Virgen-en-una-cueva-de-la-Sierra-de-la-Estrella-origen-de-la-devocion-a-Nuestra-Senora-de-Fatima.avif 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/05\/1917-tres-pastorcillos-portugueses-confiesan-haber-visto-a-la-Virgen-en-una-cueva-de-la-Sierra-de-la-Estrella-origen-de-la-devocion-a-Nuestra-Senora-de-Fatima-300x200.avif 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p><strong>Otras efem\u00e9rides<\/strong><\/p>\n\n\n\n<p>1418.- Juan II de Castilla y el Papa Martino V firman el primer concordato de la historia de Espa\u00f1a.<\/p>\n\n\n\n<p>1647.- Un fuerte terremoto destruye Santiago de Chile. Sus efectos se extendieron desde Cuzco hasta Valdivia, y por oriente hasta Cuyo.<\/p>\n\n\n\n<p>1830.- Ecuador se independiza de La Gran Colombia.<\/p>\n\n\n\n<p>1846.- El presidente de EEUU, James Polk, ordena al general Taylor la ocupaci\u00f3n de la zona entre los r\u00edos Nueces y Bravo del Norte, que M\u00e9xico consideraba territorio suyo, con lo que comienza la guerra entre ambos pa\u00edses.<\/p>\n\n\n\n<p>1888.- Se suprime la esclavitud en Brasil.<\/p>\n\n\n\n<p>1930.- El aviador franc\u00e9s Jean Mermoz aterriza en Natal (Brasil), despu\u00e9s de cruzar el Atl\u00e1ntico en 21 horas y 12 minutos.<\/p>\n\n\n\n<p>1940.- Segunda Guerra Mundial: la reina Guillermina de Holanda se traslada a Londres ante el avance alem\u00e1n.<\/p>\n\n\n\n<p>1942.- En M\u00e9xico, los nazis hunden el petrolero Potrero del Llano, motivo por el cual M\u00e9xico entra en la II Guerra Mundial.<\/p>\n\n\n\n<p>1943.- Capitulaci\u00f3n del \u00abAfrika Korps\u00bb en T\u00fanez. El mariscal Rommel concluye su campa\u00f1a de \u00c1frica, tras rendirse las tropas germano-italianas tres d\u00edas antes.<\/p>\n\n\n\n<p>1950.- Se celebra la primera carrera de F\u00f3rmula 1, en el circuito de Silverstone (Reino Unido).<\/p>\n\n\n\n<p>1960.- EEUU lanza el \u00abEcho\u00bb, primer sat\u00e9lite pasivo de comunicaciones.<\/p>\n\n\n\n<p>1981.- El Papa Juan Pablo II resulta herido en un atentado en la plaza de San Pedro, en Roma, por el turco Al\u00ed Agca.<\/p>\n\n\n\n<p>1989.- Ecuador y Per\u00fa ponen fin a d\u00e9cadas de disputas por su demarcaci\u00f3n fronteriza, al delimitarla por primera vez en su historia.<\/p>\n\n\n\n<p>1992.- El Parlamento de Ucrania anula la declaraci\u00f3n de independencia de Crimea, aprobada una semana antes por el Legislativo regional.<\/p>\n\n\n\n<p>1993.- Ezer Weizman jura como s\u00e9ptimo presidente de Israel.<\/p>\n\n\n\n<p>1994.- El escritor mexicano Carlos Fuentes es galardonado con el Premio Pr\u00edncipe de Asturias de las Letras.<\/p>\n\n\n\n<p>1994.- Tras 27 a\u00f1os de ocupaci\u00f3n, Israel traspasa el control total de Jeric\u00f3 a los palestinos.<\/p>\n\n\n\n<p>1995.- La brit\u00e1nica Alison Hargreaves se convierte en la primera mujer que corona el Everest sin ox\u00edgeno y sin ayuda de sherpas.<\/p>\n\n\n\n<p>1999.- El Pr\u00edncipe de Asturias, Felipe de Borb\u00f3n, entrega el Premio Bartolom\u00e9 de las Casas, concedido \u00abex aequo\u00bb, al Congreso General Kuna de Panam\u00e1 y al escritor mexicano Natalio Hern\u00e1ndez.<\/p>\n\n\n\n<p>2003.- La Corte Suprema de Per\u00fa encuentra responsable al ex presidente Fujimori del asesinato de 26 personas en las matanzas de Barrios Altos y La Cantuta, por lo que pide a Jap\u00f3n su extradici\u00f3n.<\/p>\n\n\n\n<p>2008.- M\u00e1s de setenta personas mueren al explotar ocho bombas en la ciudad india de Jaipur, capital del estado de Rajsat\u00e1n.<\/p>\n\n\n\n<p>2009.- La Comisi\u00f3n Europea multa con 1.060 millones de euros al fabricante de microprocesadores Intel por abuso de posici\u00f3n dominante.<\/p>\n\n\n\n<p>2009.- Descubrimiento en Alemania de la venus mas antigua del mundo (40.000 a\u00f1os).<\/p>\n\n\n\n<p>2014.- El Tribunal de Justicia de la UE falla contra el buscador Google y respalda el \u00abderecho al olvido\u00bb en Internet.<\/p>\n\n\n\n<p>2014.- Mueren 301 mineros en el mayor accidente laboral de la historia moderna de Turqu\u00eda.<\/p>\n\n\n\n<p>2016.- Procesan a la expresidenta Cristina Fern\u00e1ndez por presunto perjuicio econ\u00f3mico a la Argentina.<\/p>\n\n\n\n<p>2017.- El Papa Francisco proclama santos en F\u00e1tima a los pastorcillos Jacinta y Francisco.<\/p>\n\n\n\n<p>2019.- Guerra comercial: China anuncia que impondr\u00e1 aranceles a bienes de EEUU por valor 60.000 millones de d\u00f3lares.<\/p>\n\n\n\n<p>2020.- EE.UU. mete a Cuba en su lista de pa\u00edses que no cooperan contra el terrorismo.<\/p>\n\n\n\n<p><strong>Nacimientos<\/strong><\/p>\n\n\n\n<p>1699.- Marques de Pombal, estadista portugu\u00e9s.<\/p>\n\n\n\n<p>1717.- Mar\u00eda Teresa de Habsburgo, emperatriz de Austria-Hungr\u00eda.<\/p>\n\n\n\n<p>1840.- Alphonse Daudet, novelista franc\u00e9s.<\/p>\n\n\n\n<p>1882.- George Braque, pintor cubista franc\u00e9s.<\/p>\n\n\n\n<p>1907.- Daphne du Maurier, escritora brit\u00e1nica.<\/p>\n\n\n\n<p>1930.- Manuel Marulanda \u00abtirofijo\u00bb, l\u00edder guerrillero (de las FARC) colombiano.<\/p>\n\n\n\n<p>1935.- Luciano Benetton, empresario italiano.<\/p>\n\n\n\n<p>1938.- Giuliano Amato, pol\u00edtico italiano, ex primer ministro.<\/p>\n\n\n\n<p>1950.- Stevie Wonder, cantante y compositor estadounidense.<\/p>\n\n\n\n<p>1977.- Samantha Morton, actriz brit\u00e1nica.<\/p>\n\n\n\n<p>1979.- Carlos Felipe, pr\u00edncipe sueco.<\/p>\n\n\n\n<p>1986.- Robert Pattinson, actor brit\u00e1nico.<\/p>\n\n\n\n<p><strong>Defunciones<\/strong><\/p>\n\n\n\n<p>1961.- Gary Cooper, actor de cine estadounidense.<\/p>\n\n\n\n<p>1999.- Gene Sarazen, golfista estadounidense.<\/p>\n\n\n\n<p>2003.- Marcos Zucker, actor argentino.<\/p>\n\n\n\n<p>2019.- Doris Day, actriz estadunidense.<\/p>\n\n\n\n<p>2022.- Teresa Berganza, cantante de \u00f3pera y zarzuela, espa\u00f1ola.<\/p>\n\n\n\n<p>2022.- Jalifa bin Zayed al Nahyan, emir, presidente de Emiratos \u00c1rabes Unidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00eda 13 de mayo como hoy, pero de 1917, tres pastorcillos portugueses confiesan haber visto a la Virgen en una cueva de la Sierra de la Estrella, origen de la devoci\u00f3n a Nuestra Se\u00f1ora de F\u00e1tima. Cien a\u00f1os despu\u00e9s, en 2017, el Papa Francisco proclam\u00f3 santos en F\u00e1tima a los pastorcillos Jacinta y Francisco. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":85142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Efem\u00e9rides 13 de mayo | Un d\u00eda como hoy en la historia... - Opini\u00f3n P\u00fablica","description":"Un d\u00eda 13 de mayo como hoy, pero de 1917, tres pastorcillos portugueses confiesan haber visto a la Virgen en una cueva de la Sierra de la Estrella, origen de la"},"footnotes":""},"categories":[27],"tags":[3366,3368,3367],"class_list":["post-85140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-dia-como-hoy","tag-efemerides-13-de-mayo","tag-nuestra-senora-de-fatima","tag-pastorcillos-portugueses-de-fatima"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/85140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=85140"}],"version-history":[{"count":3,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/85140\/revisions"}],"predecessor-version":[{"id":85146,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/85140\/revisions\/85146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/85142"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=85140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=85140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=85140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}