{"id":81665,"date":"2026-03-24T00:01:00","date_gmt":"2026-03-24T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=81665"},"modified":"2026-03-23T16:45:24","modified_gmt":"2026-03-23T22:45:24","slug":"efemerides-24-de-marzo-un-dia-como-hoy-en-la-historia","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/efemerides-24-de-marzo-un-dia-como-hoy-en-la-historia\/","title":{"rendered":"Efem\u00e9rides 24 de marzo | Un d\u00eda como hoy en la historia&#8230;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Un d\u00eda 24 de marzo como hoy, pero de 1989, encalla en las costas de Alaska el barco petrolero Exxon Valdez. El vertido de 37 mil toneladas de crudo provoc\u00f3 uno de las mayores desastres medioambientales de la historia<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"850\" height=\"554\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/03\/1989-encalla-en-las-costas-de-Alaska-el-petrolero-Exxon-Valdez.webp\" alt=\"1989, encalla en las costas de alaska el petrolero exxon valdez\" class=\"wp-image-81666\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/03\/1989-encalla-en-las-costas-de-Alaska-el-petrolero-Exxon-Valdez.webp 850w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/03\/1989-encalla-en-las-costas-de-Alaska-el-petrolero-Exxon-Valdez-300x196.webp 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/03\/1989-encalla-en-las-costas-de-Alaska-el-petrolero-Exxon-Valdez-768x501.webp 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Otras efem\u00e9rides<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1815.- Fernando VII funda la Orden de Isabel la Cat\u00f3lica para recompensar los servicios prestados en las colonias de Am\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1816.- Se re\u00fane el Congreso de Tucum\u00e1n (Argentina) que proclam\u00f3 la independencia de las Provincias Unidas del R\u00edo de la Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1853.- Primer intento de creaci\u00f3n de una \u00abCompa\u00f1\u00eda de tr\u00e1nsito a\u00e9reo con globos\u00bb, por el ingl\u00e9s William Henson, quien present\u00f3 su proyecto al Parlamento brit\u00e1nico para su aprobaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1854.- El presidente Jos\u00e9 Gregorio Monagas decreta la abolici\u00f3n de la esclavitud en Venezuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1878.- El patriota cubano Antonio Maceo inicia la \u00abguerra chiquita\u00bb en el oriente de Cuba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1887.- Robert Koch explica en Berl\u00edn su descubrimiento del bacilo de la tuberculosis. En su honor se celebra todos los a\u00f1os el D\u00eda Mundial de la Tuberculosis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1916.- Un submarino alem\u00e1n torpedea el barco Sussex, con una cifra estimada de ochenta muertos, entre ellos el compositor espa\u00f1ol Enrique Granados y su esposa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1922.- Tratado Salom\u00f3n-Lozano, entre Colombia y Per\u00fa, por el que este segundo pa\u00eds cede la ciudad de Leticia a Colombia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1927.- El poeta Antonio Machado es elegido para ocupar un sill\u00f3n en la Real Academia Espa\u00f1ola, aunque no tom\u00f3 posesi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1942.- El presidente argentino Roberto Mar\u00eda Ortiz dimite de su cargo por razones de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1945.- Segunda Guerra Mundial: Termina la primera fase del plan de operaciones dirigido por el general norteamericano Eisenhower.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1949.- Por primera vez un filme extranjero obtiene el \u00d3scar a la Mejor Pel\u00edcula. Fue la brit\u00e1nica \u00abHamlet\u00bb, dirigida e interpretada por Laurence Olivier, que se alz\u00f3 adem\u00e1s con el premio al Mejor Actor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1976.- Un golpe militar encabezado por el general Videla derroca a la presidenta argentina, Mar\u00eda Estela Mart\u00ednez de Per\u00f3n, e implanta una dictadura en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1980.- Un comando de ultraderecha asesina al arzobispo de San Salvador, monse\u00f1or Oscar Arnulfo Romero, cuando celebraba misa en la catedral de la capital de El Salvador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1986.- Unidades de la VI Flota de Estados Unidos atacan objetivos militares en aguas internacionales del golfo de Sirte, frente a la costa de Libia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1986.- El director argentino de cine Luis Puenzo gana con \u00abLa historia oficial\u00bb, el primer \u00d3scar que logra un filme hispanoamericano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1994.- Ana, la hija del criminal de guerra y exgeneral serbobosnio Ratko Mladic, se suicida con la pistola de su padre en pleno conflicto bosnio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1994.- El peruano Mario Vargas Llosa se convierte en el primer iberoamericano que ocupa un sill\u00f3n en la Real Academia Espa\u00f1ola de la Lengua en el siglo XX.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1999.- M\u00e1s de 40 personas mueren en un incendio declarado en el t\u00fanel del Mont-Blanc, que une Francia e Italia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2001.- El fabricante de ordenadores Apple Computer comercializa la primera versi\u00f3n de su sistema operativo Mac OS X. Con el nombre en clave de Cheetah, tuvo solo unos meses de vida debido a los m\u00faltiples errores que conten\u00eda y a su bajo rendimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2003.- El ex asesor presidencial peruano Vladimiro Montesinos es condenado a cinco a\u00f1os de c\u00e1rcel por tr\u00e1fico de influencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2006.- El papa Benedicto XVI proclama a los quince primeros cardenales de su pontificado, entre ellos al espa\u00f1ol Antonio Ca\u00f1izares y el venezolano Jorge Liberato Urosa Savino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2011.- La Corte Interamericana de Derechos Humanos condena a Uruguay por la desaparici\u00f3n de Mar\u00eda Claudia Garc\u00eda, nuera del poeta argentino Juan Gelman.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2013.- Michel Djotodia se autoproclama presidente de la Rep\u00fablica Centroafricana tras un golpe de estado que derroc\u00f3 al presidente Fran\u00e7ois Boziz\u00e9, que abandon\u00f3 el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2015.- Se registran 150 muertos en el accidente de un avi\u00f3n de la compa\u00f1\u00eda alemana Germanwings en los Alpes franceses, provocado, de manera deliberada, por el copiloto de la aeronave.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2016.- El Tribunal Internacional para la Antigua Yugoslavia condena a 40 a\u00f1os al exl\u00edder serbobosnio Radovan Karadzic por el genocidio en Srebrenica y otros cr\u00edmenes de guerra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2021.- El Gobierno de Argentina anuncia su retirada del Grupo de Lima, creado en 2017 para tratar la situaci\u00f3n de Venezuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2023.- Corea del Norte prueba un nuevo &#8216;dron&#8217; submarino capaz, seg\u00fan las autoridades norcoreanas, de desencadenar un \u00abtsunami radiactivo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nacimientos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1809.- Mariano Jos\u00e9 de Larra, escritor espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1874.- Harry Houdini, ilusionista estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1897.- Wilhelm Reich, psicoanalista y escritor austriaco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1911.- Joe Barbera, animador, director y productor estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1916.- Jos\u00e9 B\u00f3dalo, actor espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1926.- Guillermo Timoner, espa\u00f1ol, campe\u00f3n mundial de ciclismo tras moto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1926.- Dar\u00edo Fo, dramaturgo italiano,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1930.- Steve McQueen, actor estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1930.- Crist\u00f3bal Halfter, compositor y director de orquesta espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1930.- Agust\u00edn Gonz\u00e1lez, actor espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1935.- Pedro Pubill Calaf \u00abPeret\u00bb cantante y compositor espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1948.- Eduardo Mendicutti, escritor espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1951.- Tommy Hilfiger, dise\u00f1ador de moda estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1952.- Quim Monz\u00f3, escritor espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1954.- Robert Carradine, actor estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1957.- Silvia Munt, actriz espa\u00f1ola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1969.- Stefan Eberharter, esquiador austriaco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1970.- Sharon Corr, cantante y violinista irlandesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1974.- Jim Parsons, actor estadounidense, conocido por dar vida al personaje de Sheldon Cooper en la serie \u00abThe Big Bang Theory\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1975.- Arturo Valls, actor y presentador espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1976.- Aliou Ciss\u00e9, futbolista senegal\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1987.- Mar\u00eda Valverde, actriz espa\u00f1ola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Defunciones<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1603.- Isabel I, reina de Inglaterra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1824.- Esteban de Luca, poeta argentino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1882.- Enrique W. Longfellow, poeta estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1905.- Julio Verne, novelista franc\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1916.- Enrique Granados, compositor espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1980.- Oscar Arnulfo Romero, arzobispo de San Salvador, asesinado cuando celebraba misa en la catedral de la capital salvadore\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1987.- Vicente Calder\u00f3n, expresidente del Atl\u00e9tico de Madrid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1996.- Lola Beltr\u00e1n, cantante mexicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2002.- Ram\u00f3n Tapia Espinal, miembro del Triunvirato que gobern\u00f3 la Rep\u00fablica Dominicana entre 1963 y 1965.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2008.- Rafael Azcona, guionista cinematogr\u00e1fico espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2008.- Richard Widmark, actor estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2009.- Ricard Salvat, dramaturgo espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2010.- Robert Culp, actor estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2010.- Jim Marshall, fot\u00f3grafo estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2011.- Sen\u00e9n Blanco, ciclista espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2015.- Fernando Border\u00edas, periodista espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2016.- Johan Cruyff, futbolista de origen holand\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2017.-Paloma G\u00f3mez Borrero, periodista espa\u00f1ola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2019.- Scott Walker, m\u00fasico estadounidense vocalista del grupo The Walker Brothers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2020.- Alberto Aleandro Uderzo, \u00abAlbert Uderzo\u00bb, dibujante y guionista de c\u00f3mic franc\u00e9s, creador junto a Ren\u00e9 Goscinny de las historias de \u00abAsterix, el Galo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2020.- Manu Dibango, saxofonista, compositor y cantante camerun\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2021.- Jorge Mart\u00ednez Reverte, periodista y escritor espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2021.- Jessica Walter, actriz estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2022.- Luis Rold\u00e1n, pol\u00edtico, exdirector de la Guardia Civil. Su saqueo a los fondos reservados le convirti\u00f3 en una de las caras m\u00e1s conocidas de la corrupci\u00f3n en Espa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2022.- Mar\u00eda Fernanda D&#8217;Oc\u00f3n, actriz espa\u00f1ola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00eda 24 de marzo como hoy, pero de 1989, encalla en las costas de Alaska el barco petrolero Exxon Valdez. El vertido de 37 mil toneladas de crudo provoc\u00f3 uno de las mayores desastres medioambientales de la historia. Otras efem\u00e9rides 1815.- Fernando VII funda la Orden de Isabel la Cat\u00f3lica para recompensar los servicios [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":81666,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Efem\u00e9rides 24 de marzo | Un d\u00eda como hoy en la historia... - Opini\u00f3n P\u00fablica","description":"Un d\u00eda 24 de marzo como hoy, pero de 1989, encalla en las costas de Alaska el barco petrolero Exxon Valdez. El vertido de 37 mil toneladas de crudo provoc\u00f3 uno"},"footnotes":""},"categories":[27],"tags":[2812,2813,2811],"class_list":["post-81665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-dia-como-hoy","tag-alaska","tag-desastre-petrolero-exxon-valdez","tag-efemerides-24-de-marzo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/81665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=81665"}],"version-history":[{"count":1,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/81665\/revisions"}],"predecessor-version":[{"id":81667,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/81665\/revisions\/81667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/81666"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=81665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=81665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=81665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}