{"id":81001,"date":"2026-03-14T00:01:00","date_gmt":"2026-03-14T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=81001"},"modified":"2026-03-13T19:06:01","modified_gmt":"2026-03-14T01:06:01","slug":"revelan-nombres-de-ex-funcionarios-con-pensiones-doradas-jose-angel-gurria-en-la-lista","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/revelan-nombres-de-ex-funcionarios-con-pensiones-doradas-jose-angel-gurria-en-la-lista\/","title":{"rendered":"Revelan nombres de los ex funcionarios con pensiones doradas; Gurr\u00eda en la lista"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"631\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/03\/Revelan-nombres-de-ex-funcionarios-con-pensiones-doradas-Gurria-en-la-lista-1024x631.avif\" alt=\"Revelan nombres de ex funcionarios con pensiones doradas; gurri\u0301a en la lista\" class=\"wp-image-81004\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/03\/Revelan-nombres-de-ex-funcionarios-con-pensiones-doradas-Gurria-en-la-lista-1024x631.avif 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/03\/Revelan-nombres-de-ex-funcionarios-con-pensiones-doradas-Gurria-en-la-lista-300x185.avif 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/03\/Revelan-nombres-de-ex-funcionarios-con-pensiones-doradas-Gurria-en-la-lista-768x473.avif 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2026\/03\/Revelan-nombres-de-ex-funcionarios-con-pensiones-doradas-Gurria-en-la-lista.avif 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda Anticorrupci\u00f3n revel\u00f3 los nombres de extrabajadores con pensiones millonarias en Pemex, CFE, Nafin, Bancomex, Banrural y LyFC, y en la que parecen los nombres de Jos\u00e9 \u00c1ngel Gurr\u00eda, exsecretario de Hacienda; y \u00d3scar Espinosa Villarreal, ex jefe del Departamento del DF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado, la dependencia federal, inform\u00f3 que de conformidad con el art\u00edculo 65, de la Ley General de Transparencia y Acceso a la Informaci\u00f3n P\u00fablica, las dependencias y entidades deben poner a disposici\u00f3n de la sociedad el listado de personas jubiladas y pensionadas, as\u00ed como el monto que reciben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, se report\u00f3 que Jos\u00e9 \u00c1ngel Gurr\u00eda, ex secretario de Hacienda, en el sexenio de Ernesto Zedillo y ex director general de la OCDE, quien recibe cada mes 120 mil 685.53 pesos como pensi\u00f3n por parte de Nafin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00d3scar Espinosa Villarreal recibe 33 mil 400.32 pesos mensualmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda Anticorrupci\u00f3n record\u00f3 que durante la conferencia ma\u00f1anera del pasado 18 de febrero, se realiz\u00f3 un an\u00e1lisis de la informaci\u00f3n relativa a personas pensionadas en diversas instituciones p\u00fablicas, entre ellas, Luz y Fuerza del Centro en Liquidaci\u00f3n, Petr\u00f3leos Mexicanos, Comisi\u00f3n Federal de Electricidad, Nacional Financiera, Banco Nacional de Obras y Servicios P\u00fablicos, Banco Nacional de Comercio Exterior y Banco Nacional de Cr\u00e9dito Rural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEn el marco de dicho an\u00e1lisis se identificaron pensiones exorbitantes que superan el sueldo de la presidenta de la Rep\u00fablica e incluso con percepci\u00f3n de m\u00e1s de un mill\u00f3n de pesos mensuales\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ser de inter\u00e9s general para la poblaci\u00f3n, se indica, se difundi\u00f3 esta informaci\u00f3n con corte al 31 de diciembre de 2025 y que puede consultarse en el siguiente enlace:\u200b <a href=\"https:\/\/transparencia.gob.mx\/consulta\/consulta_pensiones.html\">https:\/\/transparencia.gob.mx\/consulta\/consulta_pensiones.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSe han identificado diferencias en la manera de cumplir con las obligaciones de transparencia en esta materia, por lo que Transparencia para el Pueblo y la Coordinaci\u00f3n General de \u00d3rganos Internos de Control de la Secretar\u00eda Anticorrupci\u00f3n y Buen Gobierno, emprendieron acciones para que las instituciones competentes publiquen la informaci\u00f3n en la Plataforma Nacional de Transparencia, en los t\u00e9rminos que establece la ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEste trabajo conjunto es un ejercicio sin precedentes que fortalece la transparencia y la rendici\u00f3n de cuentas a la sociedad\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Revelan existencia de pensiones doradas en la ma\u00f1anera<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado 18 de febrero, Raquel Buenrostro, titular de la Secretar\u00eda Anticorrupci\u00f3n y Buen Gobierno de M\u00e9xico, dio a conocer en la conferencia matutina de la presidenta Claudia Sheinbaum datos que detallan el monto que reciben exfuncionarios con altos cargos de confianza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta Claudia Sheinbaum Pardo confirm\u00f3 que el dato, se\u00f1alando a ex funcionarios y exl\u00edderes sindicales de Petr\u00f3leos Mexicanos (Pemex) y de la Comisi\u00f3n Federal de Electricidad (CFE).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cS\u00ed, en efecto, Gurr\u00eda est\u00e1 entre las personas. \u00c9l recibe una pensi\u00f3n de 120 mil pesos mensuales como exfuncionario\u2026 ya sali\u00f3 p\u00fablico, lo podemos decir\u201d, expres\u00f3, la Presidenta al a\u00f1adir que solicitar\u00e1 a la Secretar\u00eda Anticorrupci\u00f3n y Buen Gobierno detallar qu\u00e9 datos pueden difundirse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde aquel momento ya se hablaba de Jos\u00e9 \u00c1ngel Gurr\u00eda Trevi\u00f1o, ex secretario de Hacienda y exdirector general de la OCDE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ese motivo, Sheinbaum Pardo anunci\u00f3 una iniciativa de reforma constitucional para eliminar estos privilegios de exfuncionarios de confianza de distintas instituciones del gobierno federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Senado avala por unanimidad fin de \u201cpensiones doradas\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pleno del Senado aprob\u00f3 por unanimidad en lo general la reforma presidencial que elimina las llamadas \u201cpensiones doradas\u201d en organismos paraestatales como CFE, Luz y Fuerza, as\u00ed como Pemex, entre otras, pero que no incluye terminar con esos privilegios a los exfuncionarios de las secretar\u00edas de Estado, ni tampoco a militares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reforma aprobada con 116 votos a favor ser\u00e1 retroactiva por lo que los pensionados que reciben remuneraciones millonarias de m\u00e1s de 100 mil pesos y hasta un mill\u00f3n en algunos casos, una que sea avalada en la C\u00e1mara de Diputados, ganar\u00e1n alrededor de 70 mil pesos, que es el tope fijado a partir de la mitad del salario de la Presidenta de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Con informaci\u00f3n de El Universal<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda Anticorrupci\u00f3n revel\u00f3 los nombres de extrabajadores con pensiones millonarias en Pemex, CFE, Nafin, Bancomex, Banrural y LyFC, y en la que parecen los nombres de Jos\u00e9 \u00c1ngel Gurr\u00eda, exsecretario de Hacienda; y \u00d3scar Espinosa Villarreal, ex jefe del Departamento del DF. En un comunicado, la dependencia federal, inform\u00f3 que de conformidad con el [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":81004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Revelan nombres de los ex funcionarios con pensiones doradas; Gurr\u00eda en la lista - Opini\u00f3n P\u00fablica","description":"La Secretar\u00eda Anticorrupci\u00f3n revel\u00f3 los nombres de extrabajadores con pensiones millonarias en Pemex, CFE, Nafin, Bancomex, Banrural y LyFC, y en la que parecen"},"footnotes":""},"categories":[4],"tags":[773,161,2405],"class_list":["post-81001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pulsopolitico","tag-cfe","tag-pemex","tag-pensiones-doradas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/81001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=81001"}],"version-history":[{"count":4,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/81001\/revisions"}],"predecessor-version":[{"id":81006,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/81001\/revisions\/81006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/81004"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=81001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=81001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=81001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}