{"id":71738,"date":"2025-11-06T00:01:00","date_gmt":"2025-11-06T07:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=71738"},"modified":"2025-11-05T20:11:04","modified_gmt":"2025-11-06T03:11:04","slug":"cuanto-va-a-pagar-cada-mexicano-de-impuestos-en-2026","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/cuanto-va-a-pagar-cada-mexicano-de-impuestos-en-2026\/","title":{"rendered":"\u00bfCu\u00e1nto va a pagar cada mexicano de impuestos en 2026 por nuevos ajustes?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/11\/\u00bfCuanto-va-a-pagar-cada-mexicano-de-impuestos-en-2026-por-nuevos-ajustes-1024x576.webp\" alt=\"\u00bfcua\u0301nto va a pagar cada mexicano de impuestos en 2026 por nuevos ajustes?\" class=\"wp-image-71742\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/11\/\u00bfCuanto-va-a-pagar-cada-mexicano-de-impuestos-en-2026-por-nuevos-ajustes-1024x576.webp 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/11\/\u00bfCuanto-va-a-pagar-cada-mexicano-de-impuestos-en-2026-por-nuevos-ajustes-300x169.webp 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/11\/\u00bfCuanto-va-a-pagar-cada-mexicano-de-impuestos-en-2026-por-nuevos-ajustes-768x432.webp 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/11\/\u00bfCuanto-va-a-pagar-cada-mexicano-de-impuestos-en-2026-por-nuevos-ajustes.webp 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cada mexicano pagar\u00e1 \u2014en promedio\u2014 2,023 pesos adicionales de impuestos en 2026 a causa de los ajustes que se aprobaron en el marco tributario de productos como refrescos y otras bebidas saborizadas, cigarros, sueros y videojuegos violentos, seg\u00fan estimaciones de M\u00e9xico Eval\u00faa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pr\u00f3ximo a\u00f1o, el desembolso per c\u00e1pita o por persona al fisco ser\u00e1 de 43,439 pesos, 4.9% m\u00e1s que en 2025. Este aumento obedece, principalmente, a los ajustes en las tasas del Impuesto Especial sobre Producci\u00f3n y Servicios (IEPS), el llamado gravamen saludable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo de este impuesto es, entre otras cosas, que los consumidores tomen menos refresco y fumen menos ante un aumento en precios para aminorar el impacto negativo en la salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl problema que vemos con el incremento de este tipo de impuestos es que la recaudaci\u00f3n no est\u00e1 etiquetada claramente en temas de salud, espec\u00edficamente a personas sin seguridad social\u201d, comenta Jorge Cano, coordinador del Programa de Gasto P\u00fablico y Rendici\u00f3n de Cuentas de M\u00e9xico Eval\u00faa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pago de m\u00e1s contribuciones al Servicio de Administraci\u00f3n Tributaria (SAT) considera que la autoridad recaude 5.8 billones de pesos en 2026. Si la cifra es mayor, el desembolso per c\u00e1pita tambi\u00e9n lo ser\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El especialista considera que un mayor cobro de impuestos puede ser muy favorable, \u00absiempre y cuando se destinen a temas que le hacen falta a las personas m\u00e1s pobres del pa\u00eds, como puede ser educaci\u00f3n, salud y obras de infraestructura espec\u00edficas en lugares aislados\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si no est\u00e1n bien etiquetados, como se prev\u00e9 que ocurra en 2026, la recaudaci\u00f3n puede tener pocos o nulos alcances en pro del consumidor, destaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Banxico ve riesgos por IEPS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El incremento en las tasas del IEPS no solo implica un mayor pago de impuestos, tambi\u00e9n mayores presiones inflacionarias y, por ende, a las finanzas del consumidor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los integrantes de la Junta de Gobierno del Banco de M\u00e9xico reconoce que existe un riesgo para la inflaci\u00f3n relacionada con los ajustes en el impuesto saludable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl incremento en el IEPS de algunos productos podr\u00eda atenuar la desaceleraci\u00f3n de la inflaci\u00f3n de mercanc\u00edas incorporada en el pron\u00f3stico para 2026\u201d, expuso en la minuta 119, con fecha del 25 de octubre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro integrante coment\u00f3 que el impacto del aumento en el IEPS ser\u00eda limitado, dado que los productos potencialmente sujetos a dichas modificaciones representan alrededor de 2% del \u00cdndice Nacional de Precios al Consumidor, indicador con el cual se mide la inflaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Banxico aument\u00f3, recientemente, su expectativa de inflaci\u00f3n subyacente del primer trimestre de 2026, de 3.5% a 3.6 por ciento. En este segmento se encuentran los productos que tendr\u00e1n tasas impositivas m\u00e1s elevadas, como refrescos, cigarros, sueros y videojuegos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Federico Rubli, integrante del Comit\u00e9 del Indicador IMEF, comenta que estos ajustes tributarios traer\u00e1n mayor presi\u00f3n a la inflaci\u00f3n y, por ende, al bolsillo de los mexicanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Con informaci\u00f3n de El Economista<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada mexicano pagar\u00e1 \u2014en promedio\u2014 2,023 pesos adicionales de impuestos en 2026 a causa de los ajustes que se aprobaron en el marco tributario de productos como refrescos y otras bebidas saborizadas, cigarros, sueros y videojuegos violentos, seg\u00fan estimaciones de M\u00e9xico Eval\u00faa.&nbsp; El pr\u00f3ximo a\u00f1o, el desembolso per c\u00e1pita o por persona al fisco ser\u00e1 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":71742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"\u00bfCu\u00e1nto va a pagar cada mexicano de impuestos en 2026 por nuevos ajustes? - Opini\u00f3n P\u00fablica","description":"Cada mexicano pagar\u00e1 \u2014en promedio\u2014 2,023 pesos adicionales de impuestos en 2026 a causa de los ajustes que se aprobaron en el marco tributario de productos como"},"footnotes":""},"categories":[3],"tags":[],"class_list":["post-71738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/71738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=71738"}],"version-history":[{"count":3,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/71738\/revisions"}],"predecessor-version":[{"id":71743,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/71738\/revisions\/71743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/71742"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=71738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=71738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=71738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}