{"id":71039,"date":"2025-10-27T00:01:00","date_gmt":"2025-10-27T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=71039"},"modified":"2025-10-26T17:37:14","modified_gmt":"2025-10-26T23:37:14","slug":"buques-de-guerra-aviones-de-combate-y-la-cia-cual-es-el-objetivo-de-trump-en-venezuela","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/buques-de-guerra-aviones-de-combate-y-la-cia-cual-es-el-objetivo-de-trump-en-venezuela\/","title":{"rendered":"Buques de guerra, aviones de combate y la CIA: \u00bfqu\u00e9 busca Donald Trump en Venezuela?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/Buques-de-guerra-aviones-de-combate-y-la-CIA-\u00bfque-busca-Donald-Trump-en-Venezuela-1024x576.webp\" alt=\"Buques de guerra, aviones de combate y la cia \u00bfque\u0301 busca donald trump en venezuela?\" class=\"wp-image-71042\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/Buques-de-guerra-aviones-de-combate-y-la-CIA-\u00bfque-busca-Donald-Trump-en-Venezuela-1024x576.webp 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/Buques-de-guerra-aviones-de-combate-y-la-CIA-\u00bfque-busca-Donald-Trump-en-Venezuela-300x169.webp 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/Buques-de-guerra-aviones-de-combate-y-la-CIA-\u00bfque-busca-Donald-Trump-en-Venezuela-768x432.webp 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/Buques-de-guerra-aviones-de-combate-y-la-CIA-\u00bfque-busca-Donald-Trump-en-Venezuela-1536x864.webp 1536w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/Buques-de-guerra-aviones-de-combate-y-la-CIA-\u00bfque-busca-Donald-Trump-en-Venezuela.webp 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Desde hace dos meses, el ej\u00e9rcito estadounidense acumula una fuerza de buques de guerra, aviones de combate, bombarderos, marines, drones y aviones esp\u00eda en la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los bombarderos de largo alcance B-52 han hecho \u00absimulacros de ataque con bombarderos\u00bb frente a las costas de Venezuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump tambi\u00e9n autoriz\u00f3 el despliegue de la CIA en Venezuela, a medida que aumentan las tensiones entre ambos pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos afirma haber matado a decenas de personas en ataques contra peque\u00f1as embarcaciones procedentes de Venezuela que, seg\u00fan alega, transportaban \u00abnarc\u00f3ticos\u00bb y \u00abnarcoterroristas\u00bb, sin aportar pruebas ni detalles sobre qui\u00e9nes iban a bordo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ataques fueron condenados en la regi\u00f3n y los expertos cuestionan su legalidad. Estados Unidos los presenta como una guerra contra el narcotr\u00e1fico, pero hay quienes consideran que se trata en realidad de una campa\u00f1a de intimidaci\u00f3n que busca derrocar al presidente de Venezuela, Nicol\u00e1s Maduro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSe trata de un cambio de r\u00e9gimen. Probablemente no vayan a invadir, la esperanza es que se trate solo de una se\u00f1al\u00bb, afirma Christopher Sabatini, investigador senior para Am\u00e9rica Latina en el centro de estudios Chatham House.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sostiene que el aumento de la presencia militar es una demostraci\u00f3n de fuerza destinada a \u00abinfundir miedo\u00bb en los corazones de los militares venezolanos y el c\u00edrculo \u00edntimo de Maduro para que se rebelen contra \u00e9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde Venezuela, Maduro acus\u00f3 este viernes a EE.UU. de estar fabricando un caso en contra de su pa\u00eds y asegur\u00f3 que est\u00e1 preparando brigadas para reaccionar a cualquier amenaza de Washington.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPrometieron que m\u00e1s nunca se met\u00edan en una guerra y se est\u00e1n inventando una guerra que nosotros vamos a evitar. \u00bfCon qu\u00e9? Con la movilizaci\u00f3n de los pueblos de Am\u00e9rica del Sur, porque Am\u00e9rica del Sur y el Caribe, todo, dice no a la guerra, s\u00ed a la paz, s\u00ed a la prosperidad, s\u00ed a la armon\u00eda y a la convivencia\u00bb, dijo en un discurso televisado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSe inventan un relato extravagante, vulgar, criminal y totalmente falso, ya demostradamente falso, Venezuela es un pa\u00eds libre de producci\u00f3n de hojas de coca, libre de producci\u00f3n de coca\u00edna, y vamos a lograr el 100% libre de paso de un min\u00fasculo 5% que viene de Colombia\u00bb, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un mapa del mar Caribe, en el que se muestran las posiciones de 10 buques estadounidenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">BBC Verify monitore\u00f3 la informaci\u00f3n de seguimiento que hay disponible de modo p\u00fablico de los barcos y aviones estadounidenses en la regi\u00f3n, junto con im\u00e1genes satelitales y de las redes sociales, para tratar de construir el panorama de d\u00f3nde se encuentran las fuerzas de Trump.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El despliegue ha ido cambiando, por lo que seguimos monitoreando la regi\u00f3n regularmente para obtener actualizaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A fecha de 23 de octubre, identificamos 10 buques militares estadounidenses en la regi\u00f3n, entre los que se incluyen destructores lanzamisiles, buques de asalto anfibio y petroleros para reabastecer a los buques en el mar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y este viernes, el Departamento de Defensa de EE.UU. inform\u00f3 que orden\u00f3 el despliegue hacia el mar Caribe del portaaviones USS Gerald R Ford, el buque de guerra m\u00e1s grande del mundo, que puede transportar hasta 90 aviones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Una recompensa para arrestar a Maduro<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es ning\u00fan secreto que la administraci\u00f3n estadounidense, en particular el secretario de Estado, Marco Rubio, desea ver derrocado a Maduro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principios de este a\u00f1o, Rubio le dijo a Fox News que Maduro es un \u00abdictador horrible\u00bb y, cuando se le pregunt\u00f3 si exig\u00eda su salida del gobierno venezolano, a\u00f1adi\u00f3: \u00abVamos a trabajar en eso\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, incluso para cr\u00edticos abiertos de Maduro como Rubio, es dif\u00edcil pedir expl\u00edcitamente un cambio de gobierno con el respaldo del ej\u00e9rcito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La oposici\u00f3n venezolana lleva tiempo apelando a las Fuerzas Armadas para que se desvinculen de Nicol\u00e1s Maduro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donald Trump hizo campa\u00f1a contra un posible cambio de gobierno en Venezuela en 2016. Entonces, prometi\u00f3 \u00abdejar de correr para derrocar reg\u00edmenes extranjeros\u00bb. De modo m\u00e1s reciente conden\u00f3 la participaci\u00f3n en \u00abguerras eternas\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de eso, varios hitos han marcado las tensiones entre ambos pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, la embajada de Estados Unidos en Caracas fue cerrada durante la primera presidencia de Trump en 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y, tras las \u00faltimas elecciones generales de julio de 2024, Estados Unidos no reconoce a Maduro como presidente de Venezuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esos comicios fueron ampliamente rechazados a nivel internacional, as\u00ed como por la oposici\u00f3n en Venezuela, al no considerarlos ni libres ni justos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Consejo Nacional Electoral anunci\u00f3 a Maduro como vencedor, pero a d\u00eda de hoy no hizo p\u00fablicas las actas que avalan este resultado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos aument\u00f3 a US$50 millones la recompensa por informaci\u00f3n que conduzca al arresto de Maduro, un incentivo para que los miembros de su c\u00edrculo m\u00e1s cercano y leal lo entreguen. Pero esto no ha dado lugar a ninguna deserci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 Ignacio Hern\u00e1ndez, profesor venezolano de Derecho y asociado s\u00e9nior del centro de estudios de seguridad nacional CSIS, afirma que US$50 millones \u00abno son nada\u00bb para las \u00e9lites venezolanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un estado rico en petr\u00f3leo como Venezuela, las posibilidades de ganar dinero de modos no l\u00edcitos son muchas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por poner un ejemplo, el exdirector del Tesoro Alejandro Andrade gan\u00f3 US$1.000 millones en sobornos antes de ser condenado en Estados Unidos por lavado de dinero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos analistas coinciden en que el ej\u00e9rcito venezolano ser\u00eda clave para cualquier cambio de poder, pero apuntan que, para volverse contra Maduro y derrocarlo, probablemente querr\u00edan garant\u00edas de inmunidad judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hern\u00e1ndez a\u00f1ade: \u00abPueden pensar que, de una forma u otra, ellos tambi\u00e9n est\u00e1n involucrados en actividades delictivas\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Michael Albertus, profesor de Ciencias Pol\u00edticas de la Universidad de Chicago y autor de numerosas publicaciones sobre Am\u00e9rica Latina, no est\u00e1 convencido de que ni siquiera una recompensa de US$500 millones pueda persuadir al c\u00edrculo \u00edntimo de Maduro para que lo entregue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLos l\u00edderes autoritarios siempre sospechan incluso de su c\u00edrculo m\u00e1s cercano y, por eso, crean mecanismos para vigilarlos y garantizar su lealtad\u00bb, afirma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las sanciones econ\u00f3micas impuestas a Venezuela han empeorado la ya grave crisis econ\u00f3mica y social, pero no han logrado persuadir a las figuras de alto rango para que se vuelvan contra su presidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>M\u00e1s all\u00e1 de las drogas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donald Trump declar\u00f3 que el movimiento de efectivos militares en la regi\u00f3n es por su guerra declarada contra los narcotraficantes y afirm\u00f3 que uno de los barcos atacados por Estados Unidos el 16 de octubre \u00abestaba cargado principalmente con fentanilo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero el fentanilo se produce principalmente en M\u00e9xico, no en Am\u00e9rica del Sur, y entra en Estados Unidos por la frontera sur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNo se trata de drogas. Pero \u00e9l ha adoptado el discurso de la oposici\u00f3n venezolana de que esto no es solo una dictadura, sino un r\u00e9gimen criminal\u00bb, indica Sabatini.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 2020, el Departamento de Justicia de Estados Unidos acusa a Maduro de liderar una organizaci\u00f3n de narcotr\u00e1fico y narcoterrorismo conocida como el cartel de los Soles, algo que el mandatario venezolano niega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente, Trump admiti\u00f3 que autoriz\u00f3 a la CIA a llevar a cabo operaciones encubiertas en Venezuela, en parte debido a la \u00abentrada de drogas\u00bb procedentes de ese pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Venezuela no produce grandes cantidades de coca\u00edna, que proviene principalmente de Colombia, Per\u00fa y Bolivia. Hay algo de coca\u00edna que se trafica a trav\u00e9s de Venezuela, y el propio gobierno afirma estar tomando medidas en\u00e9rgicas contra eso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un informe de la Administraci\u00f3n para el Control de Drogas de Estados Unidos de 2025 se\u00f1ala que el 84% de la coca\u00edna incautada en Estados Unidos procede de Colombia y menciona otros pa\u00edses, pero no a Venezuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las primeras siete operaciones de las fuerzas estadounidenses se realizaron en el Caribe, que no es una ruta mar\u00edtima importante para el tr\u00e1fico de drogas en comparaci\u00f3n con el oc\u00e9ano Pac\u00edfico, donde se produjeron las operaciones posteriores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos no ha detallado las pruebas que tiene contra Maduro como l\u00edder de una organizaci\u00f3n de tr\u00e1fico de drogas. Maduro ha negado repetidamente las acusaciones y, por su parte, acusa a Estados Unidos de imperialismo y de agravar la crisis econ\u00f3mica del pa\u00eds con sus sanciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se conocen casos de personas cercanas a \u00e9l que han sido acusadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2016, un tribunal federal de Nueva York conden\u00f3 a Efra\u00edn Antonio Campo Flores y Franqui Francisco Flores de Freitas, dos sobrinos de Cilia Flores, esposa de Maduro, a 18 a\u00f1os de c\u00e1rcel por conspirar para importar coca\u00edna a Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El caso afirmaba que planeaban utilizar parte del dinero para financiar la campa\u00f1a pol\u00edtica de Cilia Flores. Posteriormente fueron puestos en libertad a cambio de la liberaci\u00f3n de siete estadounidenses encarcelados en Venezuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Refuerzo de la potencia naval y a\u00e9rea de EE.UU.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan los analistas militares, interceptar drogas en el mar no requiere una fuerza tan grande como la que tiene desplegada ahora Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de los barcos estadounidenses que la BBC logr\u00f3 rastrear alrededor de Puerto Rico, donde Estados Unidos tiene una base militar, las im\u00e1genes satelitales tambi\u00e9n mostraron dos embarcaciones unas 75 millas (123 km) al este de Trinidad y Tobago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno era un crucero lanzamisiles, el USS Lake Erie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El otro parec\u00eda ser el MV Ocean Trader, seg\u00fan Bradley Martin, excapit\u00e1n de la Marina de Estados Unidos y ahora investigador senior de pol\u00edticas en RAND Corp.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de un buque de carga reconvertido, dise\u00f1ado para apoyar misiones de fuerzas especiales en combinaci\u00f3n con el tr\u00e1fico comercial. Puede albergar drones, helic\u00f3pteros y peque\u00f1as embarcaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay una gran variedad de misiones que podr\u00eda apoyar, incluido el reconocimiento para preparar ataques. Pero Martin subraya que su presencia \u00abno significa necesariamente que se est\u00e9n realizando o se hayan planeado ese tipo de actividades\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, Estados Unidos ha reforzado su presencia a\u00e9rea en la regi\u00f3n: BBC Verify ha identificado varios aviones militares estadounidenses en Puerto Rico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stu Ray, analista senior de McKenzie Intelligence Services, afirma que una imagen satelital tomada el 17 de octubre muestra aviones de combate F-35 en la pista, posiblemente F-35B.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de aviones sigilosos muy avanzados, muy apreciados por su capacidad de despegue corto y aterrizaje vertical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En redes sociales, un piloto de aviones privados comparti\u00f3 un video de un dron MQ-9 Reaper, filmado en el aeropuerto Rafael Hern\u00e1ndez de Puerto Rico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos los ha utilizado para llevar a cabo ataques y operaciones de vigilancia en Afganist\u00e1n, Siria, Libia y Mali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principios de octubre, BBC Verify rastre\u00f3 tres bombarderos B-52 que sobrevolaron el Caribe y se acercaron a la costa de Venezuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fuerza A\u00e9rea de Estados Unidos confirm\u00f3 posteriormente que los aviones participaron en una \u00abdemostraci\u00f3n de ataque con bombarderos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se han podido ver vuelos de bombarderos B1 y aviones esp\u00eda P-8 Poseid\u00f3n en plataformas de seguimiento de aviones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las im\u00e1genes difundidas en redes sociales tambi\u00e9n muestran helic\u00f3pteros militares operando frente a las costas de Trinidad y Tobago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos de ellos son Boeing MH-6M Little Birds, apodados Killer Eggs (\u00abhuevos asesinos\u00bb), utilizados por las fuerzas especiales estadounidenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Qu\u00e9 podr\u00eda hacer la CIA dentro de Venezuela<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando se le pregunt\u00f3 si la CIA hab\u00eda recibido la autorizaci\u00f3n para eliminar a Maduro, Donald Trump eludi\u00f3 la pregunta y dijo que ser\u00eda \u00abrid\u00edculo\u00bb responder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n dijo que Estados Unidos \u00abest\u00e1 estudiando el terreno\u00bb, en referencia a posibles operaciones militares en suelo venezolano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La CIA es vista con mucho recelo por muchos en Am\u00e9rica Latina debido a su largo historial de intervenciones encubiertas, intentos de cambio de gobierno y apoyo a dictaduras militares de derecha en el pasado, especialmente en Chile y Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ned Price, adjunto al representante de Estados Unidos ante Naciones Unidas y antiguo analista senior de la CIA y asesor senior del Departamento de Estado, dijo que las acciones encubiertas de la CIA pueden adoptar \u00abmuchas formas\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPueden ser operaciones de informaci\u00f3n. Pueden ser operaciones de sabotaje. Pueden ser la financiaci\u00f3n de partidos de la oposici\u00f3n. Pueden llegar hasta el derrocamiento de un r\u00e9gimen. Hay muchas opciones entre la opci\u00f3n m\u00e1s moderada y la m\u00e1s radical\u00bb, precis\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto podr\u00eda incluir el uso de agentes para perseguir a sospechosos de tr\u00e1fico de il\u00edcitos dentro de Venezuela. Seg\u00fan la propia definici\u00f3n de Estados Unidos, esto podr\u00eda incluir al propio Maduro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabatini afirma que, dado que Venezuela no es un importante centro de producci\u00f3n de drogas, no hay laboratorios de coca\u00edna o fentanilo que \u00abeliminar\u00bb, pero s\u00ed hay pistas de aterrizaje o puertos que Estados Unidos podr\u00eda atacar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSi quiere mostrarse agresivo, podr\u00eda enviar un misil a un cuartel militar. Hay informaci\u00f3n bastante fiable de que ciertos sectores del ej\u00e9rcito est\u00e1n involucrados en el tr\u00e1fico de coca\u00edna\u00bb, dice Sabatini.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O podr\u00eda tratarse de una \u00absituaci\u00f3n de asalto y captura\u00bb, se\u00f1ala, en la que intentar\u00edan detener a Maduro o a algunos de sus lugartenientes y llevarlos ante la justicia en Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gran pregunta, argumenta, es cu\u00e1nto tiempo est\u00e1 dispuesto Trump a mantener tantos activos estadounidenses estacionados en el Caribe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si el objetivo principal de este despliegue militar es amenazar a Maduro, no est\u00e1 claro si ser\u00e1 suficiente para provocar deserciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El profesor Albertus se pregunta si eso llegar\u00e1 a un intento real de derrocar a Maduro por la fuerza, algo que es dif\u00edcil de saber.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Con informaci\u00f3n de BBC Mundo<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde hace dos meses, el ej\u00e9rcito estadounidense acumula una fuerza de buques de guerra, aviones de combate, bombarderos, marines, drones y aviones esp\u00eda en la zona. Los bombarderos de largo alcance B-52 han hecho \u00absimulacros de ataque con bombarderos\u00bb frente a las costas de Venezuela. Trump tambi\u00e9n autoriz\u00f3 el despliegue de la CIA en Venezuela, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":71042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Buques de guerra, aviones de combate y la CIA: \u00bfqu\u00e9 busca Donald Trump en Venezuela? - Opini\u00f3n P\u00fablica","description":"Desde hace dos meses, el ej\u00e9rcito estadounidense acumula una fuerza de buques de guerra, aviones de combate, bombarderos, marines, drones y aviones esp\u00eda en la"},"footnotes":""},"categories":[4],"tags":[102,1023],"class_list":["post-71039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pulsopolitico","tag-donald-trump","tag-venezuela"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/71039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=71039"}],"version-history":[{"count":3,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/71039\/revisions"}],"predecessor-version":[{"id":71043,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/71039\/revisions\/71043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/71042"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=71039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=71039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=71039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}