{"id":70145,"date":"2025-10-13T00:01:00","date_gmt":"2025-10-13T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=70145"},"modified":"2025-10-12T19:46:42","modified_gmt":"2025-10-13T01:46:42","slug":"que-genera-mayor-estres-financiero-las-deudas-o-la-falta-de-dinero","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/que-genera-mayor-estres-financiero-las-deudas-o-la-falta-de-dinero\/","title":{"rendered":"\u00bfQu\u00e9 genera mayor estr\u00e9s financiero al mexicano, deudas o la falta de dinero?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/\u00bfQue-genera-mayor-estres-financiero-al-mexicano-deudas-o-la-falta-de-dinero-1024x576.webp\" alt=\"\u00bfque\u0301 genera mayor estre\u0301s financiero al mexicano, deudas o la falta de dinero?\" class=\"wp-image-70150\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/\u00bfQue-genera-mayor-estres-financiero-al-mexicano-deudas-o-la-falta-de-dinero-1024x576.webp 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/\u00bfQue-genera-mayor-estres-financiero-al-mexicano-deudas-o-la-falta-de-dinero-300x169.webp 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/\u00bfQue-genera-mayor-estres-financiero-al-mexicano-deudas-o-la-falta-de-dinero-768x432.webp 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/10\/\u00bfQue-genera-mayor-estres-financiero-al-mexicano-deudas-o-la-falta-de-dinero.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Experimentar estr\u00e9s financiero es una realidad com\u00fan en M\u00e9xico. Si bien el endeudamiento suele considerarse una de sus principales causas, diversos estudios indican que la incapacidad de afrontar emergencias econ\u00f3micas sin recursos puede generar a\u00fan m\u00e1s ansiedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfPor qu\u00e9 sucede esto y c\u00f3mo se vinculan nuestras actitudes hacia la deuda con la gesti\u00f3n de nuestra salud mental?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un estudio publicado en la revista Suma Psicol\u00f3gica, \u201cActitudes hacia el endeudamiento y estr\u00e9s financiero en adultos emergentes: rol mediador de las compras planificada e impulsiva, revela que las actitudes austeras frente al endeudamiento \u2014caracterizadas por evitar la deuda y priorizar el control financiero\u2014 est\u00e1n relacionadas directamente con altos niveles de estr\u00e9s financiero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan los autores, la preocupaci\u00f3n constante por evitar obligaciones puede intensificar la percepci\u00f3n de vulnerabilidad ante cualquier imprevisto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el contrario, actitudes m\u00e1s hedonistas hacia el cr\u00e9dito, que suelen asociarse a compras impulsivas, no muestran un v\u00ednculo directo con el estr\u00e9s financiero. La explicaci\u00f3n, seg\u00fan el estudio, podr\u00eda estar en la normalizaci\u00f3n social de la deuda: comprar a cr\u00e9dito se vuelve parte del d\u00eda a d\u00eda y las consecuencias se postergan, reduciendo la ansiedad inmediata \u2014aunque la amenaza exista a futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00abCubrir una necesidad con un cr\u00e9dito s\u00ed te da la sensaci\u00f3n de control\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erika Villavicencio-Ayub, directora de la consultora DserOrganizacional e investigadora en la UNAM, explica que obtener un pr\u00e9stamo para cubrir una necesidad s\u00ed te da la sensaci\u00f3n de control, a eso se le llama un sesgo de acci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntonces, este sesgo de acci\u00f3n dice que cuando enfrentamos alg\u00fan tipo de incertidumbre realizas cualquier acci\u00f3n, aunque no sea la mejor acci\u00f3n y nos da una sensaci\u00f3n de que somos eficientes. Y por ese momento te quita la ansiedad\u201d, explica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agrega que es un proceso cognitivo que todos tenemos y se activa. \u201cEl alivio va a transformar tu impotencia de no poder pagar algo en una acci\u00f3n concreta, \u201cah lo pagu\u00e9 con cr\u00e9dito\u201d. Y s\u00ed, el riesgo est\u00e1 ah\u00ed, la situaci\u00f3n est\u00e1 ah\u00ed. No obstante, lo que tu mente percibe es que tienes el control de la situaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esto, dice, de forma inmediata est\u00e1s apagando el fuego y disminuyes el estr\u00e9s financiero de inmediato, porque la amenaza ya no es tan tangible, ya no es urgente, es a futuro. \u201cEntonces, es algo abstracto y eso es lo que se genera cognitivamente hablando\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfDeuda o compra planificada? Esa es la cuesti\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio de la revista Suma Psicol\u00f3gica explica que la interrelaci\u00f3n entre las actitudes de endeudamiento austero con el estr\u00e9s financiero se llevan a cabo de la siguiente manera:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Actitud austera hacia el endeudamiento y estr\u00e9s financiero<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actitud austera se define como una postura cautelosa frente a la deuda, cuyo prop\u00f3sito es generalmente cubrir necesidades fundamentales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio encontr\u00f3 que las actitudes austeras se vinculan directamente y positivamente con el estr\u00e9s financiero. Esto significa que, al controlar otras variables, las personas con actitudes m\u00e1s cautelosas y reservadas frente al endeudamiento experimentan un mayor estr\u00e9s financiero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una posible explicaci\u00f3n para este hallazgo es que la austeridad implica una mayor preocupaci\u00f3n por el dinero y el control de las finanzas personales. Percibir un ambiente econ\u00f3mico con menos recursos disponibles podr\u00eda llevar a una actitud m\u00e1s cautelosa, lo cual resulta estresante para los adultos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Endeudamiento y estr\u00e9s financiero<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actitud hedonista implica una concepci\u00f3n positiva del uso del cr\u00e9dito para satisfacer necesidades y deseos de forma inmediata, sin una evaluaci\u00f3n adecuada de las consecuencias futuras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto podr\u00eda estar relacionado con la normalizaci\u00f3n del endeudamiento, lo que genera actitudes favorables al cr\u00e9dito sin considerar las consecuencias futuras, creando una posible falsa sensaci\u00f3n de seguridad financiera a corto plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed el estudio encontr\u00f3 que los adultos con actitudes favorables a endeudarse podr\u00edan adoptar estilos de compra impulsivos sin ser plenamente conscientes de que el endeudamiento exige un uso eficiente de los recursos para mantener la capacidad de pago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Amenaza existencial contra la amenaza postergada<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, la investigadora de la Facultad de Psicolog\u00eda de la UNAM, refiere que el estr\u00e9s financiero se genera por amenazas existenciales inmediatas en, por ejemplo, no tengo para comer, para pagar la renta, este tipo de estr\u00e9s es muy agudo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay estr\u00e9s agudo, estr\u00e9s cr\u00f3nico, hay diferentes tipos y cada uno el organismo lo asimila diferente. Entonces tengo que hacer algo para pararlo, ya que este al ser un estr\u00e9s agudo, es decir, que involucra la activaci\u00f3n del sistema l\u00edmbico, lo cual genera miedo, produce ansiedad, una alerta, algo que puede atentar contra mi supervivencia, y es cognitivamente m\u00e1s intenso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando sucede esto se activa el sesgo del presente contra el futuro. \u201cEntonces el cerebro dice &#8216;es una amenaza a largo tiempo. Ya no estoy viviendo y produciendo un estr\u00e9s agudo, ya no me impacta en mi supervivencia inmediata\u2019\u201d, refiere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ante la ausencia de salud financiera se produce el estr\u00e9s financiero<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erika Villavicencio Ayub considera que en temas de endeudamiento se puede redefinir el estr\u00e9s, transformar la ansiedad permite redefinir el origen del estr\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi tenemos ansiedad por escasez de recursos, eso se asocia con que no puedo cubrir mis necesidades b\u00e1sicas. Entonces, lo transformo en ansiedad por gesti\u00f3n de obligaciones\u201d, refiere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para la especialista esto se explica porque s\u00f3lo se tiene que planear los pagos del cr\u00e9dito. \u201cInternamente, cognitivamente, estoy cambiando la carga emocional, para pasar de una sensaci\u00f3n de par\u00e1lisis, de crisis de shock por un problema que no puedo manejar, a uno que psicol\u00f3gicamente me impacta menos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta situaci\u00f3n se explica con otro sesgo, cuando la situaci\u00f3n se percibe como un tema administrativo, entonces simplemente me organizo, hago un plan de pagos y en la imaginaci\u00f3n o en el pensamiento pues se ve f\u00e1cil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo obstante, pues el d\u00eda a d\u00eda y ya cuando le vas sumando que tienes no una, sino varias compras a cr\u00e9dito, pues empieza la situaci\u00f3n cruda, pero digamos que vas a gestionar las obligaciones, y eso pareciera ser desde el enfoque psicol\u00f3gico algo muy manejable\u201d, advierte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la especialista dice que hay que ser h\u00e1biles para comprender cu\u00e1ndo vale la pena, y sobre todo pues tener los sesgos a favor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPara avanzar y, a lo mejor, gracias a un endeudamiento controlado y acompa\u00f1ado desde este enfoque que nos permite evitar las consecuencias y lograr logres comprarte una casa, hacerte un patrimonio, irte a un viaje\u201d, dice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Con informaci\u00f3n de El Economista<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Experimentar estr\u00e9s financiero es una realidad com\u00fan en M\u00e9xico. Si bien el endeudamiento suele considerarse una de sus principales causas, diversos estudios indican que la incapacidad de afrontar emergencias econ\u00f3micas sin recursos puede generar a\u00fan m\u00e1s ansiedad. \u00bfPor qu\u00e9 sucede esto y c\u00f3mo se vinculan nuestras actitudes hacia la deuda con la gesti\u00f3n de nuestra [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":70150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"\u00bfQu\u00e9 genera mayor estr\u00e9s financiero al mexicano, deudas o la falta de dinero? - Opini\u00f3n P\u00fablica","description":"Experimentar estr\u00e9s financiero es una realidad com\u00fan en M\u00e9xico. Si bien el endeudamiento suele considerarse una de sus principales causas, diversos estudios ind"},"footnotes":""},"categories":[3],"tags":[],"class_list":["post-70145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/70145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=70145"}],"version-history":[{"count":3,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/70145\/revisions"}],"predecessor-version":[{"id":70151,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/70145\/revisions\/70151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/70150"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=70145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=70145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=70145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}