{"id":69086,"date":"2025-09-27T00:01:00","date_gmt":"2025-09-27T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=69086"},"modified":"2025-09-26T20:42:59","modified_gmt":"2025-09-27T02:42:59","slug":"fita-chihuahua-invita-a-participar-en-las-actividades-programadas-para-este-fin-de-semana","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/fita-chihuahua-invita-a-participar-en-las-actividades-programadas-para-este-fin-de-semana\/","title":{"rendered":"El FITA Chihuahua invita a participar en sus actividades durante este fin de semana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/09\/FITA-Chihuahua-invita-a-participar-en-sus-actividades-durante-este-fin-de-semana-1024x769.jpeg\" alt=\"Fita chihuahua invita a participar en sus actividades durante este fin de semana\" class=\"wp-image-69089\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/09\/FITA-Chihuahua-invita-a-participar-en-sus-actividades-durante-este-fin-de-semana-1024x769.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/09\/FITA-Chihuahua-invita-a-participar-en-sus-actividades-durante-este-fin-de-semana-300x225.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/09\/FITA-Chihuahua-invita-a-participar-en-sus-actividades-durante-este-fin-de-semana-768x576.jpeg 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/09\/FITA-Chihuahua-invita-a-participar-en-sus-actividades-durante-este-fin-de-semana-1536x1153.jpeg 1536w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/09\/FITA-Chihuahua-invita-a-participar-en-sus-actividades-durante-este-fin-de-semana.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em>Chihuahua, Chih<\/em>.- La Secretar\u00eda de Turismo, a trav\u00e9s del Festival Internacional de Turismo de Aventura (FITA) Chihuahua 2025 invita a la ciudadan\u00eda en general, a disfrutar de las actividades que se realizar\u00e1n del 26 al 28 de septiembre en distintos municipios del estado.<\/p>\n\n\n\n<p>Como parte del programa oficial del Festival, se llevar\u00e1 a cabo la Ruta Extrema Balleza los d\u00edas 26 y 27 de septiembre, un evento de veh\u00edculos Off Road que celebra su cuarta edici\u00f3n.<\/p>\n\n\n\n<p>El 28 de septiembre en Jim\u00e9nez se realizar\u00e1 el Reto Zona del Silencio, un marat\u00f3n de ciclismo de monta\u00f1a (MTB) con rutas de 60, 40 y 15 kil\u00f3metros.<\/p>\n\n\n\n<p>Ese mismo d\u00eda, en San Francisco de Conchos tendr\u00e1 lugar el Boquilla Trail Run, una carrera pedestre que desafiar\u00e1 a los corredores, con una ruta que recorre los paisajes del Lago Colina.<\/p>\n\n\n\n<p>Del 26 al 28 de septiembre se celebra el Aniversario del Motoclub Motorrad Chihuahua AC, con recorridos de motociclismo desde el Parque Barrancas hasta Cerocahui.<\/p>\n\n\n\n<p>El evento cuenta con el respaldo de la Secretar\u00eda de Turismo, como una actividad que impulsa el turismo deportivo y de naturaleza en la regi\u00f3n.<\/p>\n\n\n\n<p>El FITA Chihuahua 2025 es un programa que promueve el turismo de aventura, fortalece la econom\u00eda local y fomenta la participaci\u00f3n de visitantes nacionales e internacionales en los distintos municipios de la entidad.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n sobre pr\u00f3ximos eventos, se invita a seguir las redes oficiales: @fita.chihuahua y @TurismodeChihuahua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chihuahua, Chih.- La Secretar\u00eda de Turismo, a trav\u00e9s del Festival Internacional de Turismo de Aventura (FITA) Chihuahua 2025 invita a la ciudadan\u00eda en general, a disfrutar de las actividades que se realizar\u00e1n del 26 al 28 de septiembre en distintos municipios del estado. Como parte del programa oficial del Festival, se llevar\u00e1 a cabo la [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":69089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"El FITA Chihuahua invita a participar en sus actividades durante este fin de semana - Opini\u00f3n P\u00fablica","description":"Chihuahua, Chih .- La Secretar\u00eda de Turismo, a trav\u00e9s del Festival Internacional de Turismo de Aventura (FITA) Chihuahua 2025 invita a la ciudadan\u00eda en general,"},"footnotes":""},"categories":[11],"tags":[],"class_list":["post-69086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/69086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=69086"}],"version-history":[{"count":4,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/69086\/revisions"}],"predecessor-version":[{"id":69092,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/69086\/revisions\/69092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/69089"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=69086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=69086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=69086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}