{"id":64385,"date":"2025-07-24T14:19:10","date_gmt":"2025-07-24T20:19:10","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=64385"},"modified":"2025-07-24T14:21:55","modified_gmt":"2025-07-24T20:21:55","slug":"maru-se-reune-con-alcaldes-para-definir-acciones-contra-el-sarampion-en-la-entidad","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/maru-se-reune-con-alcaldes-para-definir-acciones-contra-el-sarampion-en-la-entidad\/","title":{"rendered":"Maru habla con alcaldes para definir m\u00e1s acciones contra el sarampi\u00f3n en toda la entidad"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"592\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/Maru-habla-con-alcaldes-para-definir-mas-acciones-contra-el-sarampion-en-toda-la-entidad-1024x592.jpeg\" alt=\"Maru habla con alcaldes para definir ma\u0301s acciones contra el sarampio\u0301n en toda la entidad\" class=\"wp-image-64391\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/Maru-habla-con-alcaldes-para-definir-mas-acciones-contra-el-sarampion-en-toda-la-entidad-1024x592.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/Maru-habla-con-alcaldes-para-definir-mas-acciones-contra-el-sarampion-en-toda-la-entidad-300x173.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/Maru-habla-con-alcaldes-para-definir-mas-acciones-contra-el-sarampion-en-toda-la-entidad-768x444.jpeg 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/Maru-habla-con-alcaldes-para-definir-mas-acciones-contra-el-sarampion-en-toda-la-entidad.jpeg 1079w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em>Chihuahua, Chih<\/em>.- Con el objetivo de llevar vacunas al mayor n\u00famero de personas en el estado, la gobernadora Maru Campos reuni\u00f3 a los alcaldes de los 67 municipios, a quienes pidi\u00f3 mantener su colaboraci\u00f3n con las instituciones estatales y federales de salud, en las jornadas intensivas de vacunaci\u00f3n contra el sarampi\u00f3n.<\/p>\n\n\n\n<p>En la sesi\u00f3n de trabajo tambi\u00e9n estuvieron el secretario de salud Gilberto Baeza; el subsecretario de Pol\u00edticas de Salud y Bienestar, Ramiro L\u00f3pez Elizalde; la directora del Centro Nacional para la Salud de la Infancia y la Adolescencia, Samantha Gardner.<\/p>\n\n\n\n<p>Adem\u00e1s de Andr\u00e9s Casta\u00f1eda, director general del Sistema Nacional de Salud P\u00fablica; Miguel \u00c1ngel Lezana, director general de Epidemiolog\u00eda y Leticia Ru\u00edz Gonz\u00e1lez, encargada de la Subsecretar\u00eda de Prevenci\u00f3n y Promoci\u00f3n de la Salud.<\/p>\n\n\n\n<p>Los participantes dieron seguimiento a los acuerdos establecidos en la sesi\u00f3n de trabajo realizada previamente con las autoridades de salud federal, que se enfoc\u00f3 en definir acciones y estrategias que permitan atender de manera puntual el tema sanitario y cumplir con la meta de aplicar 500 mil dosis en los pr\u00f3ximos d\u00edas.<\/p>\n\n\n\n<p>Entre los compromisos establecidos, se incluyen alianzas con l\u00edderes sociales, religiosos y empresariales.<\/p>\n\n\n\n<p>De igual manera con asociaciones de padres de familia, hoteleros y empleadores del sector agr\u00edcola.<\/p>\n\n\n\n<p>De esta forma, el Gobierno del Estado reitera su compromiso con la salud y el bienestar de los chihuahuenses, particularmente ni\u00f1as y ni\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chihuahua, Chih.- Con el objetivo de llevar vacunas al mayor n\u00famero de personas en el estado, la gobernadora Maru Campos reuni\u00f3 a los alcaldes de los 67 municipios, a quienes pidi\u00f3 mantener su colaboraci\u00f3n con las instituciones estatales y federales de salud, en las jornadas intensivas de vacunaci\u00f3n contra el sarampi\u00f3n. En la sesi\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":64391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Maru habla con alcaldes para definir m\u00e1s acciones contra el sarampi\u00f3n en toda la entidad - Opini\u00f3n P\u00fablica","description":"Chihuahua, Chih .- Con el objetivo de llevar vacunas al mayor n\u00famero de personas en el estado, la gobernadora Maru Campos reuni\u00f3 a los alcaldes de los 67 munici"},"footnotes":""},"categories":[11],"tags":[],"class_list":["post-64385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/64385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=64385"}],"version-history":[{"count":5,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/64385\/revisions"}],"predecessor-version":[{"id":64392,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/64385\/revisions\/64392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/64391"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=64385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=64385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=64385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}