{"id":64327,"date":"2025-07-24T00:01:00","date_gmt":"2025-07-24T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=64327"},"modified":"2025-07-23T18:33:59","modified_gmt":"2025-07-24T00:33:59","slug":"efemerides-24-de-julio-un-dia-como-hoy-en-la-historia","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/efemerides-24-de-julio-un-dia-como-hoy-en-la-historia\/","title":{"rendered":"Efem\u00e9rides 24 de julio | Un d\u00eda como hoy en la historia&#8230;"},"content":{"rendered":"\n<p><em>Un d\u00eda 24 de julio como hoy, pero de 1989, Time compra Warner Communication por 16 mil millones de d\u00f3lares, tras fracasar Paramount en el intento de fusi\u00f3n<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/1989-Time-compra-Warner-Communication-por-16-mil-millones-de-dolares-1024x576.webp\" alt=\"1989, time compra warner communication por 16 mil millones de do\u0301lares\" class=\"wp-image-64328\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/1989-Time-compra-Warner-Communication-por-16-mil-millones-de-dolares-1024x576.webp 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/1989-Time-compra-Warner-Communication-por-16-mil-millones-de-dolares-300x169.webp 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/1989-Time-compra-Warner-Communication-por-16-mil-millones-de-dolares-768x432.webp 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/1989-Time-compra-Warner-Communication-por-16-mil-millones-de-dolares-1536x864.webp 1536w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/1989-Time-compra-Warner-Communication-por-16-mil-millones-de-dolares.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Otras efem\u00e9rides<\/strong><\/p>\n\n\n\n<p>1820.- Publican en Guatemala el primer n\u00famero del semanario &#8216;El Editor Constitucional&#8217;, dirigido por Pedro Molina, uno de los art\u00edfices de la independencia y presidente de la Rep\u00fablica.<\/p>\n\n\n\n<p>1823.- Batalla naval de Maracaibo: victoria del almirante colombiano Jos\u00e9 Padilla sobre la escuadra espa\u00f1ola. Se afianza la independencia venezolana.<\/p>\n\n\n\n<p>1823.- Chile aprueba la abolici\u00f3n absoluta de la esclavitud. Declara libres a todos los esclavos del pa\u00eds y a todos los que a \u00e9l lleguen, con lo que se convierte en el pionero en Am\u00e9rica en liberarlos.<\/p>\n\n\n\n<p>1905.- El zar Nicol\u00e1s II y el kaiser Guillermo II firman el tratado secreto de Bj\u00f6rk\u00f6 de defensa mutua ante cualquier agresi\u00f3n por un Estado europeo.<\/p>\n\n\n\n<p>1911.- Per\u00fa: Expedici\u00f3n de Hiram Bingham, que da conocer al mundo la existencia de Machu Picchu.<\/p>\n\n\n\n<p>1917.- La bailarina neerlandesa Mata-Hari comparece ante un Consejo de Guerra en Par\u00eds que la condena a muerte al d\u00eda siguiente por espiar para Alemania.<\/p>\n\n\n\n<p>1923.- Tratado de Lausana, que delimita las fronteras de Turqu\u00eda y Grecia, y prev\u00e9 la desmilitarizaci\u00f3n de los estrechos.<\/p>\n\n\n\n<p>1941.- Batalla de Zarumilla: las tropas peruanas derrotan a las ecuatorianas en Tumbes.<\/p>\n\n\n\n<p>1943.- II Guerra Mundial: aviaci\u00f3n aliada inicia seis d\u00edas de intensos bombardeos sobre Hamburgo, su puerto y un centro de construcci\u00f3n de submarinos.<\/p>\n\n\n\n<p>1968.- El boxeador hispanocubano Jos\u00e9 Legr\u00e1 gana el t\u00edtulo mundial del peso pluma al vencer al brit\u00e1nico Howard Winstone, en Porthcawl (Gales).<\/p>\n\n\n\n<p>1969.- El Apolo XII cae en el Pac\u00edfico, cerca de Haw\u00e1i, 8 d\u00edas despu\u00e9s de iniciar la misi\u00f3n a la Luna.<\/p>\n\n\n\n<p>1974.- Constantino Caramanlis jura como primer ministro de Grecia tras el abandono del general Phaedon Ghizikis, jefe del Gobierno de los coroneles.<\/p>\n\n\n\n<p>1975.- Giorgio Armani y Sergio Galeottie fundan la empresa de moda Giorgio Armani, en Mil\u00e1n.<\/p>\n\n\n\n<p>1986.- Gustavo Arias Londono, &#8216;Boris&#8217;, responsable militar del guerrillero M-19, muere a manos de la Polic\u00eda en Medell\u00edn (Colombia).<\/p>\n\n\n\n<p>1989.- El Gobierno de M\u00e9xico acuerda con la banca privada internacional reducir su deuda exterior de 53 mil millones de d\u00f3lares en un 35 %, mediante la renuncia de la banca a parte de los pr\u00e9stamos y establecer un inter\u00e9s para el resto a 30 a\u00f1os.<\/p>\n\n\n\n<p>1990.- Irak env\u00eda 30 mil soldados a su frontera con Kuwait y EEUU decreta el estado de alerta de su flota en el golfo P\u00e9rsico.<\/p>\n\n\n\n<p>1994.- Se constituye la Asociaci\u00f3n de Estados del Caribe (AEC), en Cartagena de Indias (Colombia).<\/p>\n\n\n\n<p>2000.- El Partido Comunista de Chile se querella contra Pinochet por la desaparici\u00f3n de 137 de sus militantes tras el golpe de 1973.<\/p>\n\n\n\n<p>2000.- El gobierno brit\u00e1nico comienza la excarcelaci\u00f3n de 87 terroristas norirlandeses condenados por m\u00faltiples asesinatos, en aplicaci\u00f3n del Acuerdo de Paz del Ulster.<\/p>\n\n\n\n<p>2002.- La justicia argentina acata el decreto que suspende por 120 d\u00edas la ejecuci\u00f3n de fallos contra el &#8216;corralito&#8217; que retiene millonarios dep\u00f3sitos bancarios.<\/p>\n\n\n\n<p>2003.- La C\u00e1mara de Representantes de EEUU aprueba el Tratado de Libre Comercio (TLC) con Chile.<\/p>\n\n\n\n<p>2014.- Fallecen los 116 ocupantes del avi\u00f3n de la espa\u00f1ola Switfair, operado por Air Algerie, que se estrella entre la frontera de Burkina Faso y Gao (Mali).<\/p>\n\n\n\n<p>2015.- Turqu\u00eda bombardea por vez primera posiciones del Estado Isl\u00e1mico (EI) en Siria y abre sus bases a los aviones de la coalici\u00f3n liderada por EEUU.<\/p>\n\n\n\n<p>2019.- Boris Johnson, l\u00edder del Partido Conservador brit\u00e1nico desde el d\u00eda anterior, asume el cargo de primer ministro, en sustituci\u00f3n de Theresa May.<\/p>\n\n\n\n<p>2019.- Dimite el gobernador de Puerto Rico, Ricardo Rossell\u00f3, tras participar en un chat privado con burlas a colectivos, salida efectiva que se produce en agosto.<\/p>\n\n\n\n<p><strong>Nacimientos<\/strong><\/p>\n\n\n\n<p>1783.- Sim\u00f3n Bol\u00edvar, &#8216;el Libertador&#8217;, militar y pol\u00edtico venezolano.<\/p>\n\n\n\n<p>1802.- Alejandro Dumas, dramaturgo franc\u00e9s.<\/p>\n\n\n\n<p>1841.- Raimundo Madrazo, pintor espa\u00f1ol.<\/p>\n\n\n\n<p>1870.- Alphonsus de Guimaraens, poeta brasile\u00f1o.<\/p>\n\n\n\n<p>1895.- Robert Graves, escritor brit\u00e1nico.<\/p>\n\n\n\n<p>1897.- Amelia Earhart, pionera estadounidense de la aviaci\u00f3n.<\/p>\n\n\n\n<p>1925.- Ignacio Aldecoa, novelista espa\u00f1ol.<\/p>\n\n\n\n<p>1964.- Pedro Passos Coelho, pol\u00edtico portugu\u00e9s.<\/p>\n\n\n\n<p>1969.- Jennifer L\u00f3pez, actriz y cantante estadounidense de origen puertorrique\u00f1o.<\/p>\n\n\n\n<p>1981.- Nayib Bukele, presidente de El Salvador.<\/p>\n\n\n\n<p><strong>Defunciones<\/strong><\/p>\n\n\n\n<p>1957.- Sacha Guitry, actor, dramaturgo y cineasta franc\u00e9s.<\/p>\n\n\n\n<p>1974.- James Chadwick, f\u00edsico ingl\u00e9s, descubridor del neutr\u00f3n y Nobel 1935.<\/p>\n\n\n\n<p>1980.- Peter Sellers, actor brit\u00e1nico.<\/p>\n\n\n\n<p>1984.- Jos\u00e9 Mauro de Vasconcelos, escritor brasile\u00f1o.<\/p>\n\n\n\n<p>1991.- Isaac Bashevis Singer, escritor estadounidense de origen polaco y Nobel 1978.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00eda 24 de julio como hoy, pero de 1989, Time compra Warner Communication por 16 mil millones de d\u00f3lares, tras fracasar Paramount en el intento de fusi\u00f3n. Otras efem\u00e9rides 1820.- Publican en Guatemala el primer n\u00famero del semanario &#8216;El Editor Constitucional&#8217;, dirigido por Pedro Molina, uno de los art\u00edfices de la independencia y presidente [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":64328,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Efem\u00e9rides 24 de julio | Un d\u00eda como hoy en la historia... - Opini\u00f3n P\u00fablica","description":"Un d\u00eda 24 de julio como hoy, pero de 1989, Time compra Warner Communication por 16 mil millones de d\u00f3lares, tras fracasar Paramount en el intento de fusi\u00f3n . Ot"},"footnotes":""},"categories":[27],"tags":[],"class_list":["post-64327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-dia-como-hoy"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/64327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=64327"}],"version-history":[{"count":1,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/64327\/revisions"}],"predecessor-version":[{"id":64329,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/64327\/revisions\/64329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/64328"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=64327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=64327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=64327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}