{"id":63503,"date":"2025-07-12T00:01:00","date_gmt":"2025-07-12T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=63503"},"modified":"2025-07-11T17:48:16","modified_gmt":"2025-07-11T23:48:16","slug":"el-cierre-de-frontera-al-ganado-mexicano-tiene-un-costo-de-661-millones-de-dolares","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/el-cierre-de-frontera-al-ganado-mexicano-tiene-un-costo-de-661-millones-de-dolares\/","title":{"rendered":"Cierre de frontera al ganado mexicano tiene costo de 661 millones de d\u00f3lares"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"620\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/Cierre-de-frontera-al-ganado-mexicano-tiene-costo-de-661-millones-de-dolares-1024x620.avif\" alt=\"Cierre de frontera al ganado mexicano tiene costo de 661 millones de do\u0301lares\" class=\"wp-image-63508\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/Cierre-de-frontera-al-ganado-mexicano-tiene-costo-de-661-millones-de-dolares-1024x620.avif 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/Cierre-de-frontera-al-ganado-mexicano-tiene-costo-de-661-millones-de-dolares-300x182.avif 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/Cierre-de-frontera-al-ganado-mexicano-tiene-costo-de-661-millones-de-dolares-768x465.avif 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/07\/Cierre-de-frontera-al-ganado-mexicano-tiene-costo-de-661-millones-de-dolares.avif 1100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El cierre de fronteras de Estados Unidos al ganado mexicano ha tenido un costo de 11.4 millones de d\u00f3lares diarios, que del 11 de mayo al 7 de julio sumaban 661 millones de d\u00f3lares, indican organismos del sector agropecuario del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La afectaci\u00f3n es de esa magnitud si se considera que se cerr\u00f3 el paso al ganado en pie desde el 11 de mayo y se volvi\u00f3 a abrir \u2014s\u00f3lo dos d\u00edas\u2014 del 7 al 9 de julio, para volver a cerrar; mientras, los precios se ubicaron en alrededor de 2 mil d\u00f3lares por cabeza, explic\u00f3 el director del Consejo Nacional Agropecuario (CNA), Luis Fernando Haro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, habr\u00eda al menos 300 mil cabezas de ganado rezagadas en Sonora y Chihuahua, de acuerdo con ganaderos de esos estados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luis Fernando Haro precis\u00f3 que previo a que Estados Unidos prohibiera la entrada de ganado mexicano a su territorio, a causa de los casos de gusano barrenador, se registraba un cruce diario de 5 mil 700 cabezas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos hablando de que despu\u00e9s del 11 de mayo dejaron de ingresar 11.4 millones de d\u00f3lares diarios\u201d, resalta Haro en entrevista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dice que \u201chay un impacto importante, aunque no son p\u00e9rdidas, porque el ganado est\u00e1 del lado mexicano, pero no se ha comercializado\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre el anuncio hecho la noche del mi\u00e9rcoles por la secretaria de Agricultura de Estados Unidos, Brooke Rollins, para un nuevo cierre de fronteras, afirma que \u201ces injusto, es una medida unilateral\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn un a\u00f1o normal se exportan m\u00e1s de un mill\u00f3n de cabezas de ganado, y este a\u00f1o no se va a lograr esa cantidad\u201d, afirma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lo que va del presente a\u00f1o y hasta la primera quincena de junio, el CNA contabiliz\u00f3 la exportaci\u00f3n de 226 mil cabezas de ganado, casi una tercera parte de las 674 mil enviadas en el mismo periodo de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con cifras del Departamento de Comercio de Estados Unidos, en abril se export\u00f3 ganado de M\u00e9xico a Estados Unidos por un valor de 123 millones 817 mil d\u00f3lares, pero en mayo el monto cay\u00f3 a 45 millones 677 mil d\u00f3lares, es decir un desplome de 63%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Haro recuerda que se hab\u00eda anunciado una apertura gradual por parte de la Secretar\u00eda de Agricultura a partir del lunes pasado para el cruce de Agua Prieta, Sonora, y se esperaba que el 14 de julio se abriera en Chihuahua, pero apareci\u00f3 un nuevo caso de gusano barrenador en la zona centro-norte de Veracruz, y Estados Unidos volvi\u00f3 a cerrar fronteras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cVuelven a tomar la determinaci\u00f3n de cerrar. Hemos sido vocales de que era algo injusto porque en la frontera no existe el gusano barrenador, y tienen protocolos muy exhaustivos\u201d, afirma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que hay protocolos, tratamiento y puntos de verificaci\u00f3n e inspecci\u00f3n gracias a los que se puede afirmar que el ganado que cruza est\u00e1 100% garantizado e incluso hay zonas protegidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Miles cabezas de ganado en espera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mauro Parada Mu\u00f1oz, titular de la Secretar\u00eda de Desarrollo Rural de Chihuahua, declar\u00f3 que en la entidad habr\u00edan 200 mil animales en espera. En Sonora, Juan Ochoa Valenzuela, presidente de la Uni\u00f3n Ganadera Regional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este contexto, el gobierno de Sonora pidi\u00f3 que se haga una excepci\u00f3n con la entidad y propuso crear una ciudad ganadera industrial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe parece que en el caso del estado de Sonora deber\u00eda hacerse la excepci\u00f3n, en virtud de que no tiene hist\u00f3ricamente, absolutamente, ning\u00fan caso relacionado [de gusano barrenador]\u201d, argument\u00f3 el gobernador Alfonso Durazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que se envi\u00f3 a la Secretar\u00eda de Agricultura y Desarrollo Rural (Sader) la propuesta de crear una ciudad ganadera industrial que permita sacrificar con la m\u00e1s avanzada tecnolog\u00eda, cortar, empaquetar, congelar y enviar la carne a Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Coahuila, el presidente de la Uni\u00f3n Ganadera Regional del estado, Abel Ayala, calific\u00f3 el nuevo cierre de la frontera como un \u201cduro golpe, inesperado, desafortunado y profundamente preocupante\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es el tercer cierre al paso de ganado en pie en ocho meses y medio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Durango, Rogelio Soto Ochoa, presidente de la Uni\u00f3n Ganadera Regional de esa entidad, hizo un llamado a las grandes engordadoras para evitar que se disperse la plaga. (El Universal)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cierre de fronteras de Estados Unidos al ganado mexicano ha tenido un costo de 11.4 millones de d\u00f3lares diarios, que del 11 de mayo al 7 de julio sumaban 661 millones de d\u00f3lares, indican organismos del sector agropecuario del pa\u00eds. La afectaci\u00f3n es de esa magnitud si se considera que se cerr\u00f3 el paso [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":63508,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Cierre de frontera al ganado mexicano tiene costo de 661 millones de d\u00f3lares - Opini\u00f3n P\u00fablica","description":"El cierre de fronteras de Estados Unidos al ganado mexicano ha tenido un costo de 11.4 millones de d\u00f3lares diarios, que del 11 de mayo al 7 de julio sumaban 661"},"footnotes":""},"categories":[3],"tags":[],"class_list":["post-63503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/63503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=63503"}],"version-history":[{"count":4,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/63503\/revisions"}],"predecessor-version":[{"id":63509,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/63503\/revisions\/63509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/63508"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=63503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=63503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=63503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}