{"id":59917,"date":"2025-05-21T00:01:00","date_gmt":"2025-05-21T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=59917"},"modified":"2025-05-20T19:00:29","modified_gmt":"2025-05-21T01:00:29","slug":"trump-anuncia-construccion-de-cupula-dorada-para-proteger-a-eu-costara-175-mil-mdd","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/trump-anuncia-construccion-de-cupula-dorada-para-proteger-a-eu-costara-175-mil-mdd\/","title":{"rendered":"Anuncia Trump construcci\u00f3n de \u00abc\u00fapula dorada\u00bb de 175 mil millones para proteger a EU"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1100\" height=\"666\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/05\/Trump-anuncia-construccion-de-22cupula-dorada22-de-175-mil-millones-para-proteger-a-EU.avif\" alt=\"Trump anuncia construccio\u0301n de %22cu\u0301pula dorada%22 de 175 mil millones para proteger a eu\" class=\"wp-image-59921\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Washington, DC. EU<\/em>.- El presidente estadounidense, Donald Trump, anunci\u00f3 la construcci\u00f3n de una \u00abc\u00fapula dorada\u00bb, que servir\u00eda para proteger el pa\u00eds, con un costo aproximado de 175 mil millones de d\u00f3lares y se espera que est\u00e9 finalizada para el final de su mandato en 2029.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump dijo en la Oficina Oval que ha seleccionado oficialmente una arquitectura para el escudo antimisiles \u00abC\u00fapula Dorada\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abUna vez construida en su totalidad, la C\u00fapula Dorada ser\u00e1 capaz de interceptar misiles aunque se lancen desde otras partes del mundo\u00bb, e incluso \u00abdesde el espacio\u00bb, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que el sistema usar\u00e1 tecnolog\u00eda \u00abde \u00faltima generaci\u00f3n\u00bb. Asegur\u00f3 que Canad\u00e1 \u00abquiere ser parte de esto\u00bb, as\u00ed que \u00abcomo siempre, protegeremos a Canad\u00e1\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detall\u00f3 que la C\u00fapula Dorada se integrar\u00e1 con \u00abnuestras capacidades de Defensa\u00bb. Seg\u00fan indic\u00f3 en una rueda de prensa junto al secretario de Defensa, Pete Hegseth, el proyecto de ley de presupuestos que quiere ver aprobado en el Congreso contemplar\u00e1 una partida inicial de 25.000 millones que sirva para impulsar su desarrollo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abDeber\u00eda estar completamente operativo antes de que termine mi mandato, as\u00ed que lo tendremos listo en unos tres a\u00f1os. Una vez construido podr\u00e1 interceptar misiles incluso si se lanzan desde otras partes del mundo y desde el espacio\u00bb, dijo el l\u00edder republicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Trump, Estados Unidos tendr\u00e1 \u00abel mejor sistema jam\u00e1s construido\u00bb. \u00abAyudamos a Israel con el suyo y tuvimos mucho \u00e9xito. Ahora contamos con tecnolog\u00eda mucho m\u00e1s avanzada, que incluye misiles hipers\u00f3nicos, misiles bal\u00edsticos y misiles de crucero avanzados\u00bb, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario anunci\u00f3 en marzo, cuando se dirigi\u00f3 a la sesi\u00f3n conjunta del Congreso, su intenci\u00f3n de construir esta c\u00fapula y pidi\u00f3 a los legisladores que \u00abfinanciasen un escudo antimisiles de c\u00fapula dorada de \u00faltima generaci\u00f3n para proteger la patria, fabricado en Estados Unidos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese primer discurso hizo referencia al Iron Dome (c\u00fapula de hierro en ingl\u00e9s) de Israel, pero el proyecto que lanza EU, tal y como recalc\u00f3 este martes, es m\u00e1s avanzado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El sistema israel\u00ed se encarga de interceptar y destruir cohetes de corto alcance y drones en zonas pobladas con una alta precisi\u00f3n y, seg\u00fan recogen algunos medios, cada misil interceptado le cuesta al pa\u00eds unos 50.000 d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cadena CNN hab\u00eda avanzado que la oficina presupuestaria del Congreso ha estimado que EU podr\u00eda tener que gastar m\u00e1s de 500.000 millones de d\u00f3lares en 20 a\u00f1os para tener una \u00abc\u00fapula dorada\u00bb que funcione correctamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump destac\u00f3 que Canad\u00e1 ha pedido ser parte del proyecto. \u00abTiene todo el sentido y no ser\u00e1 muy dif\u00edcil hacerlo, pero pagar\u00e1n su justa parte\u00bb, dijo sobre la implicaci\u00f3n de su vecino del norte, con el que se\u00f1al\u00f3 que todav\u00eda no han cerrado los detalles econ\u00f3micos de su participaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTen\u00eda muchas ganas de que llegara este d\u00eda porque es fundamental para el \u00e9xito e incluso la supervivencia de nuestro pa\u00eds. Vivimos en un mundo malvado. As\u00ed que esto contribuye enormemente a la supervivencia de este gran pa\u00eds\u00bb, a\u00f1adi\u00f3 el mandatario republicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El secretario Hegseth consider\u00f3 que los \u00abenemigos del pa\u00eds\u00bb van a prestar mucha atenci\u00f3n al proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNuestros enemigos, nuestros adversarios, prestar\u00e1n mucha atenci\u00f3n a esto, al igual que le han prestado atenci\u00f3n al presidente Trump desde el primer d\u00eda. As\u00ed que est\u00e1 defendiendo la patria, defendiendo al pueblo estadounidense. Beneficiar\u00e1 a mis hijos, a mis nietos, a todos nosotros\u00bb, destac\u00f3. (El Universal)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington, DC. EU.- El presidente estadounidense, Donald Trump, anunci\u00f3 la construcci\u00f3n de una \u00abc\u00fapula dorada\u00bb, que servir\u00eda para proteger el pa\u00eds, con un costo aproximado de 175 mil millones de d\u00f3lares y se espera que est\u00e9 finalizada para el final de su mandato en 2029. Trump dijo en la Oficina Oval que ha seleccionado oficialmente [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":59921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Anuncia Trump construcci\u00f3n de \"c\u00fapula dorada\" de 175 mil millones para proteger a EU - Opini\u00f3n P\u00fablica","description":"Washington, DC. EU .- El presidente estadounidense, Donald Trump, anunci\u00f3 la construcci\u00f3n de una \"c\u00fapula dorada\", que servir\u00eda para proteger el pa\u00eds, con un cos"},"footnotes":""},"categories":[4],"tags":[],"class_list":["post-59917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pulsopolitico"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/59917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=59917"}],"version-history":[{"count":4,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/59917\/revisions"}],"predecessor-version":[{"id":59923,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/59917\/revisions\/59923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/59921"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=59917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=59917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=59917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}