{"id":56045,"date":"2025-03-28T00:01:00","date_gmt":"2025-03-28T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=56045"},"modified":"2025-03-27T21:23:34","modified_gmt":"2025-03-28T03:23:34","slug":"en-proximas-semanas-se-firmaria-programa-para-estabilizar-precios-de-tortilla","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/en-proximas-semanas-se-firmaria-programa-para-estabilizar-precios-de-tortilla\/","title":{"rendered":"En pr\u00f3ximas semanas se firmar\u00eda un programa para estabilizar precios de tortilla"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"707\" height=\"491\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/03\/En-proximas-semanas-se-firmaria-un-programa-para-estabilizar-precios-de-tortilla.webp\" alt=\"En pro\u0301ximas semanas se firmari\u0301a un programa para estabilizar precios de tortilla\" class=\"wp-image-56048\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/03\/En-proximas-semanas-se-firmaria-un-programa-para-estabilizar-precios-de-tortilla.webp 707w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/03\/En-proximas-semanas-se-firmaria-un-programa-para-estabilizar-precios-de-tortilla-300x208.webp 300w\" sizes=\"(max-width: 707px) 100vw, 707px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ciudad de M\u00e9xico<\/em>.- Tras una serie reuniones inciadas desde octubre, organizaciones de la industria de la masa y la tortilla adelantaron que en las pr\u00f3ximas semanas se podr\u00eda firmar con el gobierno federal el programa para poder formalizar al sector y estabilizar los precios del producto, que implicar\u00eda reducir 5 por ciento el costo de la tortilla en negocios que superen los 22 pesos el precio en mostrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de los procesos para bajar 10 por ciento el precio de este alimento con la Secretar\u00eda de Agricultura y Desarrollo Rural (Sader) en este sexenio, Sergio Jarqu\u00edn Mu\u00f1oz, presidente nacional del Consejo Rector de la Tortilla Tradicional Mexicana, indic\u00f3 a La Jornada que los beneficios ser\u00edan en un inicio para 15 mil o 20 mil tortiller\u00edas de las 110 mil registradas por el Instituto Nacional de Estad\u00edstica y Geograf\u00eda a nivel nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de considerar a la Zona Metropolitana, donde habr\u00e1 6 mil beneficiados en un inicio, confirm\u00f3 que se contemplar\u00edan los estados de Puebla, Veracruz, Tlaxcala, Hidalgo y Chiapas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegur\u00f3 que m\u00e1s establecimientos se podr\u00edan integrar tras la publicaci\u00f3n al programa, siempre y cuando cumplan con normas regulatorias, como el registro ante la Secretar\u00eda de Hacienda o paguen el seguro social a sus trabajadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los compromisos que se pactar\u00edan, se\u00f1al\u00f3, figuran la reducci\u00f3n de otras materias primas, algunos cr\u00e9ditos para maquinaria, una l\u00ednea de atenci\u00f3n directa con la Secretar\u00eda de Seguridad Ciudadana, la creaci\u00f3n de un buz\u00f3n de denuncias con la Profeco para inhibir la competencia desleal o venta ilegal de tortillas fuera de los establecimientos y atenci\u00f3n a la norma oficial mexicana 187 (que establece los est\u00e1ndares para la elaboraci\u00f3n de productos y reglamentaci\u00f3n de los establecimientos).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa intenci\u00f3n de este programa es que la poblaci\u00f3n regrese a las tortiller\u00edas a comprar, y sea el m\u00e1s beneficiado con precios accesibles\u201d, coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detall\u00f3 que se afinan los \u00faltimos detalles para concretar la firma de programa, como ver si se incorpora la empresa Maseca, de grupo Gruma, o se concretan puntos m\u00ednimos en las negociaciones, como obtener m\u00e1s apoyos para el sector. Previ\u00f3 que la firma se podr\u00eda dar en la siguientes dos o tres semanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las problem\u00e1ticas, se\u00f1al\u00f3 que en el centro de la ciudad el kilo oscila entre los 22 y 23 pesos por kilo, y en otras regiones del pa\u00eds alcanza los 32, pero en el mercado informal se han encontrado bajos que llegan hasta los 15 pesos, lo que afecta al sector. Apunt\u00f3 que tambi\u00e9n la especulaci\u00f3n en el mercado del ma\u00edz es otro factor que encarece los precios dependiendo de cada acontecimiento que surja en el sector, como la falta de producci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El l\u00edder productor confirm\u00f3 que hay abasto suficiente de ma\u00edz para atender la demanda de la industria de la masa y la tortilla. Constat\u00f3 que el precio por tonelada de maiz para el sector tortillero se encuentran en 6 mil pesos, cuando en otros a\u00f1os se encareci\u00f3 por arriba de los 10 mil pesos por asuntos de especulaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s del Consejo Rector de la Tortilla Tradicional, recapitul\u00f3 que en las negociaciones con la Sader a\u00fan participan la Uni\u00f3n Nacional de los Industriales de la Masa y la Tortilla, la C\u00e1mara Regional de la Industria de la Masa y Tortilla e Industrias del Ma\u00edz Puebla. Durante el proceso se retiraron el Consejo Nacional de la Tortilla y la C\u00e1mara Nacional de la Industria de Producci\u00f3n de Masa y Tortilla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Buscan el cumplimento de contrato<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Blanca Estela Mej\u00eda Castillo, representante legal del Consejo Rector de la Tortilla Tradicional, apunt\u00f3 que la Sader, a trav\u00e9s de Diconsa, incumpli\u00f3 un contrato firmado en el sexenio pasado para la compra de 50 mil toneladas de ma\u00edz, de las cuales se entregaron unas 7 mil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el contrato figuraban compradores de la Ciudad de M\u00e9xico, Estado de M\u00e9xico, Hidalgo, Morelos y Puebla. Acus\u00f3 que el producto probablemente fue distribuido a las harineras o en el mercado negro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo este escenario, asegur\u00f3 que se busca se cumpla con ese compromiso con la finalidad de evitar un escenario que les afecte a nivel regional, como una situaci\u00f3n de desabasto o de especulaci\u00f3n. (La Jornada)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico.- Tras una serie reuniones inciadas desde octubre, organizaciones de la industria de la masa y la tortilla adelantaron que en las pr\u00f3ximas semanas se podr\u00eda firmar con el gobierno federal el programa para poder formalizar al sector y estabilizar los precios del producto, que implicar\u00eda reducir 5 por ciento el costo de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":56048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"En pr\u00f3ximas semanas se firmar\u00eda un programa para estabilizar precios de tortilla - Opini\u00f3n P\u00fablica","description":"Ciudad de M\u00e9xico .- Tras una serie reuniones inciadas desde octubre, organizaciones de la industria de la masa y la tortilla adelantaron que en las pr\u00f3ximas sem"},"footnotes":""},"categories":[4],"tags":[],"class_list":["post-56045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pulsopolitico"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/56045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=56045"}],"version-history":[{"count":2,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/56045\/revisions"}],"predecessor-version":[{"id":56049,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/56045\/revisions\/56049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/56048"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=56045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=56045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=56045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}