{"id":52424,"date":"2025-01-30T00:01:00","date_gmt":"2025-01-30T07:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=52424"},"modified":"2025-01-29T21:04:03","modified_gmt":"2025-01-30T04:04:03","slug":"la-frontera-norte-de-mexico-esta-viviendo-una-profunda-crisis-revela-estudio","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/la-frontera-norte-de-mexico-esta-viviendo-una-profunda-crisis-revela-estudio\/","title":{"rendered":"La frontera norte de M\u00e9xico est\u00e1 viviendo una profunda crisis; revela estudio"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1100\" height=\"666\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2025\/01\/La-frontera-norte-de-Mexico-esta-viviendo-una-profunda-crisis-revela-estudio.avif\" alt=\"La Frontera Norte De Me\u0301xico Esta\u0301 Viviendo Una Profunda Crisis; Revela Estudio\" class=\"wp-image-52426\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Bruselas<\/em>.- La dura pol\u00edtica migratoria introducida por el presidente estadounidense Donald Trump llega en un momento en el que la frontera norte de M\u00e9xico est\u00e1 sumida en una enorme crisis por la ausencia de una respuesta integral duradera para atender las necesidades que enfrentan miles de personas en movimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La decisi\u00f3n de Trump de deportar masivamente a indocumentados, militarizar la frontera, suspender la aplicaci\u00f3n digital de asignaci\u00f3n de citas migratorias CBP One y ampliar las competencias del Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE), exacerbar\u00e1 la ya precaria situaci\u00f3n que experimenta la frontera compartida con la Uni\u00f3n Americana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para comprender la situaci\u00f3n de la poblaci\u00f3n mexicana en movimiento en Baja California, Chihuahua, Sonora y Nuevo Le\u00f3n, el Consejo Noruego para Refugiados (NRC) y el Comit\u00e9 Internacional de Rescate (IRC) hicieron un estudio, con fecha de diciembre y que se basa en 284 encuestas en hogares, 16 entrevistas a informantes clave y cuatro mesas de discusi\u00f3n con grupos focales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta poblaci\u00f3n se encuentra en una situaci\u00f3n particularmente vulnerable, sin opciones viables: la mayor\u00eda no puede regresar a sus lugares de origen debido a la violencia y la inseguridad, mientras que el acceso a protecci\u00f3n internacional en Estados Unidos se ve obstaculizado por pol\u00edticas restrictivas y largos tiempos de espera. En su ubicaci\u00f3n actual se enfrentan a necesidades de protecci\u00f3n y asistencia, mientras que las respuestas y servicios disponibles presentan brechas importantes\u201d, se\u00f1ala el estudio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el an\u00e1lisis, una de cada cuatro personas reporta alg\u00fan tipo de abuso, siendo las amenazas el fen\u00f3meno m\u00e1s com\u00fan. Tambi\u00e9n se documentaron casos de violencia f\u00edsica, desaparici\u00f3n, detenci\u00f3n arbitraria, discriminaci\u00f3n, intentos de reclutamiento por grupos criminales, robos y violencia basada en g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDe manera alarmante, 7% del total de encuestados reportaron casos de secuestro de ellos mismos o de familiares\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas mujeres enfrentan mayores riesgos y violencia: han huido por violencia y amenazas en mayor proporci\u00f3n y presentan mayor imposibilidad de retorno, ya que 67% reporta que retornar representa un riesgo contra su vida, versus 39% de los hombres\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a los perpetradores de los abusos, las organizaciones criminales fueron identificadas como las principales responsables, seguidas por autoridades estatales y miembros de la comunidad, aunque casi dos de cada 10 v\u00edctimas prefiri\u00f3 no identificar al actor responsable, por temor a represalias. \u201cCuando hablas de Tijuana hablas de muerte, hablas de necesidad, de narco, de delincuencia\u201d, dijo una mujer en un albergue citada en el reporte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al riesgo de protecci\u00f3n se a\u00f1ade una situaci\u00f3n de inestabilidad. S\u00f3lo 25% cuenta con ingresos por empleo u otra actividad econ\u00f3mica; 35% carece de documentos esenciales para acceder a servicios, y s\u00f3lo la mitad de los hogares con menores de edad reporta que los ni\u00f1os asisten a la escuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El informe recomienda a las autoridades aplicar programas orientados hacia una integraci\u00f3n efectiva. \u201cAlgunos albergues, preocupados por la seguridad de sus residentes, les aconsejan no salir, lo que resulta que las \u00fanicas fuentes de ingreso sean actividades dentro del albergue o remesas de familiares en Estados Unidos\u201d, ejemplifica el reporte, que a\u00f1ade que no hay datos oficiales sobre la magnitud de las personas afectadas. El Internal Displacement Monitoring Centre (IDMC) estima que en el pa\u00eds hay 392 mil personas desplazadas. (El Universal)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bruselas.- La dura pol\u00edtica migratoria introducida por el presidente estadounidense Donald Trump llega en un momento en el que la frontera norte de M\u00e9xico est\u00e1 sumida en una enorme crisis por la ausencia de una respuesta integral duradera para atender las necesidades que enfrentan miles de personas en movimiento. La decisi\u00f3n de Trump de deportar [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":52426,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"La frontera norte de M\u00e9xico est\u00e1 viviendo una profunda crisis; revela estudio - Opini\u00f3n P\u00fablica","description":"Bruselas .- La dura pol\u00edtica migratoria introducida por el presidente estadounidense Donald Trump llega en un momento en el que la frontera norte de M\u00e9xico est\u00e1"},"footnotes":""},"categories":[4],"tags":[],"class_list":["post-52424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pulsopolitico"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/52424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=52424"}],"version-history":[{"count":2,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/52424\/revisions"}],"predecessor-version":[{"id":52427,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/52424\/revisions\/52427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/52426"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=52424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=52424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=52424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}