{"id":52301,"date":"2025-01-28T00:01:00","date_gmt":"2025-01-28T07:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=52301"},"modified":"2025-01-27T16:11:45","modified_gmt":"2025-01-27T23:11:45","slug":"la-mayor-operacion-de-deportacion-en-la-historia-de-eu-esta-en-marcha-dw","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/la-mayor-operacion-de-deportacion-en-la-historia-de-eu-esta-en-marcha-dw\/","title":{"rendered":"Video: Ya est\u00e1 en marcha la mayor operaci\u00f3n de deportaci\u00f3n en la historia de Estados Unidos | DW"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"La mayor operaci\u00f3n de deportaci\u00f3n en la historia de EE.UU. est\u00e1 en marcha, seg\u00fan la Casa Blanca\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/_fB0-MJlfTE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades de Estados Unidos han detenido a m\u00e1s de 500 migrantes indocumentados y deportado a otros cientos, como parte de la ofensiva migratoria del presidente Donald Trump. Desde que asumi\u00f3 el cargo, Trump ha firmado una serie de \u00f3rdenes ejecutivas sobre migraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esas \u00f3rdenes han dejado a miles de personas en un limbo en la frontera entre Estados Unidos y M\u00e9xico. Muchos llevaban meses esperando su cita con funcionarios de inmigraci\u00f3n estadounidenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Cr\u00e9ditos: DW en espa\u00f1ol<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las autoridades de Estados Unidos han detenido a m\u00e1s de 500 migrantes indocumentados y deportado a otros cientos, como parte de la ofensiva migratoria del presidente Donald Trump. Desde que asumi\u00f3 el cargo, Trump ha firmado una serie de \u00f3rdenes ejecutivas sobre migraci\u00f3n. Esas \u00f3rdenes han dejado a miles de personas en un limbo en [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":52306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Video: Ya est\u00e1 en marcha la mayor operaci\u00f3n de deportaci\u00f3n en la historia de Estados Unidos | DW - Opini\u00f3n P\u00fablica","description":"https:\/\/youtu.be\/_fB0-MJlfTE?si=HyZCM4X9zxdKHLul Las autoridades de Estados Unidos han detenido a m\u00e1s de 500 migrantes indocumentados y deportado a otros ciento"},"footnotes":""},"categories":[13,2,8],"tags":[],"class_list":["post-52301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos-destacados-contenido","category-videos-destacados","category-videos"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/52301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=52301"}],"version-history":[{"count":4,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/52301\/revisions"}],"predecessor-version":[{"id":52305,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/52301\/revisions\/52305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/52306"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=52301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=52301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=52301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}