{"id":43492,"date":"2024-09-25T00:01:00","date_gmt":"2024-09-25T06:01:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/?p=43492"},"modified":"2024-09-24T21:11:14","modified_gmt":"2024-09-25T03:11:14","slug":"inauguran-planta-eaton-dunas-en-ciudad-juarez","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/inauguran-planta-eaton-dunas-en-ciudad-juarez\/","title":{"rendered":"Inauguran planta Eaton Dunas en Ciudad Ju\u00e1rez"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2024\/09\/Inauguran-planta-Eaton-Dunas-en-Ciudad-Juarez-1024x682.jpeg\" alt=\"Inauguran Planta Eaton Dunas En Ciudad Juarez\" class=\"wp-image-43493\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2024\/09\/Inauguran-planta-Eaton-Dunas-en-Ciudad-Juarez-1024x682.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2024\/09\/Inauguran-planta-Eaton-Dunas-en-Ciudad-Juarez-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2024\/09\/Inauguran-planta-Eaton-Dunas-en-Ciudad-Juarez-768x512.jpeg 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2024\/09\/Inauguran-planta-Eaton-Dunas-en-Ciudad-Juarez-1536x1023.jpeg 1536w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2024\/09\/Inauguran-planta-Eaton-Dunas-en-Ciudad-Juarez.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ciudad Ju\u00e1rez, Chih<\/em>.- Este martes se llev\u00f3 a cabo la inauguraci\u00f3n de otra planta de la empresa Eaton Dunas, ubicada en Hacienda de las Torres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e9ctor Rafael Ortiz Orpinel, secretario de Ayuntamiento, quien acudi\u00f3 al evento en representaci\u00f3n del presidente municipal, Cruz P\u00e9rez Cu\u00e9llar, felicit\u00f3 a los empresarios por la integraci\u00f3n de esta nueva planta Eaton Dunas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCiudad Ju\u00e1rez tiene hace muchos a\u00f1os una historia de mucha lucha, mucha entrega de gente que trabaja todos los d\u00edas, que se levanta y que viene a laborar, que se entregan y producen\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAgradecemos desde el Municipio de Ju\u00e1rez y a nombre del alcalde Cruz P\u00e9rez Cu\u00e9llar, este impulso y esta nueva imagen que se est\u00e1 dando a la ciudad, el 90 por ciento de la poblaci\u00f3n sale a trabajar sin ning\u00fan problema\u201d, indic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ortiz Orpinel dijo que siempre ser\u00e1n bienvenidos los que quieran a la ciudad y quienes quieran invertir; \u201cgracias por confiar en el talento juarense, estaremos aqu\u00ed para darles la mano\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 que Eaton es una empresa l\u00edder mundial en tecnolog\u00eda de productos el\u00e9ctricos, se dedica a la fabricaci\u00f3n de transformadores el\u00e9ctricos y equipo el\u00e9ctrico, fusibles m\u00faltiples, desde automotriz hasta navales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al final, autoridades del Gobierno Municipal y Estatal, as\u00ed como empresarios hicieron un recorrido por las instalaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento estuvieron Fernando Alba Qui\u00f1onez, subsecretario de Miner\u00eda, Industria y Energ\u00eda; Ulises Fern\u00e1ndez, secretario de Innovaci\u00f3n y Desarrollo Econ\u00f3mico del Estado; Gustavo Schimdt, presidente corporativo de Eaton M\u00e9xico; V\u00edctor Vega, manager Dunas Plant y Eduardo Carbajal, manager electrical sector M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad Ju\u00e1rez, Chih.- Este martes se llev\u00f3 a cabo la inauguraci\u00f3n de otra planta de la empresa Eaton Dunas, ubicada en Hacienda de las Torres. H\u00e9ctor Rafael Ortiz Orpinel, secretario de Ayuntamiento, quien acudi\u00f3 al evento en representaci\u00f3n del presidente municipal, Cruz P\u00e9rez Cu\u00e9llar, felicit\u00f3 a los empresarios por la integraci\u00f3n de esta nueva planta [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":43493,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Inauguran planta Eaton Dunas en Ciudad Ju\u00e1rez - Opini\u00f3n P\u00fablica","description":"Ciudad Ju\u00e1rez, Chih .- Este martes se llev\u00f3 a cabo la inauguraci\u00f3n de otra planta de la empresa Eaton Dunas, ubicada en Hacienda de las Torres. H\u00e9ctor Rafael Or"},"footnotes":""},"categories":[41],"tags":[],"class_list":["post-43492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juarez"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/43492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=43492"}],"version-history":[{"count":2,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/43492\/revisions"}],"predecessor-version":[{"id":43495,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/43492\/revisions\/43495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/43493"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=43492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=43492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=43492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}