{"id":41008,"date":"2023-12-20T07:00:00","date_gmt":"2023-12-20T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2023\/12\/20\/entrega-alcalde-repavimentacion-en-el-arroyo-del-mimbre\/"},"modified":"2023-12-20T07:00:00","modified_gmt":"2023-12-20T06:00:00","slug":"entrega-alcalde-repavimentacion-en-el-arroyo-del-mimbre","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/entrega-alcalde-repavimentacion-en-el-arroyo-del-mimbre\/","title":{"rendered":"Entrega CPC repavimentaci\u00f3n en calle \u2018Arroyo del Mimbre\u2019"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-41007\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2023\/12\/7f2400e5ec9c0e9de0b479040d2f98d5.jpg\" alt=\"\" class=\"caption\" title=\"La obra permiti\u00f3 rehabilitar un total de 16 mil 543.98 metros cuadrados de superficie.\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2023\/12\/7f2400e5ec9c0e9de0b479040d2f98d5.jpg 1600w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2023\/12\/7f2400e5ec9c0e9de0b479040d2f98d5-300x200.jpg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2023\/12\/7f2400e5ec9c0e9de0b479040d2f98d5-1024x682.jpg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2023\/12\/7f2400e5ec9c0e9de0b479040d2f98d5-768x512.jpg 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2023\/12\/7f2400e5ec9c0e9de0b479040d2f98d5-1536x1023.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Ciudad Ju\u00e1rez, Chih<\/em>.- El alcalde Cruz P\u00e9rez Cu\u00e9llar (CPC) estuvo en el norponiente de la mancha urbana para entregar a la comunidad las obras de repavimentaci\u00f3n de la calle el Arroyo del Mimbre, las cuales fueron ejecutadas por la Direcci\u00f3n General de Obras P\u00fablicas.<\/p>\n<p style=\"text-align: justify;\">La vialidad fue rehabilitada en el tramo que comprende las calles Bernardo Norzagaray y Tabaco, con una inversi\u00f3n de 6 millones 496 mil pesos provenientes del Programa de Mejoramiento de Vialidades.<\/p>\n<p style=\"text-align: justify;\">Al respecto, el Presidente Municipal, Cruz P\u00e9rez Cu\u00e9llar, coment\u00f3 que esta obra era de gran necesidad para la comunidad, pues durante a\u00f1os la vialidad no fue intervenida por ninguna administraci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s record\u00f3 que su administraci\u00f3n tambi\u00e9n esta trabajando en la rehabilitaci\u00f3n del Arroyo de las V\u00edboras, la cual se estima que sea entregada a la comunidad dentro de tres semanas.<\/p>\n<p style=\"text-align: justify;\">El director general de Obras P\u00fablicas, Daniel Gonz\u00e1lez Garc\u00eda, explic\u00f3 que la obra permiti\u00f3 rehabilitar un total de 16 mil 543.98 metros cuadrados de superficie de rodamiento que se encontraba deteriorada.<\/p>\n<p style=\"text-align: justify;\">Dijo que adem\u00e1s de las obras de repavimentaci\u00f3n, tambi\u00e9n se mejoro la base de la carpeta con cemento, a fin de que esta obra sea m\u00e1s duradera.<\/p>\n<p style=\"text-align: justify;\">Por otro lado, el coordinador general de Seguridad Vial, C\u00e9sar Tapia Mart\u00ednez, dijo que la dependencia a su cargo aplico pintura termopl\u00e1stica en 2 mil 250 metros lineales, as\u00ed como la instalaci\u00f3n de 125 vialetas amarillas.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":41007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Entrega CPC repavimentaci\u00f3n en calle \u2018Arroyo del Mimbre\u2019 - Opini\u00f3n P\u00fablica","description":"Ciudad Ju\u00e1rez, Chih .- El alcalde Cruz P\u00e9rez Cu\u00e9llar (CPC) estuvo en el norponiente de la mancha urbana para entregar a la comunidad las obras de repavimentaci\u00f3"},"footnotes":""},"categories":[41],"tags":[],"class_list":["post-41008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juarez"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/41008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=41008"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/41008\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/41007"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=41008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=41008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=41008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}