{"id":27129,"date":"2021-07-26T06:00:00","date_gmt":"2021-07-26T04:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2021\/07\/26\/efemerides-26-de-julio-4\/"},"modified":"2021-07-26T06:00:00","modified_gmt":"2021-07-26T04:00:00","slug":"efemerides-26-de-julio-4","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/efemerides-26-de-julio-4\/","title":{"rendered":"Efem\u00e9rides 26 de julio"},"content":{"rendered":"<img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-27128\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2021\/07\/5d94b1c75a22eb26e9f59b4a2147da03.jpg\" alt=\"\" class=\"caption\" title=\"Con el lanzamiento del Discovery, Estados Unidos reanud\u00f3 sus programas espaciales.\" width=\"412\" height=\"337\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2021\/07\/5d94b1c75a22eb26e9f59b4a2147da03.jpg 412w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2021\/07\/5d94b1c75a22eb26e9f59b4a2147da03-300x245.jpg 300w\" sizes=\"(max-width: 412px) 100vw, 412px\" \/>\n<p style=\"text-align: justify;\">Un d\u00eda 26 de julio como hoy, pero de 2005, Estados Unidos reanuda el programa espacial con el lanzamiento del Discovery.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>Otras efem\u00e9rides<\/strong><\/p>\n<p style=\"text-align: justify;\">1529.- Capitulaci\u00f3n entre Carlos I y Francisco Pizarro por la que \u00e9ste es nombrado gobernador y capit\u00e1n general de Nueva Castilla, actual territorio de Per\u00fa.<\/p>\n<p style=\"text-align: justify;\">1847.- Los colonos afroamericanos -antiguos esclavos estadounidenses libertos- declararon la independencia de Liberia, que significa \u00abla tierra libre\u00bb, y denominaron Monrovia a la capital en honor del presidente norteamericano James Monroe.<\/p>\n<p style=\"text-align: justify;\">1852.- El general Justo Jos\u00e9 de Urquiza asume el Gobierno de la Rep\u00fablica Argentina.<\/p>\n<p style=\"text-align: justify;\">1856.- Nace George Bernard Shaw, dramaturgo irland\u00e9s, Premio Nobel de Literatura en 1925.<\/p>\n<p style=\"text-align: justify;\">1858.- Se celebra en Barcelona (Espa\u00f1a) una novillada a cargo exclusivamente de mujeres toreras. Lleno hasta la bandera.<\/p>\n<p style=\"text-align: justify;\">1872.- Los cuatro coroneles y hermanos Guti\u00e9rrez derrocan y asesinan al presidente peruano Jos\u00e9 Balta.<\/p>\n<p style=\"text-align: justify;\">1875.- Nace Antonio Machado, escritor espa\u00f1ol.<\/p>\n<p style=\"text-align: justify;\">1890.- Estalla en Buenos Aires una revoluci\u00f3n dirigida por Leandro N. Alem contra Miguel Ju\u00e1rez Celman, que dej\u00f3 la Presidencia argentina.<\/p>\n<p style=\"text-align: justify;\">1894.- Nace Aldous Huxley, escritor brit\u00e1nico.<\/p>\n<p style=\"text-align: justify;\">1899.- El presidente de la Rep\u00fablica Dominicana Ulises Heureaux es asesinado.<\/p>\n<p style=\"text-align: justify;\">1915.- Juan Luis Sanfuentes es elegido presidente de Chile.<\/p>\n<p style=\"text-align: justify;\">1922.- Francia recibe de la Sociedad de Naciones un mandato sobre Siria, y Gran Breta\u00f1a otro sobre Palestina.<\/p>\n<p style=\"text-align: justify;\">1928.- Nace Stanley Kubrick, cineasta estadounidense.<\/p>\n<p style=\"text-align: justify;\">1930.- El pol\u00edtico brasile\u00f1o Juan Pesoa es asesinado.<\/p>\n<p style=\"text-align: justify;\">1932.- Elly Beinhorn llega a Berl\u00edn tras su vuelo alrededor del mundo. 1942.- II Guerra Mundial: La aviaci\u00f3n brit\u00e1nica bombardea Hamburgo y Duisburgo.<\/p>\n<p style=\"text-align: justify;\">1943.- Nace Mick Jagger, cantante brit\u00e1nico de rock.<\/p>\n<p style=\"text-align: justify;\">1945.- Reuni\u00f3n constituyente de las Naciones Unidas en Nueva York.<\/p>\n<p style=\"text-align: justify;\">1945.- El partido Laborista vence en las elecciones del Reino Unido: Winston Churchill renuncia a su cargo de primer ministro y es sustituido por Clement Attle.<\/p>\n<p style=\"text-align: justify;\">1952.- Muere Eva Duarte, esposa del presidente argentino Juan Domingo Per\u00f3n.<\/p>\n<p style=\"text-align: justify;\">1953.- Asalto frustrado al cuartel Moncada, cercano a Santiago de Cuba, por un grupo de rebeldes encabezado por Fidel Castro, para derrocar al dictador Batista: mueren 30 asaltantes.<\/p>\n<p style=\"text-align: justify;\">1953.- El Gobierno h\u00fangaro disuelve los campos de trabajo y ordena una amplia amnist\u00eda.<\/p>\n<p style=\"text-align: justify;\">1956.- El presidente egipcio Gamal Abdel Nasser anuncia la nacionalizaci\u00f3n de la explotaci\u00f3n del canal de Suez.<\/p>\n<p style=\"text-align: justify;\">1957.- El general Castillo Armas, presidente de Guatemala, es asesinado en el palacio presidencial por un soldado de su guardia.<\/p>\n<p style=\"text-align: justify;\">1958.- Estados Unidos lanza al espacio el sat\u00e9lite Explorer IV.<\/p>\n<p style=\"text-align: justify;\">1959.- Nace Kevin Spacey, actor estadounidense.<\/p>\n<p style=\"text-align: justify;\">1961.- Cuba unifica todas las fuerzas pol\u00edticas en el Partido Unido de la Revoluci\u00f3n Socialista.<\/p>\n<p style=\"text-align: justify;\">1964.- Nace Sandra Bullock, actriz estadounidense.<\/p>\n<p style=\"text-align: justify;\">1967.- Ecuador rompe relaciones diplom\u00e1ticas con Hait\u00ed por la violaci\u00f3n de derechos humanos efectuada por el Gobierno de Duvalier.<\/p>\n<p style=\"text-align: justify;\">1975.- Los presidentes de Bolivia, Hugo Banzer, y de Uruguay, Juan Mar\u00eda Bordaberry, firman un acta de entendimiento bilateral.<\/p>\n<p style=\"text-align: justify;\">1975.- El Movimiento de las Fuerzas Armadas de Portugal acuerda concentrar el poder en un triunvirato formado por el presidente de la Rep\u00fablica, el general Costa Gomes; el primer ministro, el general Vasco Goncalves, y el general Otelo Saraiva de Carvalho.<\/p>\n<p style=\"text-align: justify;\">1984.- El Gobierno militar uruguayo rehabilita a casi toda la izquierda del pa\u00eds, excepto a Wilson Ferreira Aldunate.<\/p>\n<p style=\"text-align: justify;\">1990.- Comienza la Operaci\u00f3n Drag\u00f3n, que pone fin a 20 a\u00f1os de presencia de armas qu\u00edmicas estadounidenses en la RFA.<\/p>\n<p style=\"text-align: justify;\">1994.- El presidente de Rusia, Bor\u00eds Yeltsin, acuerda la retirada de tropas rusas de Estonia.<\/p>\n<p style=\"text-align: justify;\">1999.- El escritor mexicano Sergio Pitol gana el Premio de Literatura Iberoamericana y del Caribe \u00abJuan Rulfo\u00bb.<\/p>\n<p style=\"text-align: justify;\">2000.- Unos 200 presos pol\u00edticos chilenos, torturados durante la dictadura, presentan una nueva querella criminal contra Pinochet.<\/p>\n<p style=\"text-align: justify;\">2002.- La C\u00e1mara de Representantes de Estados Unidos aprueba la creaci\u00f3n del Departamento de Seguridad Nacional, que combatir\u00e1 y prevendr\u00e1 el terrorismo.<\/p>\n<p style=\"text-align: justify;\">2003.- Fidel Castro conmemora en el cuartel de Moncada, en Santiago de Cuba, el 50 aniversario de la primera acci\u00f3n armada de la revoluci\u00f3n que le llev\u00f3 al poder en 1959.<\/p>\n<p style=\"text-align: justify;\">2004.- El Banco Santander Central Hispano anuncia la adquisici\u00f3n del grupo brit\u00e1nico Abbey, por 13,400 millones de euros.<\/p>\n<p style=\"text-align: justify;\">2004.- El escritor espa\u00f1ol Juan Goytisolo recibe el Premio Juan Rulfo de Literatura Latinoamericana.<\/p>\n<p style=\"text-align: justify;\">2007.- Pakist\u00e1n prueba con \u00e9xito su misil de crucero Hataf VII con capacidad nuclear y un alcance de 700 kil\u00f3metros.<\/p>\n<p style=\"text-align: justify;\">2011.- Mueren 17 presos en la c\u00e1rcel mexicana de Ciudad Ju\u00e1rez durante un altercado entre bandas rivales.<\/p>\n<p style=\"text-align: justify;\">2011.- Mueren 78 personas al estrellarse un avi\u00f3n militar marroqu\u00ed en las proximidades del Sahara Occidental.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00eda 26 de julio como hoy, pero de 2005, Estados Unidos reanuda el programa espacial con el lanzamiento del Discovery.<\/p>\n","protected":false},"author":6,"featured_media":27128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Efem\u00e9rides 26 de julio - Opini\u00f3n P\u00fablica","description":"Un d\u00eda 26 de julio como hoy, pero de 2005, Estados Unidos reanuda el programa espacial con el lanzamiento del Discovery. Otras efem\u00e9rides 1529.- Capitulaci\u00f3n en"},"footnotes":""},"categories":[27],"tags":[],"class_list":["post-27129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-dia-como-hoy"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/27129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=27129"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/27129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/27128"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=27129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=27129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=27129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}