{"id":27101,"date":"2021-07-23T06:00:00","date_gmt":"2021-07-23T04:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2021\/07\/23\/tapados-destapadores-dedazos-y-corcholatas\/"},"modified":"2021-07-23T06:00:00","modified_gmt":"2021-07-23T04:00:00","slug":"tapados-destapadores-dedazos-y-corcholatas","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/tapados-destapadores-dedazos-y-corcholatas\/","title":{"rendered":"Tapados, destapadores, dedazos y corcholatas"},"content":{"rendered":"<img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-27100\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2021\/07\/2d4da8ffc3004f1a8475eb96a68de3bb.jpg\" alt=\"\" class=\"caption\" title=\"Jos\u00e9 Woldenberg, acad\u00e9mico y primer presidente del IFE.\" width=\"270\" height=\"235\" \/>\n<p style=\"text-align: justify;\">Hace 25 a\u00f1os Enrique Florescano ide\u00f3 y coordin\u00f3 un libro sobre los mitos mexicanos. Eran textos breves encargados a muy diferentes autores y ah\u00ed aparec\u00eda El Caudillo, La Malinche, El Pueblo, El Macho, La Madre, El Ciudadano, El Charro, El Licenciado, La Diva y muchos m\u00e1s. A m\u00ed me invit\u00f3 a escribir sobre\u00a0El Tapado.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Una f\u00f3rmula para resolver el problema de la\u00a0sucesi\u00f3n presidencial\u00a0que requiri\u00f3 de la construcci\u00f3n de un partido hegem\u00f3nico (pr\u00e1cticamente sin competencia) y un presidente concentrador del poder. Este \u00faltimo no solo era visible y encarnaba la c\u00faspide del Estado, sino que ten\u00eda la capacidad de remover la capucha al tapado y convertirlo en el ungido. El sucesor, por el contrario, se manten\u00eda en una media luz y esperaba ser designado por el dedo del presidente.<\/p>\n<p style=\"text-align: justify;\">El \u201cjuego\u201d era reducido y estaba excluida la sociedad. Era una disputa palaciega, opaca, refractaria al aut\u00e9ntico debate p\u00fablico, y por ello la picaresca popular acu\u00f1\u00f3 dos nociones juguetonas, hasta cierto punto vengativas: el Dedazo a cargo del presidente y el Tapado, que ser\u00eda descubierto cuando el mero-mero lo considerara oportuno.<\/p>\n<p style=\"text-align: justify;\">Era un escenario casi monopartidista, sin competitividad, en el cual ganadores y perdedores estaban predeterminados. De hecho, el momento estelar de la sucesi\u00f3n era el destape, luego del cual se celebraban unas elecciones sin tensi\u00f3n ni sorpresa. Pero hace 25 a\u00f1os ya soplaban vientos de transformaci\u00f3n. La\u00a0diversidad pol\u00edtica\u00a0se abr\u00eda paso, los comicios eran cada vez m\u00e1s peleados y las oposiciones ganaban alcald\u00edas, algunas gubernaturas y estaban presentes en los congresos locales y en el federal.<\/p>\n<p style=\"text-align: justify;\">El partido oficial pod\u00eda acudir al mismo m\u00e9todo para designar a su candidato, pero cada vez resultaba menos probable que tuviese durante la campa\u00f1a un d\u00eda de campo, puesto que otras opciones pod\u00edan derrotarlo. Todo indicaba que la \u00e9poca del\u00a0Dedazo\u00a0y el\u00a0Tapado\u00a0venturosamente estaban quedando como un vestigio del pasado. El pluralismo pol\u00edtico se hac\u00eda presente y la voluntad presidencial, por m\u00e1s poderosa que fuera, no era la \u00fanica en el teatro de la sucesi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En los \u00faltimos a\u00f1os la designaci\u00f3n de los diversos candidatos fue eso, un nombramiento avalado por un partido o coalici\u00f3n que estaba obligado a competir con otros, de tal suerte que el ritual del Tapado se fue apagando. No obstante, nuestro presidente, que mucho a\u00f1ora del pasado monopartidista y del h\u00edper presidencialismo, ya nos avis\u00f3 que aquel juego le gusta. Nos dijo: \u201cHay muchas mujeres y hombres para el relevo\u2026Yo soy el destapador y mi corcholata favorita va a ser la del pueblo\u2026\u201d.<\/p>\n<p style=\"text-align: justify;\">Sin rubor, el dedazo de entonces es el destapador de hoy y el tapado se convierte en corcholata. M\u00e1s all\u00e1 del dudoso humor, llama la atenci\u00f3n que el presidente siga pens\u00e1ndose a s\u00ed mismo como la voz del pueblo, como si \u00e9ste se expresara a trav\u00e9s de \u00e9l, como si esa constelaci\u00f3n heterog\u00e9nea que es el pueblo pudiera tener un solo sentir y un solo candidato. Al presidente le atrae ese ritual cortesano porque \u00e9l ser\u00e1 el \u201cdestapador\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00bfUna vuelta al pasado? Si por \u00e9l fuera, s\u00ed. Sin embargo, no existe m\u00e1s un partido hegem\u00f3nico, tenemos aut\u00e9nticas elecciones y competidores genuinos, y est\u00e1 por verse que la disciplina de ayer cuando no hab\u00eda m\u00e1s que un partido capaz de ganar cargos p\u00fablicos se renueve ma\u00f1ana cuando las opciones son varias. De lo que cada d\u00eda hay menos dudas es que a nuestro presidente le encantar\u00eda un formato pol\u00edtico como el de mediados del siglo pasado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace 25 a\u00f1os Enrique Florescano ide\u00f3 y coordin\u00f3 un libro sobre los mitos mexicanos. Eran textos breves encargados a muy diferentes autores y ah\u00ed aparec\u00eda El Caudillo, La Malinche, El Pueblo, El Macho, La Madre, El Ciudadano, El Charro, El Licenciado, La Diva y muchos m\u00e1s. A m\u00ed me invit\u00f3 a escribir sobre\u00a0El Tapado.<\/p>\n","protected":false},"author":6,"featured_media":27100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Tapados, destapadores, dedazos y corcholatas - Opini\u00f3n P\u00fablica","description":"Hace 25 a\u00f1os Enrique Florescano ide\u00f3 y coordin\u00f3 un libro sobre los mitos mexicanos. Eran textos breves encargados a muy diferentes autores y ah\u00ed aparec\u00eda El Cau"},"footnotes":""},"categories":[26],"tags":[],"class_list":["post-27101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de-chile-dulce-y-manteca-columna-invitada"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/27101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=27101"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/27101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/27100"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=27101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=27101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=27101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}