{"id":25625,"date":"2021-01-29T07:00:00","date_gmt":"2021-01-29T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2021\/01\/29\/efemerides-29-de-enero-4\/"},"modified":"2021-01-29T07:00:00","modified_gmt":"2021-01-29T06:00:00","slug":"efemerides-29-de-enero-4","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/efemerides-29-de-enero-4\/","title":{"rendered":"Efem\u00e9rides 29 de enero"},"content":{"rendered":"<img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-25624\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2021\/01\/eee8e0099ee34ebb6cbef4d7c40efb69.jpg\" alt=\"\" class=\"caption\" title=\"El general Augusto Pinochet lleg\u00f3 al poder en Chile mediante un golpe de estado.\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2021\/01\/eee8e0099ee34ebb6cbef4d7c40efb69.jpg 900w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2021\/01\/eee8e0099ee34ebb6cbef4d7c40efb69-300x200.jpg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2021\/01\/eee8e0099ee34ebb6cbef4d7c40efb69-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n<p style=\"text-align: justify;\">Un d\u00eda 29 de enero como hoy, pero de 2001, el juez chileno Juan Guzm\u00e1n ordena el procesamiento y arresto domiciliario del general retirado Augusto Pinochet como coautor del secuestro y homicidio en el \u00abcaso Caravana de la Muerte\u00bb.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>M\u00e1s efem\u00e9rides<\/strong><\/p>\n<p style=\"text-align: justify;\">1810.- La invasi\u00f3n de Andaluc\u00eda por los franceses provoca el descr\u00e9dito de la Junta central, que pone sus poderes en un Consejo de Regencia constituido en la isla de Le\u00f3n (actual San Fernando, en C\u00e1diz).<\/p>\n<p style=\"text-align: justify;\">1821.- Una conjura de generales destituye al virrey Pezuela en Per\u00fa.<\/p>\n<p style=\"text-align: justify;\">1860.- Nace Anton P. Ch\u00e9jov, dramaturgo ruso.<\/p>\n<p style=\"text-align: justify;\">1867.- Nace Vicente Blasco Ib\u00e1\u00f1ez, novelista espa\u00f1ol.<\/p>\n<p style=\"text-align: justify;\">1918.- Nace John Forsythe, actor estadounidense.<\/p>\n<p style=\"text-align: justify;\">1924.- Movimiento revolucionario en Santa Clara (Cuba), sofocado una semana despu\u00e9s. Ocupaba la presidencia de la Rep\u00fablica el escritor Alfredo Zayas.<\/p>\n<p style=\"text-align: justify;\">1929.- Le\u00f3n Trotski llega a Constantinopla tras ser expulsado de la Uni\u00f3n Sovi\u00e9tica.<\/p>\n<p style=\"text-align: justify;\">1942.- Ecuador y Per\u00fa firman el Tratado de R\u00edo de Janeiro, para el arreglo del pleito de l\u00edmites en la zona amaz\u00f3nica fronteriza de ambos pa\u00edses, con Argentina, Brasil, Chile y EEUU como garantes.<\/p>\n<p style=\"text-align: justify;\">1942.- Un maremoto en Mar del Plata (Argentina) produce graves da\u00f1os materiales.<\/p>\n<p style=\"text-align: justify;\">1945.- Nace Tom Selleck, actor estadounidense.<\/p>\n<p style=\"text-align: justify;\">1948.- El delegado sovi\u00e9tico en el Consejo de Seguridad de la ONU, Andrei Gromyko, pide la destrucci\u00f3n de todas las bombas at\u00f3micas existentes.<\/p>\n<p style=\"text-align: justify;\">1954.- Nace Oprah Winfrey, periodista estadounidense.<\/p>\n<p style=\"text-align: justify;\">1963.- La Comunidad Econ\u00f3mica Europea rechaza la petici\u00f3n de ingreso de Gran Breta\u00f1a.<\/p>\n<p style=\"text-align: justify;\">1981.- Adolfo Su\u00e1rez dimite de sus cargos de presidente del Gobierno espa\u00f1ol y del partido Uni\u00f3n de Centro Democr\u00e1tico.<\/p>\n<p style=\"text-align: justify;\">1984.- Es asesinado por ETA el teniente general Guillermo Quintana Lacaci, ex capit\u00e1n general de Madrid.<\/p>\n<p style=\"text-align: justify;\">1986.- Un avi\u00f3n DC-3 de Aerocalifornia se estrella cerca del aeropuerto de Mochis (M\u00e9xico) y mueren sus 21 ocupantes.<\/p>\n<p style=\"text-align: justify;\">1986.- Yoeri Museveni toma posesi\u00f3n como presidente de Uganda.<\/p>\n<p style=\"text-align: justify;\">1991.- El Congreso de Somalia Unificada nombra a Al\u00ed Mahdi Mohamed nuevo presidente del pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">1996.- Un incendio destruye \u00abLa Fenice\u00bb de Venecia, un teatro con m\u00e1s de 200 a\u00f1os de antig\u00fcedad.<\/p>\n<p style=\"text-align: justify;\">1999.- El cuadro de Vel\u00e1zquez \u00abSanta Rufina\u00bb es adquirido por un coleccionista an\u00f3nimo por 1,166 millones de pesetas (7 millones de euros) en Nueva York.<\/p>\n<p style=\"text-align: justify;\">2000.- Se aprueba en Montreal el Protocolo de la Bioseguridad, que regular\u00e1 el comercio internacional de productos transg\u00e9nicos.<\/p>\n<p style=\"text-align: justify;\">2003.- Muere Natalia Dudinskaya, estrella del ballet sovi\u00e9tico.<\/p>\n<p style=\"text-align: justify;\">2003.- El Gobierno de Nepal y la guerrilla mao\u00edsta anuncian un alto el fuego.<\/p>\n<p style=\"text-align: justify;\">2006.- El Foro Social Mundial finaliza su sexta edici\u00f3n en Caracas (Venezuela), del que sali\u00f3 un compromiso contra la globalizaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">2006.- El jeque Sabah al Ahmad al Yaber al Sabah jura su cargo como emir de Kuwait, en sustituci\u00f3n del fallecido Jaber al Ahmad al Sabah.<\/p>\n<p style=\"text-align: justify;\">2012.- Fallece Oscar Luigi Scalfaro, pol\u00edtico italiano.<\/p>\n<p style=\"text-align: justify;\">2013.- Fallece Said Musa \u00abAbu Musa\u00bb, hist\u00f3rico combatiente palestino.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00eda 29 de enero como hoy, pero de 2001, el juez chileno Juan Guzm\u00e1n ordena el procesamiento y arresto domiciliario del general retirado Augusto Pinochet como coautor del secuestro y homicidio en el \u00abcaso Caravana de la Muerte\u00bb.<\/p>\n","protected":false},"author":6,"featured_media":25624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Efem\u00e9rides 29 de enero - Opini\u00f3n P\u00fablica","description":"Un d\u00eda 29 de enero como hoy, pero de 2001, el juez chileno Juan Guzm\u00e1n ordena el procesamiento y arresto domiciliario del general retirado Augusto Pinochet como"},"footnotes":""},"categories":[27],"tags":[],"class_list":["post-25625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-dia-como-hoy"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=25625"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25625\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/25624"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=25625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=25625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=25625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}