{"id":25435,"date":"2020-12-16T07:00:00","date_gmt":"2020-12-16T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2020\/12\/16\/recuerdan-a-marisela-escobedo-a-10-anos-de-su-muerte\/"},"modified":"2020-12-16T07:00:00","modified_gmt":"2020-12-16T06:00:00","slug":"recuerdan-a-marisela-escobedo-a-10-anos-de-su-muerte","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/recuerdan-a-marisela-escobedo-a-10-anos-de-su-muerte\/","title":{"rendered":"Recuerdan a Marisela Escobedo a 10 a\u00f1os de su ejecuci\u00f3n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-25434\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/8eb26c25fba6dafca6109525352be910.jpg\" alt=\"\" class=\"caption\" title=\"La activista juarense Marisela Escobedo fue asesinada hace ya 10 a\u00f1os.\" width=\"768\" height=\"479\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/8eb26c25fba6dafca6109525352be910.jpg 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/8eb26c25fba6dafca6109525352be910-300x187.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Chihuahua, Chih<\/em>.- En el d\u00e9cimo aniversario del asesinato de la activista juarense Marisela Escobedo a las puertas del Palacio de Gobierno en Chihuahua, la ma\u00f1ana de este mi\u00e9rcoles le rindieron un homenaje en el lugar de su muerte.<\/p>\n<p style=\"text-align: justify;\">\u201cEn este lugar se silenci\u00f3 a Marisela, una mujer que nunca se resign\u00f3 a cada acto de incompetencia de los procuradores de justicia, en nuestra mente se quedar\u00e1 la imagen de la madre con la foto de su hija en manos exigiendo justicia\u201d, dijo Luis Fernando Mesta Soul\u00e9, secretario general de gobierno al presidir la ceremonia luctuosa por el d\u00e9cimo aniversario.<\/p>\n<p style=\"text-align: justify;\">Alrededor de la placa, se colocaron algunos arreglos florales y veladoras en honor a Marisela, mientras que en la puerta de palacio de gobierno se pusieron dos coronas como s\u00edmbolo de puertas abiertas.<\/p>\n<p style=\"text-align: justify;\">En el evento, Luis Fernando Mesta y Emma Salda\u00f1a, directora del Instituto Chihuahuense de las Mujeres, recordaron que fueron muchas las caminatas con la misma exigencia, hace 10 a\u00f1os acamp\u00f3 frente a Palacio a pesar de las amenazas. Sab\u00eda que si mor\u00eda ser\u00eda culpa del gobierno que nunca la acompa\u00f1\u00f3 ni apoyo.<\/p>\n<p style=\"text-align: justify;\">A la ofrenda floral acudi\u00f3 secretario de Desarrollo Social, Luis Aguilar Lozoya; titular de la Comisi\u00f3n Ejecutiva de Atenci\u00f3n a V\u00edctimas, Irma Villanueva N\u00e1jera as\u00ed como representantes de la Fiscal\u00eda de la Mujer.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":25434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Recuerdan a Marisela Escobedo a 10 a\u00f1os de su ejecuci\u00f3n - Opini\u00f3n P\u00fablica","description":"Chihuahua, Chih .- En el d\u00e9cimo aniversario del asesinato de la activista juarense Marisela Escobedo a las puertas del Palacio de Gobierno en Chihuahua, la ma\u00f1a"},"footnotes":""},"categories":[4],"tags":[],"class_list":["post-25435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pulsopolitico"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=25435"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/25434"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=25435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=25435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=25435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}