{"id":25353,"date":"2020-12-07T07:00:00","date_gmt":"2020-12-07T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2020\/12\/07\/propone-amlo-a-tatiana-clouthier-en-secretaria-de-economia\/"},"modified":"2020-12-07T07:00:00","modified_gmt":"2020-12-07T06:00:00","slug":"propone-amlo-a-tatiana-clouthier-en-secretaria-de-economia","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/propone-amlo-a-tatiana-clouthier-en-secretaria-de-economia\/","title":{"rendered":"Ser\u00e1 Tatiana Clouthier la nueva secretaria de Econom\u00eda"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-25352\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/14affa13a3795b177f8127d1c472c042.jpg\" alt=\"\" class=\"caption\" title=\"El nombramiento de Tatiana Clouthier debe ser ratificado por el Senado de la Rep\u00fablica.\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/14affa13a3795b177f8127d1c472c042.jpg 1280w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/14affa13a3795b177f8127d1c472c042-300x169.jpg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/14affa13a3795b177f8127d1c472c042-1024x576.jpg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/14affa13a3795b177f8127d1c472c042-768x432.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Ciudad de M\u00e9xico<\/em>.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador inform\u00f3 este lunes que propondr\u00e1 a Graciela M\u00e1rquez Col\u00edn, actual secretaria de Econom\u00eda, para la Junta de Gobierno del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi).<\/p>\n<p style=\"text-align: justify;\">En su lugar, dijo L\u00f3pez Obrador, entrar\u00e1 Tatiana Clouthier Carrillo, cargo que tiene que ser ratificado por el Senado de la Rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">El nombramiento de M\u00e1rquez Col\u00edn, al igual que el de Clouthier Carrillo, tiene que ser avalado por la C\u00e1mara de Senadores.<\/p>\n<p style=\"text-align: justify;\">Los cambios no tienen que ver con \u00abuna cuota de g\u00e9nero. Tiene que ver con la necesidad de tener en el servicio p\u00fablico a hombres y mujeres caracterizados por la honestidad\u00bb, se\u00f1al\u00f3 el mandatario nacional.<\/p>\n<p style=\"text-align: justify;\">Y agreg\u00f3: \u00abEn el caso de Tatiana, es una mujer con principios, con integridad, honesta y va a ayudarnos para que se siga promoviendo la actividad econ\u00f3mica en el pa\u00eds y se tenga buenas relaciones con el sector empresarial, con el sector obrero; se siga fomentando el comercio exterior. Ese fue el motivo por el que decid\u00ed nombrarla secretaria de Econom\u00eda\u00bb<\/p>\n<p style=\"text-align: justify;\">Por otra parte, L\u00f3pez Obrador propuso a Galia Borja para ocupar el puesto de subgobernadora del Banco de M\u00e9xico (Banxico).<\/p>\n<p style=\"text-align: justify;\">\u00abVoy a proponer el d\u00eda de hoy al Senado de la Rep\u00fablica dos nombramientos para subgobernadora del Banco de M\u00e9xico y miembro de la Junta de Gobierno del mismo Banco, estoy proponiendo a Galia Borja G\u00f3mez. A finales de este a\u00f1o se concluye el periodo de un subgobernador y va a ser sustituido por Galia Borja G\u00f3mez, (que) es actualmente la tesorera de la Federaci\u00f3n\u00bb, apunt\u00f3 en la conferencia matutina.<\/p>\n<p style=\"text-align: justify;\">Borja ser\u00e1 sustituida en la Tesorer\u00eda por Elvira Concheiro. (El Financiero)<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":25352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Ser\u00e1 Tatiana Clouthier la nueva secretaria de Econom\u00eda - Opini\u00f3n P\u00fablica","description":"Ciudad de M\u00e9xico .- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador inform\u00f3 este lunes que propondr\u00e1 a Graciela M\u00e1rquez Col\u00edn, actual secretaria de Econom\u00eda, para la"},"footnotes":""},"categories":[9],"tags":[],"class_list":["post-25353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=25353"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/25352"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=25353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=25353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=25353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}