{"id":25301,"date":"2020-12-01T07:00:00","date_gmt":"2020-12-01T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2020\/12\/01\/marca-inseguridad-a-2020-como-el-ano-mas-violento\/"},"modified":"2020-12-01T07:00:00","modified_gmt":"2020-12-01T06:00:00","slug":"marca-inseguridad-a-2020-como-el-ano-mas-violento","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/marca-inseguridad-a-2020-como-el-ano-mas-violento\/","title":{"rendered":"Marca la inseguridad al 2020 como el a\u00f1o m\u00e1s violento"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-25300\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/b054b29f5804a3cf592ce084bd85f701.jpg\" alt=\"\" class=\"caption\" title=\"La violencia en M\u00e9xico se increment\u00f3 a\u00fan m\u00e1s en el gobierno de L\u00f3pez Obrador.\" width=\"2048\" height=\"1352\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/b054b29f5804a3cf592ce084bd85f701.jpg 2048w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/b054b29f5804a3cf592ce084bd85f701-300x198.jpg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/b054b29f5804a3cf592ce084bd85f701-1024x676.jpg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/b054b29f5804a3cf592ce084bd85f701-768x507.jpg 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/12\/b054b29f5804a3cf592ce084bd85f701-1536x1014.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Ciudad de M\u00e9xico<\/em>.- Con la creaci\u00f3n de la Guardia Nacional (GN), en marzo de 2019, el presidente Andr\u00e9s Manuel L\u00f3pez Obrador asegur\u00f3 que pacificar\u00eda al pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">En enero de este a\u00f1o, prometi\u00f3 que, para el primero de diciembre terminar\u00eda de sentar las bases de la transformaci\u00f3n del pa\u00eds y, con ello, vendr\u00edan los resultados en materia de seguridad.<\/p>\n<p style=\"text-align: justify;\">\u201cEs el tema m\u00e1s dif\u00edcil que hemos enfrentado, pero estoy optimista\u201d, expres\u00f3 entonces.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, el pa\u00eds se apresta a cerrar el que podr\u00eda ser el a\u00f1o m\u00e1s violento de las \u00faltimas d\u00e9cadas.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan los datos del Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica, en 2019 se registraron 34 mil 600 homicidios dolosos.<\/p>\n<p style=\"text-align: justify;\">Los reportes refieren que, en lo que va de este a\u00f1o, se han registrado casi 31 mil asesinatos. Un promedio mensual de 2 mil 850 v\u00edctimas.<\/p>\n<p style=\"text-align: justify;\">El \u00faltimo informe presentado por la Secretar\u00eda de Seguridad P\u00fablica en Palacio Nacional revel\u00f3 que el homicidio doloso y el feminicidio mantienen una tendencia al alza, a pesar de que el Gobierno sigue sosteniendo que los asesinatos en M\u00e9xico est\u00e1n en una \u201cl\u00ednea de contenci\u00f3n\u201d o que, con su estrategia, logr\u00f3 \u201cun punto de inflexi\u00f3n\u201d.<\/p>\n<p style=\"text-align: justify;\">En comparaci\u00f3n con el 2019, los homicidios subieron 1.1 por ciento, ya que, mientras entre enero y octubre del a\u00f1o pasado se registraron 28 mil 855 v\u00edctimas, este a\u00f1o sumaron 29 mil 182 en el mismo periodo.\u00a0<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, el feminicidio creci\u00f3 1.5 por ciento, al pasar de 789 a 801 v\u00edctimas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":25300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Marca la inseguridad al 2020 como el a\u00f1o m\u00e1s violento - Opini\u00f3n P\u00fablica","description":"Ciudad de M\u00e9xico .- Con la creaci\u00f3n de la Guardia Nacional (GN), en marzo de 2019, el presidente Andr\u00e9s Manuel L\u00f3pez Obrador asegur\u00f3 que pacificar\u00eda al pa\u00eds. En"},"footnotes":""},"categories":[9],"tags":[],"class_list":["post-25301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=25301"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/25300"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=25301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=25301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=25301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}