{"id":25269,"date":"2020-11-27T07:00:00","date_gmt":"2020-11-27T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2020\/11\/27\/diputados-se-podran-reelegir-sin-pedir-licencia-y-con-apoyos\/"},"modified":"2020-11-27T07:00:00","modified_gmt":"2020-11-27T06:00:00","slug":"diputados-se-podran-reelegir-sin-pedir-licencia-y-con-apoyos","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/diputados-se-podran-reelegir-sin-pedir-licencia-y-con-apoyos\/","title":{"rendered":"Diputados se podr\u00e1n reelegir sin pedir licencia y con apoyos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-25268\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/11\/df09e94d1bc3d4c81c0122a36d5ef990.jpg\" alt=\"\" class=\"caption\" title=\"La C\u00e1mara de Diputados aprob\u00f3 su propio esquema de reelecci\u00f3n y sin pedir licencia.\" width=\"1080\" height=\"626\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/11\/df09e94d1bc3d4c81c0122a36d5ef990.jpg 1080w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/11\/df09e94d1bc3d4c81c0122a36d5ef990-300x174.jpg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/11\/df09e94d1bc3d4c81c0122a36d5ef990-1024x594.jpg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/11\/df09e94d1bc3d4c81c0122a36d5ef990-768x445.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Ciudad de M\u00e9xico<\/em>.- El pleno de la C\u00e1mara de Diputados aprob\u00f3, con 454 votos a favor, los lineamientos con los que los diputados interesados en reelegirse puedan realizarlo sin pedir licencia.<\/p>\n<p style=\"text-align: justify;\">El acuerdo de la Junta de Coordinaci\u00f3n Pol\u00edtica y de la Mesa Directiva, se separ\u00f3 del proyecto del Instituto Nacional Electoral (INE) que propon\u00eda que los legisladores se separaran de su cargo 60 d\u00edas antes del d\u00eda de la elecci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La principal justificaci\u00f3n que se dio al tema fue que al permitirse por primera vez la reelecci\u00f3n en legisladores, la legislatura podr\u00eda quedar a la deriva y no lograr las votaciones necesarias para los temas de gran relevancia como el paquete fiscal que se discutir\u00e1 en breve en San L\u00e1zaro.<\/p>\n<p style=\"text-align: justify;\">Esta situaci\u00f3n permitir\u00e1 que, adem\u00e1s de seguir atendiendo sus labores legislativas, reciban los 74 mil 672 pesos correspondientes a su dieta mensual, as\u00ed como los recursos por concepto de Asistencia Legislativa y Atenci\u00f3n Ciudadana.<\/p>\n<p style=\"text-align: justify;\">\u201cNo podr\u00e1n participar en eventos de car\u00e1cter proselitista en los d\u00edas en que se encuentren obligados a desempe\u00f1ar su cargo, de acuerdo con la programaci\u00f3n para los trabajos legislativos, emitida por la Conferencia para la Direcci\u00f3n y Programaci\u00f3n de los Trabajos Legislativos\u201d, establece el acuerdo.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":25268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Diputados se podr\u00e1n reelegir sin pedir licencia y con apoyos - Opini\u00f3n P\u00fablica","description":"Ciudad de M\u00e9xico .- El pleno de la C\u00e1mara de Diputados aprob\u00f3, con 454 votos a favor, los lineamientos con los que los diputados interesados en reelegirse pueda"},"footnotes":""},"categories":[9],"tags":[],"class_list":["post-25269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=25269"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/25268"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=25269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=25269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=25269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}