{"id":25267,"date":"2020-11-27T07:00:00","date_gmt":"2020-11-27T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2020\/11\/27\/alerta-115-juarenses-murieron-por-covid-en-48-horas-y-ya-son-mas-de-2-mil-fallecimientos\/"},"modified":"2020-11-27T07:00:00","modified_gmt":"2020-11-27T06:00:00","slug":"alerta-115-juarenses-murieron-por-covid-en-48-horas-y-ya-son-mas-de-2-mil-fallecimientos","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/alerta-115-juarenses-murieron-por-covid-en-48-horas-y-ya-son-mas-de-2-mil-fallecimientos\/","title":{"rendered":"Alerta: 115 juarenses murieron por Covid en 48 horas y ya son m\u00e1s de 2 mil fallecimientos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-25266\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/11\/a2aae08ac3d2b6a3e374edba9c010a94.jpg\" alt=\"\" class=\"caption\" title=\"Ciudad Ju\u00e1rez rebas\u00f3 este viernes la barrera de dos mil muertos por Covid-19.\" width=\"580\" height=\"330\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/11\/a2aae08ac3d2b6a3e374edba9c010a94.jpg 580w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/11\/a2aae08ac3d2b6a3e374edba9c010a94-300x171.jpg 300w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Ciudad Ju\u00e1rez, Chih<\/em>.- La crisis del Covid-19 sigue fuera de control en Ciudad Ju\u00e1rez, donde en tan solo 48 horas han perdido la vida 115 personas y se rebas\u00f3 adem\u00e1s, la barrera de los 2 mil fallecimientos a causa de esta enfermedad.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan datos de la Secretar\u00eda de Salud, la cifra total de muertos por coronavirus lleg\u00f3 este viernes a 2 mil 013, al tiempo que persiste la saturaci\u00f3n hospitalaria y la falta de camas y medicamentos en las cl\u00ednicas del sector p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, confirm\u00f3 167 casos m\u00e1s al \u00faltimo corte, con los que alcanz\u00f3 20 mil 783 confirmados a trav\u00e9s de pruebas de Reacci\u00f3n en Cadena de la Polimerasa (PCR); son m\u00e1s de 9 mil 600 sanados.<\/p>\n<p style=\"text-align: justify;\">Arturo Valenzuela Zorrilla, director m\u00e9dico Zona Norte, reiter\u00f3 que es necesario mantener la sana distancia, higiene y cubrebocas para evitar contraer esta enfermedad.<\/p>\n<p style=\"text-align: justify;\">Agreg\u00f3 que a nivel estatal, son ya 37 mil 099 casos acumulados con 3 mil 326 finados y poco m\u00e1s de 18 mil 700 sanados, as\u00ed como 112 defunciones en la entidad en las \u00faltimas 24 horas.<\/p>\n<p style=\"text-align: justify;\">Urgi\u00f3 a la comunidad y en especial a las personas vulnerables como adultos mayores o enfermos cr\u00f3nicos, a no salir de casa a menos de que sea para actividades indispensables para evitar que sufran complicaciones.<\/p>\n<p style=\"text-align: justify;\">Valenzuela agreg\u00f3 que hay 665 personas hospitalizadas a nivel estatal, de las cuales 110 est\u00e1n intubadas.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":25266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Alerta: 115 juarenses murieron por Covid en 48 horas y ya son m\u00e1s de 2 mil fallecimientos - Opini\u00f3n P\u00fablica","description":"Ciudad Ju\u00e1rez, Chih .- La crisis del Covid-19 sigue fuera de control en Ciudad Ju\u00e1rez, donde en tan solo 48 horas han perdido la vida 115 personas y se rebas\u00f3 a"},"footnotes":""},"categories":[3],"tags":[],"class_list":["post-25267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=25267"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/25267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/25266"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=25267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=25267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=25267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}