{"id":24513,"date":"2020-09-27T06:00:00","date_gmt":"2020-09-27T04:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2020\/09\/27\/respuesta-a-queja-de-rocio-reza\/"},"modified":"2020-09-27T06:00:00","modified_gmt":"2020-09-27T04:00:00","slug":"respuesta-a-queja-de-rocio-reza","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/respuesta-a-queja-de-rocio-reza\/","title":{"rendered":"Respuesta a queja de Roc\u00edo Reza"},"content":{"rendered":"<img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-24512\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/b6f590e78fde2d74340b23e2ea9500d8.jpg\" alt=\"\" class=\"caption\" title=\"Luis Villegas Montes.\" width=\"255\" height=\"198\" \/>\n<p style=\"text-align: justify;\">Desde hace quince d\u00edas, circulan en medios notas relativas a la queja interpuesta en contra del suscrito por la Ing. Roc\u00edo Esmeralda Reza Gallegos, en su calidad de militante del Partido Acci\u00f3n Nacional, y como Presidenta del Comit\u00e9 Directivo Estatal de dicho instituto pol\u00edtico en el Estado, por la comisi\u00f3n de diversos actos constitutivos de violencia pol\u00edtica contra la mujer en raz\u00f3n de g\u00e9nero.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Hasta el d\u00eda de hoy he guardado silencio, pero resulta intolerable consentir con esa agresi\u00f3n dirigida en mi contra y la consiguiente persecuci\u00f3n pol\u00edtica.<\/p>\n<p style=\"text-align: justify;\">En mi descargo, debo decir que las acusaciones en que se funda son falsas; s\u00ed existi\u00f3 un intercambio de mensajes v\u00eda\u00a0<em>Facebook<\/em>\u00a0entre ella y yo, pero en ning\u00fan momento la hice objeto de agravio alguno en raz\u00f3n de sexo o g\u00e9nero; me limit\u00e9, en su momento, a hacer una serie de se\u00f1alamientos respecto de su omiso proceder, en torno a la confrontaci\u00f3n y ataques infundados, m\u00faltiples y reiterados, que el Gobernador constitucional del Estado, Lic. Javier Corral Jurado, ha dirigido, de manera constante, en contra de la persona de la Lic. Mar\u00eda Eugenia Campos Galv\u00e1n, Presidenta Municipal de Chihuahua, por una parte; y por otra, el descarado, y vil, apoyo que el primero ha demostrado en beneficio del Lic. Gustavo Enrique Madero Mu\u00f1oz, actual Senador de la Rep\u00fablica, con el t\u00e1cito consentimiento del Comit\u00e9 Directivo Estatal del Partido Acci\u00f3n Nacional en el Estado, a cargo de la propia Ing. Roc\u00edo Esmeralda Reza Gallegos.<\/p>\n<p style=\"text-align: justify;\">Por razones de equidad medi\u00e1tica creo justo informar a la opini\u00f3n p\u00fablica el contenido de mi respuesta a dicha queja, lo que hago agregando al presente correo copia de la misma, pues se trata de m\u00e1s de sesenta p\u00e1ginas y m\u00e1s de ochenta medios de prueba que demuestran, sin ning\u00fan lugar a dudas,\u00a0 que el intercambio de notas entre la quejosa y el suscrito se suscit\u00f3 en medio de una serie de hechos que EST\u00c1N DIRECTA E \u00cdNTIMAMENTE LIGADOS AL CASO QUE NOS OCUPA, pues del 1.\u00ba de julio de 2020 al 16 del mismo mes, e incluso semanas despu\u00e9s, el se\u00f1alado Gobernador constitucional del Estado, Lic. Javier Corral Jurado, se vio envuelto en una din\u00e1mica que ha sido se\u00f1alada en el p\u00e1rrafo anterior, cuyo contenido f\u00e1cilmente se puede apreciar del siguiente esquema:<\/p>\n<p style=\"text-align: justify;\">\u00a0Ataques a la Lic. Mar\u00eda Eugenia Campos Galv\u00e1n, puntera en los sondeos para elegir Gobernador en el Estado de Chihuahua, como queda dicho;<\/p>\n<p style=\"text-align: justify;\">\u00a0Apoyo descarado al Senador, Gustavo Enrique Madero Mu\u00f1oz, tambi\u00e9n como ya se dijo;<\/p>\n<p style=\"text-align: justify;\">Uso del aparato estatal para emprender una persecuci\u00f3n en contra de la Lic. Mar\u00eda Eugenia Campos Galv\u00e1n;<\/p>\n<p style=\"text-align: justify;\">Caso omiso a las mujeres panistas que pidieron a la Ing. Roc\u00edo Esmeralda Reza Gallegos investigar la violencia de g\u00e9nero perpetrada por el Gobernador constitucional del Estado, Lic. Javier Corral Jurado, en contra de la Lic. Mar\u00eda Eugenia Campos Galv\u00e1n, Presidenta Municipal de Chihuahua, y<\/p>\n<p style=\"text-align: justify;\">\u201cDesplantes\u201d y groser\u00edas por parte del Gobernador constitucional del Estado, Lic. Javier Corral Jurado, en contra de la Lic. Mar\u00eda Eugenia Campos Galv\u00e1n, Presidenta Municipal de Chihuahua.<\/p>\n<p style=\"text-align: justify;\">Todos estos hechos se demuestran plenamente merced al caudal probatorio que, como queda dicho, agregu\u00e9 a mi respuesta; sin embargo, lo verdaderamente relevante no es si la Comisi\u00f3n de Atenci\u00f3n a la Violencia Pol\u00edtica en raz\u00f3n de G\u00e9nero contra las Mujeres Militantes del Partido Acci\u00f3n Nacional me sanciona o no, eso es lo de menos.<\/p>\n<p style=\"text-align: justify;\">Lo importante, lo trascendente, lo destacable, es que en medio de ese desorden propiciado por el titular del Poder Ejecutivo Estatal, la respuesta institucional del Comit\u00e9 Directivo Estatal del Partido Acci\u00f3n Nacional en el Estado, a cargo de la Ing. Roc\u00edo Esmeralda Reza Gallegos, sean el linchamiento y la persecuci\u00f3n pol\u00edticos para acallar a las miles de voces disidentes (por eso en estas l\u00edneas no me ocupo de demostrar mi inocencia, lo que detallo en la contestaci\u00f3n a la infundada denuncia, misma que acompa\u00f1o a este escrito, como queda dicho).<\/p>\n<p style=\"text-align: justify;\">Tengo entendido, no me consta, que no soy la \u00fanica persona en esa lista de perseguidos pol\u00edticos; a todos ellos, por este medio, les convoco para que hagan contacto con el suscrito y emprendamos una lucha conjunta por la dignificaci\u00f3n del Partido Acci\u00f3n Nacional en el Estado de Chihuahua para deponer a quien es incapaz de atender en forma adecuada los asuntos de la instituci\u00f3n por estar alimentando apetitos personales o de facci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En efecto, no es atacando a adversarios inexistentes, ciudadanos todos, compa\u00f1eros de ideales y de lucha, como se alcanzar\u00e1n los objetivos, mediatos o inmediatos, de la Instituci\u00f3n. En todo caso, es de tener en cuenta que la dirigencia deber\u00eda constituirse en \u00e1rbitro imparcial, promotora del di\u00e1logo y procuradora eficiente en la soluci\u00f3n de los diferendos propios de cualquier comunidad de personas.<\/p>\n<p style=\"text-align: justify;\">Otra cosa, alzarse, como de hecho se alza, en diligente verdugo para acallar las voces disidentes solo sirve para debilitar a un organismos que, visto los tiempos que corren, deber\u00eda estar m\u00e1s fuerte que nunca.<\/p>\n<p style=\"text-align: justify;\">Esa actitud es no solo irresponsable, es tambi\u00e9n est\u00fapida.<\/p>\n<p style=\"text-align: justify;\">En mi descargo, s\u00f3lo dir\u00e9 una cosa: en lo medular, la denunciante se escandaliza y se siente agraviada por un solo comentario, hecho por el suscrito una sola vez, dirigido a su persona llam\u00e1ndola \u201cignorante\u201d (lo que, por lo dem\u00e1s, demostrar\u00e9 en los p\u00e1rrafos subsecuentes) y no toma en cuenta la lesi\u00f3n de que una mujer como la Lic. Mar\u00eda Eugenia Campos Galv\u00e1n, Presidenta Municipal de Chihuahua, debi\u00f3 sufrir en su estado de \u00e1nimo, honra, fama p\u00fablica y buen nombre, pues a pesar de ser una reconocida panista, bien posicionada, con buena imagen y con todas las posibilidades de ser la pr\u00f3xima Gobernadora en la Entidad, debe padecer el escarnio y los ataques indemostrados perpetrados en su contra por el Gobernador constitucional de la Entidad, Lic. Javier Corral Jurado, quien de manera p\u00fablica y falaz, en medios locales y nacionales, la ha insultado de m\u00faltiples maneras, con una serie de ep\u00edtetos y calificativos esos s\u00ed denigrantes y del todo injustificados.<\/p>\n<p style=\"text-align: justify;\">Es decir, en el \u00e1nimo de la ahora denunciada, Ing. Roc\u00edo Esmeralda Reza Gallegos pesa m\u00e1s que el suscrito, con justa raz\u00f3n y en medio de la crisis pol\u00edtica que nos circunda, la haya llamado \u201cignorante\u201d, que el hecho de que el supuesto panista con el m\u00e1s elevado cargo p\u00fablico en el Estado, el Gobernador constitucional de la Entidad, Lic. Javier Corral Jurado, agreda, ataque, vilipendie, calumnie y difame, de lo que multitud de medios dan cuenta, a una exitosa mujer panista. Eso demuestra de manera palmaria, y sin ning\u00fan lugar a dudas, el desinter\u00e9s en los asuntos del partido, su parcialidad evidente a favor de un displicente irracional como es el Gobernador constitucional de la Entidad, Lic. Javier Corral Jurado, y la poca, o nula, diligencia que dicha dirigente partidista pone en los asuntos propios de su responsabilidad.<\/p>\n<p style=\"text-align: justify;\">Sin que pueda soslayarse lo fr\u00edvolo e ingenuo del proceder de dicha funcionaria, pues en medio de la grave y manifiesta crisis por la que atraviesa el Partido, a causa del actuar del referido funcionario p\u00fablico, y como ella misma lo confiesa, su acci\u00f3n se limita a enviar mensajitos de texto en vez de emprender una serie de acciones contundentes y manifiestas, que no dejaran lugar para la duda, como son: a) Exigir el estricto cumplimiento del estado de derecho y b) Exigir del Gobernador que cese en sus amagos, insultos y amenazas en contra de la Lic. Mar\u00eda Eugenia Campos Galv\u00e1n, Presidenta Municipal de Chihuahua; lo anterior porque eso s\u00ed \u2014y no llamados confusos y equ\u00edvocos, vac\u00edos de contenido\u2014 le abonar\u00eda a la unidad y a reivindicar la imagen del Partido.<\/p>\n<p style=\"text-align: justify;\">Y es as\u00ed, porque a mi comentario, que fue del tenor literal siguiente:<\/p>\n<p style=\"text-align: justify;\">\u201c<em>Qu\u00e9 pena, Roc\u00edo, que pierdas la oportunidad de poner las cosas en orden. Como panista, l\u00edder de panistas y mujer, tendr\u00edas que exigir el estricto cumplimiento del estado de derecho y pedirle al energ\u00fameno, loco, enfermo de poder y actual gobernador del estado de Chihuahua, que cese en sus amagos, insultos y amenazas. Eso s\u00ed le abonar\u00eda a la unidad y a reivindicar la imagen del Partido. Cr\u00e9eme, enti\u00e9ndelo, Corral es un lastre que va a hundir al PAN y entregarle el gobierno a MORENA. Es un loco que debe ser ignorado y rebasado por la militancia; y tu \u00fanica obligaci\u00f3n ES LOGRAR QUE EL PAN GANE EN 2021. NO hacerle caso a un pobre demente que cree que gobierna. Ojal\u00e1 y puedas entender esa verdad tan simple. Lo contrario ser\u00eda traicionar tu deber<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">La Ing. Roc\u00edo Esmeralda Reza Gallegos, respondi\u00f3, textualmente:<strong>\u00a0<\/strong>\u201c<em>Luis Villegas que pena estimado Magistrado que con su investidura se exprese de esa manera. En efecto como Presidenta del PAN debo actuar con prudencia y firmeza, situaci\u00f3n que no tengo porque hacer p\u00fablico. Le pido como Presidenta del partido en el q ud sigue militando abone a la unidad<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">Ese fue el momento en que, con toda raz\u00f3n, la llam\u00e9 ignorante. La llam\u00e9 ignorante:<\/p>\n<p style=\"text-align: justify;\">Primero, porque la denunciante parece ignorar la diferencia entre ciudadano, militante y magistrado.<\/p>\n<p style=\"text-align: justify;\">Por ciudadano, el diccionario<a href=\"https:\/\/unareflexionpersonal.wordpress.com\/2020\/09\/26\/respuesta-a-queja-de-rocio-reza\/#_ftn1\">[1]<\/a>\u00a0entiende al natural o vecino de una ciudad o, ya m\u00e1s en lo espec\u00edfico, a la persona considerada como miembro activo de un Estado o el titular de derechos sometido a las leyes; por \u201cmilitante\u201d, el mismo diccionario entiende a \u201cqui\u00e9n milita\u201d [en favor de algo]; y por \u201cmagistrado\u201d, al miembro de la carrera judicial \u201c<em>con categor\u00eda superior a la del juez<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">De esa guisa, cuando la denunciante responde con eso de que:<strong>\u00a0<\/strong>\u201c<em>que pena estimado Magistrado que con su investidura se exprese de esa manera<\/em>\u201d, demuestra su ignorancia pues NO EXISTE ninguna relaci\u00f3n l\u00f3gico-jur\u00eddica o causal entre mis dichos o expresiones y la investidura que ostento.<\/p>\n<p style=\"text-align: justify;\">Es decir, no existe ning\u00fan v\u00ednculo, de ning\u00fan tipo, entre las expresiones vertidas por el suscrito y una de tantas de las caracter\u00edsticas que, como ser humano, me definen; pues, en efecto, adem\u00e1s de Magistrado y militante de un Partido pol\u00edtico como ciudadano que soy, soy tambi\u00e9n mexicano, comunicador, licenciado en derecho, especialista en cultura de la legalidad, Maestro en Pol\u00edticas P\u00fablicas, Doctor en Derecho Judicial, padre de familia, abuelo, hijo, hermano y un etc\u00e9tera enorme que me define en lo que soy y en qui\u00e9n soy; de tal suerte que mis dichos, dirigidos a la denunciante, junto a decenas de mujeres panistas, exigi\u00e9ndole una conducta en concreto a ra\u00edz del grave problema pol\u00edtico-partidista-medi\u00e1tico-preelectoral provocado por el Gobernador constitucional de la Entidad, Lic. Javier Corral Jurado, NO GUARDAN RELACI\u00d3N de ning\u00fan tipo con mi investidura; lo que demuestra, insisto, una ignorancia grosera de las distintas condiciones que me definen.<\/p>\n<p style=\"text-align: justify;\">Segundo, por destacada y destacable, la llam\u00e9 ignorante porque saltaron a la vista una serie de lamentables yerros ling\u00fc\u00edsticos plasmados por la denunciante; en efecto, como se aprecia de la transcripci\u00f3n que ella misma hace de su texto, escribi\u00f3 lo que escribi\u00f3 ignorando en la especie que:<\/p>\n<p style=\"text-align: justify;\">La palabra\u00a0\u201c<em>qu\u00e9<\/em>\u201d, es t\u00f3nica y se escribe con tilde diacr\u00edtica cuando tiene sentido interrogativo o exclamativo, como es el caso;<\/p>\n<p style=\"text-align: justify;\">Otro tanto puede decirse de la palabra \u201cporque\u201d, la cual, en la especie, hace las veces de un sustantivo masculino que equivale a\u00a0<em>causa, motivo<\/em>\u00a0o\u00a0<em>raz\u00f3n; por lo que\u00a0<\/em>se escribe con tilde por ser palabra aguda terminada en vocal;<\/p>\n<p style=\"text-align: justify;\">Sin que pueda obviarse que cuando escribe: \u201c<em>En efecto como Presidenta<\/em>\u201d, lo hace tambi\u00e9n en forma incorrecta pues falta una coma (,) entre la expresi\u00f3n \u201cEn efecto\u201d y la de \u201ccomo Presidenta\u201d, pues la primera tiene como finalidad reiterar una afirmaci\u00f3n previa, de tal suerte que se trata de dos ideas que, aunque conectadas, se deben escribir por separado;<\/p>\n<p style=\"text-align: justify;\">Situaci\u00f3n que se repite cuando escribe: \u201c<em>Le pido como Presidenta del partido en el q ud sigue militando abone a la unidad<\/em>\u201d, pues entre las palabras \u201c<em>partido<\/em>\u201d y \u201c<em>en<\/em>\u201d y \u201c<em>militando<\/em>\u201d y \u201c<em>abone<\/em>\u201d, debi\u00f3 escribir sendo par de comas, pues la expresi\u00f3n \u201c<em>en el q ud sigue militando<\/em>\u201d, es una idea secundaria del enunciado principal: \u201c<em>Le pido como Presidenta del partido abone a la unidad<\/em>\u201d;<\/p>\n<p style=\"text-align: justify;\">Por no hablar de la falta del pronombre relativo \u201cque\u201d, el cual sirve para introducir una oraci\u00f3n en la que se indican ciertas caracter\u00edsticas del nombre al que dicha oraci\u00f3n complementa, entre las palabras \u201cmilitando\u201d y \u201c<em>abone<\/em>\u201d, pues efectivamente como Presidenta del Partido me estaba pidiendo \u201c<em>que abonara a la unidad<\/em>\u201d;<\/p>\n<p style=\"text-align: justify;\">La palabra \u201c<em>p\u00fablico<\/em>\u201d tambi\u00e9n est\u00e1 mal escrita pues en el caso concreto se emplea como adjetivo y complementa al sustantivo \u201csituaci\u00f3n\u201d, que es femenino; y como se sabe, entre el sustantivo y el adjetivo debe existir concordancia, por lo que debi\u00f3 escribir \u201cp\u00fablica\u201d y no como lo hizo;<\/p>\n<p style=\"text-align: justify;\">Aunque las anteriores son minucias, al alcance solo de quienes s\u00ed tienen experiencia en la escritura, donde ya s\u00ed resulta lamentable, y visible, la ignorancia de la autora del texto, es cuando escribe la letra: \u201cq\u201d, misma que, en espa\u00f1ol, carece de significado; y<\/p>\n<p style=\"text-align: justify;\">Seguido de esa letra aislada carente de significado, agrega otras dos letras sueltas \u201cud\u201d que tambi\u00e9n en espa\u00f1ol no significan absolutamente nada, a menos, claro est\u00e1, que las siga un punto, mismo que constituye la abreviatura de la palabra \u201custed\u201d.<\/p>\n<p style=\"text-align: justify;\">Ocuparme de los detalles ling\u00fc\u00edsticos referidos con antelaci\u00f3n no constituye un af\u00e1n gratuito de evidenciar la ignorancia de la denunciante, sino destacar el hecho de que una persona incapaz de redactar sin errores ortogr\u00e1ficos un texto de dos o tres l\u00edneas, dif\u00edcilmente podr\u00e1 captar el entorno jur\u00eddico-pol\u00edtico-partidista-preelectoral que rese\u00f1o en mi contestaci\u00f3n en forma detallada y la encomienda a su cargo en dicho trance, como queda demostrado por lo que ya apunt\u00e9 l\u00edneas atr\u00e1s, es decir, que frente a una agresi\u00f3n actual, con claros tintes de misoginia, enderezada por un var\u00f3n (el ahora denunciado, Gobernador constitucional de la Entidad, Lic. Javier Corral Jurado), en contra de una mujer, para descalificarla p\u00fablicamente y destruir su carrera pol\u00edtica de cara a la elecci\u00f3n de Gobernador del a\u00f1o pr\u00f3ximo, en claro beneficio de un var\u00f3n (el Senador Gustavo Enrique Madero Mu\u00f1oz), se limit\u00f3 a emitir un comunicado confuso y equ\u00edvoco, en el mejor de los casos, o grotesco y ofensivo en el peor.<\/p>\n<p style=\"text-align: justify;\">Por las razones anteriores, es que no me limito a responder la infundada denuncia interpuesta en mi contra, sino que respond\u00ed presentando a mi vez, una queja en contra de la militante Ing. Roc\u00edo Esmeralda Reza Gallegos, en su car\u00e1cter de Presidenta del Comit\u00e9 Directivo Estatal del Partido Acci\u00f3n Nacional de Chihuahua; y del Lic. Javier Corral Jurado, Gobernador Constitucional del Estado de Chihuahua, por hechos constitutivos de violencia pol\u00edtica en contra de las mujeres en raz\u00f3n de g\u00e9nero.<\/p>\n<p style=\"text-align: justify;\">Antes de concluir, es de tener en cuenta el dicho de la propia quejosa en su escrito inicial, donde textualmente refiri\u00f3: \u201c<em>Por tanto, es necesario que el Partido Acci\u00f3n Nacional no pase por alto este tipo de acciones violentas de un militante en contra de otra mujer militante, pues de lo contrario no se estar\u00eda cumpliendo con el objetivo que tenemos como instituci\u00f3n p\u00fablica y como sociedad para sancionar y erradicar la violencia pol\u00edtica en contra de las mujeres en raz\u00f3n de g\u00e9nero<\/em>\u201d; mismo que al tenor de los principios jur\u00eddicos de: \u201ca confesi\u00f3n de parte, relevo de prueba\u201d y de adquisici\u00f3n procesal, solicito que se tome en cuenta para determinar la gravedad y trascendencia de los hechos que se denuncian.<\/p>\n<p style=\"text-align: justify;\">As\u00ed es, el que la denunciante estime que es necesario que el Partido Acci\u00f3n Nacional no pase por alto este tipo de acciones violentas de un militante en contra de otra mujer militante, pues de lo contrario no se estar\u00eda cumpliendo con el objetivo que se tiene como instituci\u00f3n p\u00fablica y como sociedad para sancionar y erradicar la violencia pol\u00edtica en contra de las mujeres en raz\u00f3n de g\u00e9nero, debe servir para orientar la actividad sancionatoria que se enderece en contra del Lic. Javier Corral Jurado, Gobernador Constitucional del Estado de Chihuahua, por hechos constitutivos de violencia pol\u00edtica en contra de las mujeres en raz\u00f3n de g\u00e9nero, primero; y segundo, en contra de la propia denunciante, por su omisi\u00f3n culpable para poner fin, y sancionar, a dicho funcionario, por los mismos motivos.<\/p>\n<p style=\"text-align: justify;\">En s\u00edntesis, sobre esos ejes es que gira la respuesta del suscrito a los ataques y a la persecuci\u00f3n pol\u00edtica de que se me pretende hacer objeto; adem\u00e1s de alegar que a quejosa no prueba sus dichos y que el suscrito est\u00e1 amparado por el derecho a la libre expresi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Termino reiterando un llamado a todos aquellos que se sienten agraviados o perseguidos por una dirigencia que en vez de actuar de conformidad con la l\u00f3gica y el sentido com\u00fan, act\u00faa con la v\u00edscera y el desconocimiento en claro beneficio de apetitos personales y de facci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Cont\u00e1cteme a trav\u00e9s de mi correo electr\u00f3nico o s\u00edgame en los medios que gentilmente me publican, en\u00a0<em>Facebook<\/em>\u00a0o tambi\u00e9n en mi blog:\u00a0<a href=\"https:\/\/unareflexionpersonal.wordpress.com\/\">https:\/\/unareflexionpersonal.wordpress.com\/<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Chihuahua, Chih. a 26 de septiembre de 2020.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Luis Villegas Montes.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"mailto:luvimo6608@gmail.com\">luvimo6608@gmail.com<\/a>,\u00a0<a href=\"mailto:luvimo6614@hotmail.com\">luvimo6614@hotmail.com<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde hace quince d\u00edas, circulan en medios notas relativas a la queja interpuesta en contra del suscrito por la Ing. Roc\u00edo Esmeralda Reza Gallegos, en su calidad de militante del Partido Acci\u00f3n Nacional, y como Presidenta del Comit\u00e9 Directivo Estatal de dicho instituto pol\u00edtico en el Estado, por la comisi\u00f3n de diversos actos constitutivos de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":24512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Respuesta a queja de Roc\u00edo Reza - Opini\u00f3n P\u00fablica","description":"Desde hace quince d\u00edas, circulan en medios notas relativas a la queja interpuesta en contra del suscrito por la Ing. Roc\u00edo Esmeralda Reza Gallegos, en su calida"},"footnotes":""},"categories":[19],"tags":[],"class_list":["post-24513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal-columnas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/24513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=24513"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/24513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/24512"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=24513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=24513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=24513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}