{"id":24228,"date":"2020-09-01T06:00:00","date_gmt":"2020-09-01T04:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2020\/09\/01\/inicia-el-tercer-ano-legislativo-del-congreso-de-chihuahua\/"},"modified":"2020-09-01T06:00:00","modified_gmt":"2020-09-01T04:00:00","slug":"inicia-el-tercer-ano-legislativo-del-congreso-de-chihuahua","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/inicia-el-tercer-ano-legislativo-del-congreso-de-chihuahua\/","title":{"rendered":"Inicia Tercer A\u00f1o Legislativo del Congreso de Chihuahua"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-24227\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/6623323f9f8f70ebc3c816c8be881db8.jpg\" alt=\"\" class=\"caption\" title=\"Este 1 de septiembre inici\u00f3 el Tercer A\u00f1o Legislativo del Congreso de Chihuahua.\" width=\"1280\" height=\"853\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/6623323f9f8f70ebc3c816c8be881db8.jpg 1280w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/6623323f9f8f70ebc3c816c8be881db8-300x200.jpg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/6623323f9f8f70ebc3c816c8be881db8-1024x682.jpg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/6623323f9f8f70ebc3c816c8be881db8-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Chihuahua, Chih<\/em>.- En Sesi\u00f3n Solemne de la Sexag\u00e9sima Sexta Legislatura del Congreso de Chihuahua, con la presencia de manera virtual de los representantes de los Poderes Ejecutivo y Judicial, este martes se llev\u00f3 a cabo la instalaci\u00f3n del Primer Periodo Ordinario de Sesiones, dentro del Tercer A\u00f1o de Ejercicio Constitucional, el cual ser\u00e1 presidido por la diputada Blanca G\u00e1mez Guti\u00e9rrez.\u00a0<\/p>\n<p style=\"text-align: justify;\">La diputada Blanca G\u00e1mez dio lectura al Decreto de inicio del Primer Periodo Ordinario, as\u00ed como al Decreto de designaci\u00f3n de la Mesa Directiva que dirigir\u00e1 los trabajos a partir de este 1 de septiembre del 2020.<\/p>\n<p style=\"text-align: justify;\">G\u00e1mez Guti\u00e9rrez, emiti\u00f3 un mensaje en el que resalt\u00f3 que durante este a\u00f1o, las labores del Legislativo se conducir\u00e1n de manera pulcra y transparente, para dar privilegio en todo momento la Ley Org\u00e1nica y el Reglamento del Poder Legislativo; as\u00ed mismo, en uni\u00f3n y construcci\u00f3n de lazos de confianza, basados en respeto y ayuda mutua.<\/p>\n<p style=\"text-align: justify;\">Para finalizar, agradeci\u00f3 a sus compa\u00f1eros y compa\u00f1eras por la confianza brindada al ser elegida para dirigir las labores de este \u00faltimo a\u00f1o Legislativo y resalt\u00f3 que asumir dicha responsabilidad es un gran honor para ella.<\/p>\n<p style=\"text-align: justify;\">El acto solemne cont\u00f3 con la presencia virtual del Lic. Luis Fernando Mesta Soul\u00e9, Secretario General de la Administraci\u00f3n Estatal, en representaci\u00f3n del Gobernador del Estado, Javier Corral Jurado, y del Magistrado Presidente del Tribunal Superior de Justicia del Estado, Pablo H\u00e9ctor Gonz\u00e1lez Villalobos.<\/p>\n<p style=\"text-align: justify;\">Cabe mencionar que con fundamento en los art\u00edculos 7 y 75, fracci\u00f3n XXII de la Ley Org\u00e1nica del Poder Legislativo del Estado de Chihuahua, las sesiones del Congreso se pueden realizar en la modalidad de acceso remoto o virtual, y presencial en el Recinto Oficial del Poder Legislativo; a partir de este d\u00eda, las sesiones del Periodo Ordinario se llevar\u00e1n a cabo martes y jueves, a las 11:00 horas, en el Recinto Legislativo.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":24227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Inicia Tercer A\u00f1o Legislativo del Congreso de Chihuahua - Opini\u00f3n P\u00fablica","description":"Chihuahua, Chih .- En Sesi\u00f3n Solemne de la Sexag\u00e9sima Sexta Legislatura del Congreso de Chihuahua, con la presencia de manera virtual de los representantes de l"},"footnotes":""},"categories":[4],"tags":[],"class_list":["post-24228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pulsopolitico"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/24228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=24228"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/24228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/24227"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=24228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=24228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=24228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}