{"id":24218,"date":"2020-09-01T06:00:00","date_gmt":"2020-09-01T04:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2020\/09\/01\/efemerides-1-de-septiembre-4\/"},"modified":"2020-09-01T06:00:00","modified_gmt":"2020-09-01T04:00:00","slug":"efemerides-1-de-septiembre-4","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/efemerides-1-de-septiembre-4\/","title":{"rendered":"Efem\u00e9rides 1 de septiembre"},"content":{"rendered":"<img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-24217\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/bb7a359323276c80ff4ede845d0a865d-scaled.jpg\" alt=\"\" class=\"caption\" title=\"Tropas nazis invaden Polonia con lo que inicia la Segunda Guerra Mundial.\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/bb7a359323276c80ff4ede845d0a865d-scaled.jpg 2560w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/bb7a359323276c80ff4ede845d0a865d-300x225.jpg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/bb7a359323276c80ff4ede845d0a865d-1024x768.jpg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/bb7a359323276c80ff4ede845d0a865d-768x576.jpg 768w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/bb7a359323276c80ff4ede845d0a865d-1536x1152.jpg 1536w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/09\/bb7a359323276c80ff4ede845d0a865d-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\n<p style=\"text-align: justify;\">Un d\u00eda 1 de septiembre como hoy, pero de 1939, comienza la II Guerra Mundial con la invasi\u00f3n nazi de Polonia y la anexi\u00f3n de Danzig (actual Gdansk).<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>M\u00e1s efem\u00e9rides<\/strong><\/p>\n<p style=\"text-align: justify;\">1340.- Petrarca recibe del Senado de la ciudad de Roma la corona de laurel que le consagra como poeta de obra inmortal.<\/p>\n<p style=\"text-align: justify;\">1823.- Sim\u00f3n Bol\u00edvar llega a Lima y asume la suprema autoridad pol\u00edtica y militar.<\/p>\n<p style=\"text-align: justify;\">1841.- Un terremoto destruye la ciudad de Cartago (Costa Rica).<\/p>\n<p style=\"text-align: justify;\">1851.- Es fusilado en La Habana el dirigente de la insurrecci\u00f3n cubana Narciso L\u00f3pez.<\/p>\n<p style=\"text-align: justify;\">1870.- Cirilo Antonio Rivarola es designado presidente provisional de Paraguay.<\/p>\n<p style=\"text-align: justify;\">1882.- El general Ulises Heureaux inaugura su segundo bienio presidencial en la Rep\u00fablica Dominicana.<\/p>\n<p style=\"text-align: justify;\">1904.- Fundaci\u00f3n del Estado del L\u00edbano.<\/p>\n<p style=\"text-align: justify;\">1906.- Nace Joaqu\u00edn Balaguer, siete veces presidente de la Rep\u00fablica Dominicana.<\/p>\n<p style=\"text-align: justify;\">1922.- Nace Vittorio Gassman, actor italiano.<\/p>\n<p style=\"text-align: justify;\">1923.- Terremoto en Jap\u00f3n e incendios masivos: 140,000 muertos en Tokio, Yokohama y entornos.<\/p>\n<p style=\"text-align: justify;\">1924.- Gonzalo C\u00f3rdoba asume el poder en Ecuador en un ambiente de agitaci\u00f3n social y militar.<\/p>\n<p style=\"text-align: justify;\">1929.- Atentado nazi con bombas en el edificio del Reichstag (Parlamento) en Berl\u00edn.<\/p>\n<p style=\"text-align: justify;\">1932.- Tropas peruanas toman el puerto colombiano de Leticia en el Amazonas y provocan una guerra no declarada.<\/p>\n<p style=\"text-align: justify;\">1934.- Jos\u00e9 Mar\u00eda Velasco Ibarra es elegido presidente de Ecuador por amplia mayor\u00eda.<\/p>\n<p style=\"text-align: justify;\">1935.- Nace Seiji Ozawa, director de orquesta japon\u00e9s.<\/p>\n<p style=\"text-align: justify;\">1940.- Carlos Alberto Arroyo del R\u00edo asume la presidencia de Ecuador.<\/p>\n<p style=\"text-align: justify;\">1946.- Los griegos aprueban en refer\u00e9ndum, con el 69 % de los votos, la restauraci\u00f3n de la Monarqu\u00eda.<\/p>\n<p style=\"text-align: justify;\">1948.- Se constituye en Bonn (Alemania) el Consejo Parlamentario presidido por Konrad Adenauer.<\/p>\n<p style=\"text-align: justify;\">1948.- Galo Plaza Laso, nuevo presidente de la Rep\u00fablica de Ecuador.<\/p>\n<p style=\"text-align: justify;\">1949.- Se proh\u00edbe el uso monetario del oro y la plata en Argentina.<\/p>\n<p style=\"text-align: justify;\">1951.- Eva Duarte de Per\u00f3n renuncia a la candidatura a la vicepresidencia de Argentina, propuesta por el sindicato CGT.<\/p>\n<p style=\"text-align: justify;\">1951.- Australia, Nueva Zelanda y EEUU firman en San Francisco el Tratado de Seguridad Tripartito del Pac\u00edfico (ANZUS).<\/p>\n<p style=\"text-align: justify;\">1957.- Nace Gloria Estefan, cantante estadounidense nacida en Cuba.<\/p>\n<p style=\"text-align: justify;\">1962.- Un violento terremoto azota Ir\u00e1n y ocasiona la muerte de m\u00e1s de 12,000 personas.<\/p>\n<p style=\"text-align: justify;\">1969.- El coronel Muamar Gadafi y j\u00f3venes oficiales de la izquierda del Ej\u00e9rcito derrocan en Libia al rey Idris, e instauran el Consejo Supremo de la Revoluci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">1971.- El emirato de Catar se declara independiente y deja de ser protectorado brit\u00e1nico.<\/p>\n<p style=\"text-align: justify;\">1962.- Inauguraci\u00f3n del puente m\u00e1s largo de Am\u00e9rica del Sur, sobre el lago Maracaibo, en Venezuela.<\/p>\n<p style=\"text-align: justify;\">1970.- Muere Francois Mauriac, escritor franc\u00e9s, Premio Nobel 1952.<\/p>\n<p style=\"text-align: justify;\">1974.- El general Anastasio Somoza es reelegido presidente de Nicaragua.<\/p>\n<p style=\"text-align: justify;\">1977.- Muere Jorge Icaza, novelista ecuatoriano.<\/p>\n<p style=\"text-align: justify;\">1982.- Nacionalizaci\u00f3n de la Banca de M\u00e9xico.<\/p>\n<p style=\"text-align: justify;\">1983.- Cazas sovi\u00e9ticos derriban un avi\u00f3n comercial surcoreano de la compa\u00f1\u00eda de bandera JAL con 269 pasajeros que se hab\u00eda adentrado en el espacio a\u00e9reo de la URSS a la altura de la isla de Sajal\u00edn. No hubo supervivientes.<\/p>\n<p style=\"text-align: justify;\">1985.- Hallazgo de los restos del Titanic en el Atl\u00e1ntico Norte por la expedici\u00f3n del ocean\u00f3grafo estadounidense Robert Ballard y un equipo internacional.<\/p>\n<p style=\"text-align: justify;\">1986.- Se hunde en el Mar Negro el buque sovi\u00e9tico \u00abAlmirante Najimov\u00bb al chocar contra un carguero. Mueren 116 personas y otras 282 desaparecen.<\/p>\n<p style=\"text-align: justify;\">1986.- Muere Jorge Alessandri, ex presidente chileno.<\/p>\n<p style=\"text-align: justify;\">1989.- El general Augusto Pinochet anuncia el regreso al pa\u00eds de los exiliados del r\u00e9gimen militar.<\/p>\n<p style=\"text-align: justify;\">1991.- El L\u00edbano y Siria firman un pacto de defensa y seguridad mutua que otorga a Damasco el derecho a responder a cualquier ataque israel\u00ed contra el L\u00edbano.<\/p>\n<p style=\"text-align: justify;\">1992.- Presentan en Roma la primera vacuna anticonceptiva v\u00e1lida para seis meses, descubierta por el indio Gurseran Talwar.<\/p>\n<p style=\"text-align: justify;\">1992.- Un maremoto arrasa las costas del Pac\u00edfico en Nicaragua: 118 muertos, 63 desaparecidos, 1,143 casas destruidas, 489 heridos, 25,000 damnificados y da\u00f1os por 26 millones de d\u00f3lares.<\/p>\n<p style=\"text-align: justify;\">1999.- Mireya Moscoso, viuda del pol\u00edtico Arnulfo Arias, es investida presidenta de Panam\u00e1.<\/p>\n<p style=\"text-align: justify;\">2003.- Un fiscal argentino pide la detenci\u00f3n de Jorge Videla y Alfredo Astiz y otros nueve militares en la causa que investiga el Plan C\u00f3ndor.<\/p>\n<p style=\"text-align: justify;\">2004.- Un comando terrorista chech\u00e9n asalta una escuela de Beslan, en Osetia del Norte, con 1,120 personas en su interior, entre profesores, padres y alumnos. El ataque termin\u00f3 dos d\u00edas despu\u00e9s con la muerte de 331 personas, 186 de ellas ni\u00f1os, al entrar las tropas rusas en el recinto.<\/p>\n<p style=\"text-align: justify;\">2004.- Mart\u00edn Torrijos es investido nuevo presidente de Panam\u00e1.<\/p>\n<p style=\"text-align: justify;\">2008.- Muere Edwin Guthman, periodista estadounidense premio pulitzer 1950. Fue jefe de prensa de Robert F. Kennedy.<\/p>\n<p style=\"text-align: justify;\">2010.- Treinta y cinco muertos y 200 heridos en Pakist\u00e1n en un atentado contra una procesi\u00f3n chi\u00ed en Lahore, la segunda ciudad m\u00e1s poblada del pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">2011.- Comienza a arrasar Colombia el temporal \u00abLa ni\u00f1a\u00bb, que durante tres meses y medio, provoc\u00f3 lluvias torrenciales que causaron 164 muertos, una treintena de desaparecidos, cerca de 200 heridos y casi 900 mil damnificados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00eda 1 de septiembre como hoy, pero de 1939, comienza la II Guerra Mundial con la invasi\u00f3n nazi de Polonia y la anexi\u00f3n de Danzig (actual Gdansk).<\/p>\n","protected":false},"author":6,"featured_media":24217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Efem\u00e9rides 1 de septiembre - Opini\u00f3n P\u00fablica","description":"Un d\u00eda 1 de septiembre como hoy, pero de 1939, comienza la II Guerra Mundial con la invasi\u00f3n nazi de Polonia y la anexi\u00f3n de Danzig (actual Gdansk). M\u00e1s efem\u00e9ri"},"footnotes":""},"categories":[27],"tags":[],"class_list":["post-24218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-dia-como-hoy"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/24218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=24218"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/24218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/24217"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=24218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=24218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=24218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}