{"id":22889,"date":"2020-04-08T06:00:00","date_gmt":"2020-04-08T04:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2020\/04\/08\/fotogaleria-fin-de-la-cuarentena-del-coronavirus-en-wuhan-en-imagenes\/"},"modified":"2020-04-08T06:00:00","modified_gmt":"2020-04-08T04:00:00","slug":"fotogaleria-fin-de-la-cuarentena-del-coronavirus-en-wuhan-en-imagenes","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/fotogaleria-fin-de-la-cuarentena-del-coronavirus-en-wuhan-en-imagenes\/","title":{"rendered":"Fotogaler\u00eda: As\u00ed se vivi\u00f3 el fin de la cuarentena del coronavirus en Wuhan, China"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-22876\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/a734cedca0e6708d3dc14224a8530be6.jpg\" alt=\"\" class=\"caption\" title=\"Millones de chinos celebraron el fin de la cuarentena de 76 d\u00edas en Wuhan, cuna del Covid-19.\" width=\"680\" height=\"430\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/a734cedca0e6708d3dc14224a8530be6.jpg 680w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/a734cedca0e6708d3dc14224a8530be6-300x190.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Wuhan, China<\/em>.- Luego de 11 semanas de confinamiento la gente sali\u00f3 a la calle y miles subieron a los primeros trenes y aviones que partieron de la ciudad d\u00f3nde se origin\u00f3 la pandemia del nuevo coronavirus.<\/p>\n<p style=\"text-align: justify;\">Pese a las dudas sobre la veracidad de las estad\u00edsticas de China, la cuarentena sin precedentes decretada en la provincia de Hubei ha tenido \u00e9xito suficiente para que otros pa\u00edses adoptaran medidas similares. A las 00H00 del mi\u00e9rcoles (16H00 GMT del martes) se\u00a0levantaron\u00a0las\u00a0restricciones\u00a0impuestas hace\u00a0m\u00e1s de dos meses\u00a0que\u00a0imped\u00edan abandonar la ciudad\u00a0de\u00a011 millones de habitantes, un paso clave para el fin de la\u00a0crisis sanitaria\u00a0en\u00a0China.<\/p>\n<p style=\"text-align: justify;\">Las siguientes im\u00e1genes dan testimonio de ese hecho hist\u00f3rico en la ciudad donde naci\u00f3 el coronavirus Covid-19.<\/p>\n<p style=\"text-align: justify;\"><strong>1\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\" size-full wp-image-22877\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_1.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_1.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_1-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_1-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_1-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">Un grupo de m\u00e9dicos celebra que ya pueden regresar a sus casa en otras provincias de China en el aeropuerto de Wuhan. Tras 11 semanas de confinamiento, la gente sali\u00f3 a la calle y miles subieron a los primeros trenes y aviones que partieron de la ciudad d\u00f3nde se origin\u00f3 la pandemia del coronavirus.\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>2\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\" size-full wp-image-22878\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_2.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_2.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_2-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_2-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_2-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">Pasajeros entrando al primer tren que parti\u00f3 de una estaci\u00f3n despu\u00e9s de que se levant\u00f3 la cuarentena en Wuhan. Con el final de las restricciones, la capital de la provincia de Hubei inicia otro experimento: reanudar la actividad econ\u00f3mica y la vida cotidiana mientras se evitan nuevos contagios.\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>3\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22879\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_3.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_3.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_3-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_3-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_3-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">El tr\u00e1nsito no tard\u00f3 mucho en recuperar la normalidad en los puentes, t\u00faneles y peajes reabiertos y seg\u00fan las autoridades casi 1,000 veh\u00edculos cruzaron un concurrido peaje en la frontera de Wuhan a la medianoche, cuando se levantaron las barricadas. El gobierno no report\u00f3 nuevos contagios el mi\u00e9rcoles.\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>4\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22880\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_4a.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_4a.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_4a-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_4a-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_4a-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Pasajeros reunidos frente a la estaci\u00f3n de tren Hankou en Wuhan, donde despu\u00e9s de 11 semanas de cuarentena, parti\u00f3 el primer tren la ma\u00f1ana del mi\u00e9rcoles. Los 11 millones de residentes de la ciudad tienen ahora permiso para salir sin una autorizaci\u00f3n especial, pero deben llevar una aplicaci\u00f3n en su tel\u00e9fono en la que las autoridades pueden vigilar sus movimientos, estado de salud y contacto con otras personas.\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>5\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22881\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_5.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_5.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_5-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_5-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_5-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">Los residentes cruzan el r\u00edo Yangtz\u00e9 en ferry luego del levantamiento de las restricciones. La ocasi\u00f3n se conmemor\u00f3 con un espect\u00e1culo de luces a ambas orillas de este r\u00edo. En los embarcaderos y puentes, residentes ondearon banderas, corearon \u201c\u00a1Vamos Wuhan!\u201d e interpretaron el himno nacional.<\/p>\n<p style=\"text-align: justify;\"><strong>6\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22882\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_6.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_6.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_6-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_6-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_6-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">M\u00e9dicos de un hospital de Wuhan celebrando en el aeropuerto. \u201cLlevaba m\u00e1s de 70 d\u00edas sin salir\u201d, dijo emocionado a la agencia AP Tong Zhengkun, residente de un edificio donde varios estuvieron enfermos de covid-19, por lo que todo el inmueble qued\u00f3 cerrado. \u201cEstar en casa por tanto tiempo me volvi\u00f3 loco\u201d, asegur\u00f3.\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>7\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22883\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_7.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_7.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_7-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_7-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_7-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">En cuesti\u00f3n de horas, unas 65,000 personas hab\u00edan dejado la ciudad solo en trenes y aviones, seg\u00fan medios locales. En la fotograf\u00eda pasajeros en la estaci\u00f3n Hankou, despu\u00e9s de la reanudaci\u00f3n de los servicios<\/p>\n<p style=\"text-align: justify;\"><strong>8\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22884\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_8.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_8.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_8-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_8-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_8-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">Trabajadores de una f\u00e1brica de veh\u00edculos en Wuhan a la hora del almuerzo, separados por barreras para evitar nuevos contagios. En esta ciudad se registraron la mayor\u00eda de los decesos por el coronavirus en China y las restricciones de movimiento se hab\u00edan aliviado gradualmente mientras el n\u00famero de nuevos casos descend\u00eda, seg\u00fan cifras del gobierno chino.\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>9\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22885\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_9.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_9.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_9-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_9-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_9-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">\u00abLa estaci\u00f3n Hankou te da la bienvenida\u00bb, se lee en un cartel que sostiene un trabajador ferroviario en Wuhan. Pese a las dudas sobre la veracidad del conteo de China, la cuarentena sin precedentes decretada en Wuhan y en Hubei ha tenido \u00e9xito suficiente para que otros pa\u00edses adoptasen medidas similares.<\/p>\n<p style=\"text-align: justify;\"><strong>10\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22886\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_10.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_10.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_10-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_10-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_10-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">Un grupo de j\u00f3venes comiendo en un restaurante callejero. Durante los 76 d\u00edas de confinamiento, los residentes de Wuhan pod\u00edan salir de sus casas solo para comprar comida y otras tareas consideradas absolutamente necesarias.<\/p>\n<p style=\"text-align: justify;\"><strong>11\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22887\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_11.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_11.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_11-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_11-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_11-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">La multitud de viajeros protegidos con m\u00e1scaras y trajes en el aeropuerto. Pese a las nuevas libertades, muchas medidas preventivas como llevar mascarilla, controles de temperatura o limitar el acceso a comunidades residenciales seguir\u00e1n en vigor en Wuhan. Y la gente que sale de la ciudad enfrentar\u00e1 numerosos obst\u00e1culos, como cuarentenas de 14 d\u00edas y ex\u00e1menes m\u00e9dicos en sus destinos.<\/p>\n<p style=\"text-align: justify;\"><strong>12\/12<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22888\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_12.jpeg\" width=\"1093\" height=\"729\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_12.jpeg 1093w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_12-300x200.jpeg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_12-1024x683.jpeg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/04\/wuhan_12-768x512.jpeg 768w\" sizes=\"(max-width: 1093px) 100vw, 1093px\" \/><\/p>\n<p style=\"text-align: justify;\">M\u00e9dicos que residen en otras provincias de China celebran en el aeropuerto antes de regresar a casa. Un editorial del diario oficial chino advirti\u00f3 que la gente no debe apresurarse a festejar. \u201cEste es el d\u00eda que el pueblo esperaba con tanta ansiedad y est\u00e1 bien alegrarse. Sin embargo, este d\u00eda no es el de la victoria final\u201d, escribi\u00f3 el diario.<\/p>\n<p style=\"text-align: justify;\"><em>Con informaci\u00f3n de Univision<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":22876,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Fotogaler\u00eda: As\u00ed se vivi\u00f3 el fin de la cuarentena del coronavirus en Wuhan, China - Opini\u00f3n P\u00fablica","description":"Wuhan, China .- Luego de 11 semanas de confinamiento la gente sali\u00f3 a la calle y miles subieron a los primeros trenes y aviones que partieron de la ciudad d\u00f3nde"},"footnotes":""},"categories":[15],"tags":[],"class_list":["post-22889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-galerias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/22889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=22889"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/22889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/22876"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=22889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=22889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=22889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}