{"id":21921,"date":"2020-01-13T07:00:00","date_gmt":"2020-01-13T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2020\/01\/13\/el-costa-concordia-una-historia-que-se-hunde-en-las-contradicciones-8-anos-despues\/"},"modified":"2020-01-13T07:00:00","modified_gmt":"2020-01-13T06:00:00","slug":"el-costa-concordia-una-historia-que-se-hunde-en-las-contradicciones-8-anos-despues","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/el-costa-concordia-una-historia-que-se-hunde-en-las-contradicciones-8-anos-despues\/","title":{"rendered":"El Costa Concordia: una historia que se hunde en las contradicciones 8 a\u00f1os despu\u00e9s"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-21919\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/01\/953d65378d220a7a21e874b82c8e9a03.jpg\" alt=\"\" class=\"caption\" title=\"El Costa Concordia se hundi\u00f3 el 13 de enero de 2012 por un error humano.\" width=\"656\" height=\"370\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/01\/953d65378d220a7a21e874b82c8e9a03.jpg 656w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/01\/953d65378d220a7a21e874b82c8e9a03-300x169.jpg 300w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\">Hace ya ocho a\u00f1o, el viernes 13 de enero, el crucero\u00a0<em>Costa Concordia\u00a0<\/em>choc\u00f3 contra las rocas\u00a0de la italiana isla de Giglio provocando el accidente naval m\u00e1s grave de los \u00faltimos a\u00f1os. En el barco viajaban\u00a04.229 personas, de ellas 3.209 viajeros de 62 nacionalidades, en su mayor parte italianos, franceses y alemanes. Tambi\u00e9n viajaban 177 espa\u00f1oles, 107 latinoamericanos y un andorrano.<\/p>\n<p style=\"text-align: justify;\">El capit\u00e1n del barco Francesco Schettino, de 52 a\u00f1os,\u00a0es detenido ese mismo s\u00e1bado\u00a0y acusado de homicidio culposo m\u00faltiple, naufragio y abandono del barco mientras muchos pasajeros a\u00fan se encontraban dentro de la nave.<\/p>\n<p style=\"text-align: justify;\"><strong>Enero 2012<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><img decoding=\"async\" class=\" size-full wp-image-21920\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/01\/costa.jpg\" width=\"660\" height=\"371\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/01\/costa.jpg 660w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2020\/01\/costa-300x169.jpg 300w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Viernes 13.\u00a0<\/strong>El crucero de lujo\u00a0<em>Costa Concordia<\/em>, encalla junto a la costa de la\u00a0isla italiana de Giglio. La nave\u00a0<strong>efectuaba un crucero por el Mediterr\u00e1neo<\/strong>, que sali\u00f3 del puerto de Civitavecchia (centro) con destino Savona (norte) para iniciar el viaje con escalas en Palermo (Sicilia), Cagliari (Cerde\u00f1a), Palma de Mallorca (Espa\u00f1a), Barcelona (Espa\u00f1a), Marsella (Francia) y regreso a Savona, seg\u00fan una nota de la compa\u00f1\u00eda naviera. Dos horas despu\u00e9s de<strong>\u00a0salir de Civitavecchia<\/strong>, hacia las 21.30 horas (20.30 GMT), cuando el buque estaba en las cercan\u00edas de la isla de Giglio y los pasajeros cenaban, se produjo el choque.<\/p>\n<p style=\"text-align: justify;\"><strong>S\u00e1bado 14.<\/strong>\u00a0Hallan\u00a0los primeros cad\u00e1veres\u00a0tras el naufragio. Adem\u00e1s, Francesco Schettino, capit\u00e1n del crucero,\u00a0es detenido. Schettino asegura que las rocas\u00a0<strong>no estaban en el mapa<\/strong>\u00a0que llevaba la embarcaci\u00f3n, pero la fiscal\u00eda le acusa de homicidio culposo m\u00faltiple, naufragio y abandono del barco. El equipo de salvamento italiano\u00a0rescata una pareja surcoreana\u00a0de 29 a\u00f1os (Hye Jim Jeong y Kideok Han) y a Marrico Giampetroni, jefe comisario de a bordo.<\/p>\n<p style=\"text-align: justify;\"><strong>Domingo 15.\u00a0<\/strong>A lo largo del fin de semana\u00a0<strong>el n\u00famero de fallecidos<\/strong>\u00a0se eleva a cinco,\u00a0uno de ellos espa\u00f1ol\u00a0e\u00a0identificado como Guillermo Gual, adem\u00e1s de dos franceses, un italiano y un peruano, heridos son cerca de medio centenar y los desaparecidos son 16.\u00a0Los primeros vuelos con supervivientes\u00a0espa\u00f1oles comienzan a llegar a Espa\u00f1a, entre quejas de la actuaci\u00f3n durante la evacuaci\u00f3n del barco.<\/p>\n<p style=\"text-align: justify;\"><strong>Lunes 16.<\/strong>Se devela que el capit\u00e1n del crucero\u00a0se acerc\u00f3 tanto a la isla de Giglio\u00a0para hacer \u00abuna reverencia\u00bb,\u00a0<strong>un regalo<\/strong>, a su jefe de camareros, natural de all\u00ed, y a un ex comandante de la naviera Costa Crucero. Empiezan a desvelarse\u00a0algunas inc\u00f3gnitas\u00a0del accidente.<\/p>\n<p style=\"text-align: justify;\"><strong>Martes 17.\u00a0<\/strong>Aumentan a 29 el n\u00famero de desaparecidos\u00a0y los buzos de los servicios de rescate italianos <strong>localizan otros cinco cad\u00e1veres.\u00a0<\/strong>Con estas cinco v\u00edctimas, el balance del naufragio se eleva a once fallecidos. Adem\u00e1s, la jueza de instrucci\u00f3n italiana Valeria Montesarchio\u00a0ordena el arresto domiciliario\u00a0para Francesco Schettino.<\/p>\n<p style=\"text-align: justify;\"><strong>Mi\u00e9rcoles 18.\u00a0<\/strong>La prensa italiana\u00a0transcribe las conversaciones\u00a0entre el capit\u00e1n Schettino, de 52 a\u00f1os, y la Capitan\u00eda de Puerto que desvelan que el comandante del nav\u00edo\u00a0<strong>abandon\u00f3 el barco<\/strong>\u00a0tras el accidente\u00a0sin cumplir su obligaci\u00f3n de coordinar\u00a0el desembarco de los n\u00e1ufragos. \u00abPuedo hacerle mucho da\u00f1o, le puedo meter en un verdadero l\u00edo. Vaya a bordo, cojones\u00bb, le exigieron a Schettino. \u00bfLa excusa del capit\u00e1n?\u00a0<strong>\u00abNo quer\u00eda huir, me ca\u00ed a un bote salvavidas\u00bb<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Jueves 19.\u00a0<\/strong>Mientras la polic\u00eda italiana buscaba a una mujer identificada como Domnica Cemortan,\u00a0de origen moldavo y unos 25 a\u00f1os, que acompa\u00f1aba en cabina al capit\u00e1n del Costa Concordia,\u00a0<strong>la joven aparece en una televisi\u00f3n moldava\u00a0<\/strong>asegurando que Schettino \u00abera un h\u00e9roe\u00bb y que estaba con \u00e9l en el momento del naufragio. Por su parte, la compa\u00f1\u00eda naviera Costa Cruceros,\u00a0propietaria del Costa Concordia, anuncia va a \u00abreembolsar el billete y el resto de gastos materiales\u00bb y\u00a0los buzos\u00a0vuelven a las tareas de rescate.<\/p>\n<p style=\"text-align: justify;\"><strong>Viernes 20.<\/strong>\u00a0El capit\u00e1n del\u00a0<em>Costa Concordia <\/em><a href=\"http:\/\/www.20minutos.es\/noticia\/1282913\/0\/costa-concordia\/capitan-cena\/choque\/\">pidi\u00f3 la cena para \u00e9l y Domnica<\/a> <strong>despu\u00e9s del choque<\/strong>\u00a0del crucero contra las rocas de la isla italiana de Giglio, seg\u00fan ha confesado el cocinero en una entrevista a la cadena filipina GMA. Rogelio Barista explica que el capit\u00e1n Francesco Schettino\u00a0<strong>solicit\u00f3 la comida casi una hora despu\u00e9s<\/strong>\u00a0del accidente, sobre las 22.30 horas.<\/p>\n<p style=\"text-align: justify;\"><strong>S\u00e1bado 21.\u00a0<\/strong>Los especialistas de la Marina Militar italiana<strong>\u00a0abren nuevas v\u00edas de acceso<\/strong>, mediante el uso de cargas explosivas.\u00a0Hallan un nuevo cad\u00e1ver, con lo que la cifra de fallecidos asciende a 12 una semana despu\u00e9s del accidente.<\/p>\n<p style=\"text-align: justify;\"><strong>Domingo 22.<\/strong>\u00a0Los medios italianos publican\u00a0<strong>nuevas declaraciones pol\u00e9micas\u00a0<\/strong>del capit\u00e1n del\u00a0<em>Concordia\u00a0<\/em>en las que dice que la maniobra de acercarse a la costa para \u00absaludar\u00bb era una\u00a0pr\u00e1ctica conocida por la naviera\u00a0y que las apoyaba como un sistema \u00abpublicitario\u00bb. Francesco Schettino asegura que ya la hab\u00eda realizado en m\u00e1s ocasiones, lo que contradice la versi\u00f3n del consejero delegado de la naviera, Pier Luigi Foschi, quien en los \u00faltimos d\u00edas dijo que tan solo hab\u00edan autorizado en una ocasi\u00f3n una maniobra de este estilo. Hallan otro cad\u00e1ver (una mujer) en la zona de popa y\u00a0se eleva a 13 el balance total de muertos.<\/p>\n<p style=\"text-align: justify;\"><strong>Lunes 23.<\/strong>\u00a0Protecci\u00f3n Civil cree que\u00a0<a href=\"http:\/\/www.20minutos.es\/noticia\/1284300\/0\/costa-concordia\/inmigrantes\/clandestinos\/\">a bordo del crucero naugrafado<strong>\u00a0viajaban tambi\u00e9n inmigrantes clandestinos<\/strong><\/a>, seg\u00fan ha publicado el diario italiano\u00a0<em>La Repubblica<\/em>. El jefe de los camareros del crucero, Manrico Giampedroni, descarta esta posibilidad: \u00abEs imposible, todos estaban registrados y fotografiados en el barco\u00bb, declar\u00f3. El abogado del capit\u00e1n dice a la prensa italiana que Schettino\u00a0<strong>ha dado negativo<\/strong>\u00a0en los test toxicol\u00f3gicos. Por otro lado, Los servicios de rescate localizaron\u00a0los cuerpos de otras dos mujeres, elevando a 15 el balance de v\u00edctimas mortales por el accidente.<\/p>\n<p style=\"text-align: justify;\"><strong>Martes 24.<\/strong>\u00a0Un d\u00eda despu\u00e9s de hallar dos mujeres muertas en el crucero, los servicios de rescate\u00a0localizan otro cad\u00e1ver m\u00e1s\u00a0y se eleva el balance total de v\u00edctimas a\u00a0<strong>16<\/strong>. Francesco Schettino\u00a0<a href=\"http:\/\/www.20minutos.es\/noticia\/1286068\/0\/capitan-costa-concordia\/test-drogas\/no-realizado\/\"><strong>todav\u00eda no ha realizado ning\u00fan test toxicol\u00f3gico<\/strong><\/a>, como aseguraba su abogado. El examen sobre un cabello y la orina del capit\u00e1n comenzar\u00e1 el 26 de enero y se necesitar\u00e1 un mes para conocer los resultados.<\/p>\n<p style=\"text-align: justify;\"><strong>S\u00e1bado 28. <\/strong>Localizan un nuevo cad\u00e1ver ubicado en la parte sumergida del puente n\u00famero 6 del barco. Adem\u00e1s, retrasaron debido al mal tiempo las labores de extracci\u00f3n de carburante del buque encallado.<\/p>\n<p style=\"text-align: justify;\"><strong>Febrero 2012<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Mi\u00e9rcoles 22<\/strong>.\u00a0Localizan los cad\u00e1veres de otras<strong>\u00a0ocho personas<\/strong>,\u00a0entre los cuerpos est\u00e1 el de la ni\u00f1a de cinco a\u00f1os<strong>\u00a0Dayana Arlotti,<\/strong>\u00a0que desapareci\u00f3 junto con su padre, William, de 36 a\u00f1os.<\/p>\n<p style=\"text-align: justify;\"><strong>Marzo de 2012<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Jueves 22.<\/strong>\u00a0Localizan, gracias a robots, los\u00a0cuerpos de otros tres fallecidos en el naufragio del buque. Los restos mortales estaban situados entre el casco del barco y el fondo del mar. El saldo oficial hasta ahora de<strong>\u00a0muertos es de 28.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Julio de 2012<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Martes 10.<\/strong>\u00a0Francesco Schettino, capit\u00e1n del crucero Costa Concordia, admite que \u201ces normal\u201d que tenga que pedir perd\u00f3n por el accidente que provoc\u00f3 la muerte de 30 personas y dej\u00f3 2 desaparecidos, pero tambi\u00e9n piensa que\u00a0\u00e9l es \u00abv\u00edctima de todo este sistema\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Octubre de 2012<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Mi\u00e9rcoles 10.<\/strong>\u00a0El capit\u00e1n del buque &#8216;Costa Concordia&#8217;, Francesco Schettino,\u00a0ha recurrido el despido que decret\u00f3 la naviera Costa Cruceros por el naufragio porque considera que \u00abno est\u00e1 justificado\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":21919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"El Costa Concordia: una historia que se hunde en las contradicciones 8 a\u00f1os despu\u00e9s - Opini\u00f3n P\u00fablica","description":"Hace ya ocho a\u00f1o, el viernes 13 de enero, el crucero\u00a0 Costa Concordia\u00a0 choc\u00f3 contra las rocas\u00a0de la italiana isla de Giglio provocando el accidente naval m\u00e1s gr"},"footnotes":""},"categories":[14],"tags":[],"class_list":["post-21921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/21921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=21921"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/21921\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/21919"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=21921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=21921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=21921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}