{"id":21333,"date":"2019-11-08T07:00:00","date_gmt":"2019-11-08T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2019\/11\/08\/aprueban-ubicacion-de-casillas-para-el-plebiscito-en-chihuahua\/"},"modified":"2019-11-08T07:00:00","modified_gmt":"2019-11-08T06:00:00","slug":"aprueban-ubicacion-de-casillas-para-el-plebiscito-en-chihuahua","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/aprueban-ubicacion-de-casillas-para-el-plebiscito-en-chihuahua\/","title":{"rendered":"Aprueban ubicaci\u00f3n de casillas para el plebiscito en Chihuahua"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-21332\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2019\/11\/ca25a015ca276dd7ae395249f4a22116.jpg\" alt=\"\" class=\"caption\" title=\"Habr\u00e1 188 urnas para el plebicito del alumbrado p\u00fablico en Chihuahua.\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2019\/11\/ca25a015ca276dd7ae395249f4a22116.jpg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2019\/11\/ca25a015ca276dd7ae395249f4a22116-300x169.jpg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2019\/11\/ca25a015ca276dd7ae395249f4a22116-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Chihuahua.-<\/em>\u00a0La ubicaci\u00f3n de las 188 mesas receptoras de votaci\u00f3n (MRV) en el plebiscito municipal de Chihuahua fue aprobada en la 14\u00aa Sesi\u00f3n Extraordinaria del Consejo Estatal del Instituto Estatal Electoral de Chihuahua (IEE).<\/p>\n<p style=\"text-align: justify;\">La gran mayor\u00eda de las MRVs (175 de las 188)\u00a0estar\u00e1n ubicadas en las escuelas; cuatro en domicilios particulares; tres en salones de actos; dos en salones ejidales; dos en oficinas p\u00fablicas y dos en parques.<\/p>\n<p style=\"text-align: justify;\">El listado completo de la ubicaci\u00f3n puede ser consultado en\u00a0<em>www.ieechihuahua.org.mx\/UbicaMRV<\/em><\/p>\n<p style=\"text-align: justify;\">S\u00f3lo hay que introducir el n\u00famero de la secci\u00f3n de tu credencial de elector y aparecer\u00e1 la direcci\u00f3n de la casilla en la que te corresponde votar en el plebiscito el domingo 24 de noviembre, as\u00ed mismo su ubicaci\u00f3n en el mapa digital.<\/p>\n<p style=\"text-align: justify;\">Cada mesa receptora de votaci\u00f3n tiene la capacidad de atenci\u00f3n de hasta cinco mil votantes, esto considerando la utilizaci\u00f3n de urna electr\u00f3nica para la recepci\u00f3n del voto.<\/p>\n<p style=\"text-align: justify;\">Las ubicaciones son de f\u00e1cil y libre acceso para la ciudadan\u00eda, aseguran la instalaci\u00f3n de mesas de trabajo y urnas electr\u00f3nicas, as\u00ed como la movilidad de funcionarios y sufragantes.<\/p>\n<p style=\"text-align: justify;\">Las condiciones de los inmuebles garantizan la libertad y secrec\u00eda del voto.<\/p>\n<p style=\"text-align: justify;\">Considerando la disponibilidad de las urnas electr\u00f3nicas (420 en total),\u00a0cada Mesa Receptora de Votaci\u00f3n podr\u00e1 contar con dos urnas, y habr\u00e1 una reserva de 44 urnas.<\/p>\n<p style=\"text-align: justify;\">En casa casilla habr\u00e1 tres funcionarios: presidente, secretario y escrutador, que son ciudadanas y ciudadanos voluntarios capacitados y designados por el IEE. Tambi\u00e9n podr\u00e1n estar una o un representante de quienes promueven el plebiscito, observadores de participaci\u00f3n ciudadana, persona auxiliar operador de urna.<\/p>\n<p style=\"text-align: justify;\">Igual que en las elecciones constitucionales,\u00a0para ejercer el voto en el plebiscito las ciudadanas y los ciudadanos tendr\u00e1n que presentarse con su credencial para votar vigente.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":21332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Aprueban ubicaci\u00f3n de casillas para el plebiscito en Chihuahua - Opini\u00f3n P\u00fablica","description":"Chihuahua.- \u00a0La ubicaci\u00f3n de las 188 mesas receptoras de votaci\u00f3n (MRV) en el plebiscito municipal de Chihuahua fue aprobada en la 14\u00aa Sesi\u00f3n Extraordinaria del"},"footnotes":""},"categories":[4],"tags":[],"class_list":["post-21333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pulsopolitico"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/21333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=21333"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/21333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/21332"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=21333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=21333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=21333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}