{"id":18445,"date":"2018-12-09T07:00:00","date_gmt":"2018-12-09T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2018\/12\/09\/lo-inapreciable\/"},"modified":"2018-12-09T07:00:00","modified_gmt":"2018-12-09T06:00:00","slug":"lo-inapreciable","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/lo-inapreciable\/","title":{"rendered":"Lo inapreciable"},"content":{"rendered":"<p style=\"text-align: justify;\">Empieza un nuevo gobierno, no la historia. Un gobierno que gan\u00f3 de manera indiscutible e indiscutida. Un potente hartazgo fue el caldo de cultivo de esta tercera alternancia en el ejecutivo en las \u00faltimas cuatro elecciones, aunado a la tenaz oposici\u00f3n y la vena popular de Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Se ha dicho y repetido: la corrupci\u00f3n tolerada y escasamente combatida, la inseguridad y la violencia crecientes, el d\u00e9bil crecimiento econ\u00f3mico que vulnera las expectativas de millones de j\u00f3venes que se incorporan a una vida laboral precaria, informal; en el marco de unas desigualdades sociales que no son de ahora ni de ayer, sino de siempre, generaron y con raz\u00f3n una recia ola de insatisfacci\u00f3n la cual fue explotada y conducida por quien hoy encabeza la Presidencia.<\/p>\n<p style=\"text-align: justify;\">Fue a trav\u00e9s de un m\u00e9todo civilizado que se expres\u00f3 ese malestar. Las elecciones, imparciales y equitativas, permitieron la contienda pac\u00edfica, institucional y participativa de la diversidad de opciones pol\u00edticas que coexisten en el pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Se dice f\u00e1cil, pero fue una construcci\u00f3n reciente la que posibilita que los humores p\u00fablicos refrenden o castiguen gobiernos, multiplicando los fen\u00f3menos de alternancia. El desgaste sucesivo de gobiernos del PRI y del PAN est\u00e1 a la vista. Y el gran reto del nuevo gobierno es el de lograr revertir esa situaci\u00f3n. Llega con un gran apoyo popular.<\/p>\n<p style=\"text-align: justify;\">Ha desatado expectativas e ilusiones para dar y prestar. Pero el \u201ccaldo de cultivo\u201d del deterioro de sus antecesores sigue ah\u00ed. Si avanza combatiendo la corrupci\u00f3n, atemperando la violencia y la inseguridad, generando crecimiento econ\u00f3mico e inclusi\u00f3n social el aprecio crecer\u00e1\u2026pero si no, puede sufrir un da\u00f1o similar al de los gobiernos anteriores.<\/p>\n<p style=\"text-align: justify;\">No obstante, hay algo que M\u00e9xico construy\u00f3 en las \u00faltimas d\u00e9cadas que me temo no se aprecia con suficiencia, en buena medida por el mal humor p\u00fablico alimentado por las patolog\u00edas enunciadas y algunas m\u00e1s. Existe un malestar tan grande por la vida pol\u00edtica que genera un desd\u00e9n por todo y por todos. No hay paciencia para distinguir.<\/p>\n<p style=\"text-align: justify;\">Se igualan instituciones (las que funcionan bien y las que lo hacen mal), se lanzan al viento descalificaciones gen\u00e9ricas y totalizantes, se compite por ver qui\u00e9n es m\u00e1s radical en las reprobaciones y no m\u00e1s exacto en el juicio. Un ambiente refractario al an\u00e1lisis matizado y a valorar lo que debe ser preservado y fortalecido, y si se quiere, reformado.<\/p>\n<p style=\"text-align: justify;\">Eso que el pa\u00eds edific\u00f3 en las \u00faltimas d\u00e9cadas fue una germinal democracia. Un espacio institucional en el que la diversidad pol\u00edtica del pa\u00eds puede vivir, coexistir y competir de manera regulada y pac\u00edfica. No fue una construcci\u00f3n impostada, todo lo contrario: un pa\u00eds de las dimensiones, la diversidad y la complejidad de M\u00e9xico solo cabe, para su convivencia, en un formato democr\u00e1tico.<\/p>\n<p style=\"text-align: justify;\">De ah\u00ed la pluralidad que se instal\u00f3 en los \u00f3rganos representativos, el fortalecimiento de las agrupaciones civiles, el complejo entramado de intermediaciones entre Estado y sociedad, la ampliaci\u00f3n de las libertades, las elecciones competidas y las recurrentes alternancias. No obstante, eso no es valorado con suficiencia ni por franjas m\u00e1s que numerosas de la sociedad, ni por quienes han sido usufructuarios directos de esas nuevas y venturosas realidades, entre ellos, al parecer, el gobierno que inicia.<\/p>\n<p style=\"text-align: justify;\">Por supuesto, cualquier partido o coalici\u00f3n de partidos leg\u00edtimamente puede aspirar a convertirse en una mayor\u00eda en los cuerpos de representaci\u00f3n. No obstante, es necesario subrayar que esas mayor\u00edas, en democracia, siempre ser\u00e1n y son contingentes, cambiantes.<\/p>\n<p style=\"text-align: justify;\">Que ninguna fuerza pol\u00edtica naci\u00f3 para ganar de manera eterna ni que las minor\u00edas est\u00e1n condenadas a serlo por siempre. Y que esa mec\u00e1nica cambiante entre unas y otras, producto de los alineamientos y realineamientos que se producen en la sociedad, debe contar con un marco normativo e institucional para expresarse. De tal suerte que ojal\u00e1 en los meses y a\u00f1os por venir no deterioremos o adelgacemos ese germinal entramado democr\u00e1tico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empieza un nuevo gobierno, no la historia. Un gobierno que gan\u00f3 de manera indiscutible e indiscutida. Un potente hartazgo fue el caldo de cultivo de esta tercera alternancia en el ejecutivo en las \u00faltimas cuatro elecciones, aunado a la tenaz oposici\u00f3n y la vena popular de Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"slim_seo":{"title":"Lo inapreciable - Opini\u00f3n P\u00fablica","description":"Empieza un nuevo gobierno, no la historia. Un gobierno que gan\u00f3 de manera indiscutible e indiscutida. Un potente hartazgo fue el caldo de cultivo de esta tercer"},"footnotes":""},"categories":[26],"tags":[],"class_list":["post-18445","post","type-post","status-publish","format-standard","hentry","category-de-chile-dulce-y-manteca-columna-invitada"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/18445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=18445"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/18445\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=18445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=18445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=18445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}