{"id":15656,"date":"2017-11-15T07:00:00","date_gmt":"2017-11-15T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2017\/11\/15\/fobaproa-el-fraude-que-endeudo-a-los-mexicanos-para-beneficiar-a-los-banqueros\/"},"modified":"2017-11-15T07:00:00","modified_gmt":"2017-11-15T06:00:00","slug":"fobaproa-el-fraude-que-endeudo-a-los-mexicanos-para-beneficiar-a-los-banqueros","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/fobaproa-el-fraude-que-endeudo-a-los-mexicanos-para-beneficiar-a-los-banqueros\/","title":{"rendered":"Fobaproa; el fraude que endeud\u00f3 a los mexicanos para beneficiar a los banqueros"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-15655\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2017\/11\/752ab50b0e2f6f31d16cf43aacd96ba5.jpg\" alt=\"\" class=\"caption\" title=\"Los ex presidentes Ernesto Zedillo y Carlos Salinas son considerados los responsables de este quebranto nacional.\" width=\"621\" height=\"435\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2017\/11\/752ab50b0e2f6f31d16cf43aacd96ba5.jpg 621w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2017\/11\/752ab50b0e2f6f31d16cf43aacd96ba5-300x210.jpg 300w\" sizes=\"(max-width: 621px) 100vw, 621px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Ciudad de M\u00e9xico<\/em>.- A principios de la d\u00e9cada de 1990, el gobierno del presidente Carlos Salinas de Gortari\u00a0privatiz\u00f3 la banca\u00a0y la entreg\u00f3 a un pu\u00f1ado de empresarios que comenzaron a\u00a0comprar bancos a un precio 3.48 veces mayor a su precio real, con cr\u00e9ditos de otros bancos. Esto incluso\u00a0ser\u00eda criticado por el mismo Salinas.<\/p>\n<p style=\"text-align: justify;\">Un proceso de privatizaci\u00f3n que de acuerdo con el investigador del Instituto de Investigaciones Jur\u00eddicas de la UNAM, Francisco Ibarra Palafox, autor del libro\u00a0La privatizaci\u00f3n de la banca en M\u00e9xico, se da como consecuencia de un acuerdo pol\u00edtico entre el PRI y PAN, posterior a las elecciones de 1988.<\/p>\n<p style=\"text-align: justify;\">Manejados por banqueros inexpertos, los bancos comenzaron a otorgar cr\u00e9ditos de alto riesgo sin que el gobierno hiciera nada para impedirlo.<\/p>\n<p style=\"text-align: justify;\">\u00abLas decisiones de cr\u00e9dito en los bancos las tomaban personas sin experiencia que con frecuencia otorgaban pr\u00e9stamos a los peores sujetos, que eran casi los \u00fanicos dispuestos a pagar las tasas exorbitantes de inter\u00e9s que prevalec\u00edan. La burbuja creci\u00f3 desmesuradamente, como lo muestra el crecimiento constante y sistem\u00e1tico, pero no siempre reconocido, de la cartera vencida y de la cartera mala en general\u00bb, se\u00f1al\u00f3 el polit\u00f3logo Luis Rubio en un texto titulado\u00a0<em>Fobaproa o las consecuencias de la ineptitud.<\/em><\/p>\n<p style=\"text-align: justify;\">Con la crisis econ\u00f3mica de 1994 y la devaluaci\u00f3n del peso, las tasas de inter\u00e9s se dispararon y los cr\u00e9ditos que mucha gente hab\u00eda solicitado para comprar una casa, un auto o emprender un negocio, se volvieron impagables. Esta situaci\u00f3n provoc\u00f3 la quiebra de los bancos y que el gobierno iniciara un proceso de rescate bancario al absorber los pasivos del Fondo Bancario de Protecci\u00f3n al Ahorro (Fobaproa), un fideicomiso privado creado en 1990 para proteger a la banca.<\/p>\n<p style=\"text-align: justify;\">\u00abAl iniciarse 1995, el notable repunte en las tasas de inter\u00e9s condujo a una gran cantidad de deudores a una situaci\u00f3n de insolvencia, quienes dejaron de pagar sus deudas con los bancos. Ante el riesgo de inminente quiebra de muchos bancos, el gobierno empez\u00f3 su pol\u00edtica de apoyos por medio del Fobaproa, otorgando l\u00edneas de cr\u00e9dito para compensar su falta de recuperaci\u00f3n de cartera. Entonces fue cuando se inici\u00f3 el uso del Fobaproa de manera ilegal, ya que ese fondo pas\u00f3 de ser un organismo privado (de los bancos), a transformarse en un instrumento del gobierno, sin existencia como tal en ninguna ley, pero mediante el cual el gobierno adquiri\u00f3 todo tipo de compromisos que terminaron en una deuda creciente\u00bb, explica Juan Moreno P\u00e9rez, doctor en historia econ\u00f3mica por la UCLA y quien fuera el principal asesor del PRD en el tema, en su libro\u00a0<em>Fobaproa: el costo del rescate bancario.<\/em><\/p>\n<p style=\"text-align: justify;\">Aunque existe un consenso entre los expertos de que el gobierno ten\u00eda que intervenir ante tal situaci\u00f3n, con el objetivo de salvar el dinero de los ahorradores, en el proceso se cometieron una serie de abusos y decisiones discrecionales que terminar\u00edan beneficiando a los banqueros y elevando sustancialmente el costo del rescate bancario.<\/p>\n<p style=\"text-align: justify;\">\u00abEl gobierno, en realidad, se comport\u00f3 como un administrador de los intereses de los grandes inversionistas, en especial de los extranjeros, y no como un aut\u00e9ntico representante de los intereses de la mayor\u00eda del pueblo mexicano. Desde ese enfoque, por supuesto que resulta razonable lo hecho por el gobierno, y justificable la frase del presidente Zedillo de que \u00abno ten\u00eda opci\u00f3n\u00bb. Pero la alternativa hubiera sido convocar a toda la sociedad para enfrentar eficazmente la crisis, priorizando la protecci\u00f3n de los dep\u00f3sitos de 99.75 de los ahorradores, que representa s\u00f3lo 44% del ahorro financiero. Sin embargo, no fue as\u00ed, el gobierno decidi\u00f3 que los tenedores extranjeros de\u00a0tesobonos no tuvieran ninguna p\u00e9rdida, acudiendo a financiamientos extraordinarios en el exterior para conseguirlo, lo cual fue muy\u00a0festinado por el gobierno de los Estados Unidos.<\/p>\n<p style=\"text-align: justify;\">Ese fue el inicio de la cadena que impidi\u00f3 un ajuste diferente. As\u00ed, el gobierno, que profesa un dogmatismo a favor del mercado, impidi\u00f3 que el mercado funcionara, e impuso una situaci\u00f3n que ha sido ficticia desde el principio hasta la fecha\u00bb, a\u00f1ade Moreno.<\/p>\n<p style=\"text-align: justify;\">De este modo, banqueros como Jorge Lankenau (Banca Conf\u00eda: 3 mil millones de d\u00f3lares), Carlos Cabal Peniche (Banco Uni\u00f3n-Cremi: 800 millones de d\u00f3lares) y \u00c1ngel Isidoro Rodr\u00edguez\u00a0<em>El Divino<\/em>(Banpa\u00eds: 400 millones de d\u00f3lares) fueron acusados de cometer diversos delitos al beneficiarse ilegalmente por el rescate bancario, al autoasignarse cr\u00e9ditos que de antemano sab\u00edan que no tendr\u00edan que pagar gracias a la intervenci\u00f3n de las autoridades.<\/p>\n<p style=\"text-align: justify;\">Pero los a\u00f1os siguientes, el problema segu\u00eda creciendo como una bola de nieve. Para lidiar con la crisis, el gobierno del entonces presidente Ernesto Zedillo mand\u00f3 al Congreso una iniciativa para convertir en deuda p\u00fablica los pasivos del Fobaproa, que en aquel entonces fueron calculados en 552 mil 300 millones de pesos. Aunque el gobierno estaba financiando de manera ilegal el rescate bancario (debido a que toda deuda p\u00fablica asumida por el gobierno deb\u00eda ser previamente aprobada por el Congreso), la ca\u00edda de los precios del petr\u00f3leo fueron la raz\u00f3n principal por la que el gobierno de Zedillo decidi\u00f3 reconocer el problema que hab\u00eda tratado de mantener oculto y mand\u00f3 una iniciativa de ley al Poder Legislativo para asumir el rescate bancario como deuda p\u00fablica.<\/p>\n<p style=\"text-align: justify;\">\u00abEl mecanismo para financiar de manera subrepticia el creciente costo del Fobaproa, exprimiendo fiscalmente a Pemex, se sostuvo mientras los petroprecios se mantuvieron elevados. Cuando el precio del petr\u00f3leo se derrumb\u00f3, a principios de 1998, el escondido mecanismo dise\u00f1ado para canalizar recursos hacia el rescate bancario dej\u00f3 de operar. Esa fue una de las razones que condujeron al presidente Zedillo a explicitar el problema del Fobaproa en marzo de 1998\u00bb, apunta Moreno.<\/p>\n<p style=\"text-align: justify;\">Tras meses de intenso debate, en que el gobierno intent\u00f3 justificar la medida para proteger el dinero de los ahorradores, el PRI y PAN\u00a0avalaron en diciembre de 1998\u00a0convertir en deuda p\u00fablica el rescate bancario mediante la creaci\u00f3n del Instituto para la Protecci\u00f3n del Ahorro Bancario, con la f\u00e9rrea oposici\u00f3n del PRD, partido que calific\u00f3 dicha acci\u00f3n como \u00abel fraude m\u00e1s grande en la historia del pa\u00eds\u00bb.<\/p>\n<p style=\"text-align: justify;\">De este modo, el Congreso aval\u00f3 una deuda de poco m\u00e1s de 600 mil millones de pesos que, en opini\u00f3n de Moreno, explica buena parte de la situaci\u00f3n financiera de Pemex se debe a la manera en que se exprimi\u00f3 a la paraestatal para pagar los pasivos del rescate bancario.<\/p>\n<p style=\"text-align: justify;\">\u00abLa pol\u00edtica de exprimir fiscalmente a Pemex, con el fin de financiar el rescate bancario, como se coment\u00f3 antes, fue mantenida durante los a\u00f1os siguientes a 1998. El r\u00e9gimen fiscal aplicado a Pemex dej\u00f3 a esa paraestatal sin recursos para invertir\u00bb, explica el especialista, quien apunta que a partir de ah\u00ed el gobierno impuls\u00f3 un mecanismo conocido como\u00a0Pidiregas\u00a0(Proyecto de Inversi\u00f3n de Infraestructura Productiva con Registro Diferido en el Gasto P\u00fablico),\u00a0proyectos de obra p\u00fablica financiada por el sector privado o social\u00a0y construidos por un privado o un tercero, que\u00a0hasta 2009 formaron\u00a0parte de la deuda oculta del gobierno mexicano.<\/p>\n<p style=\"text-align: justify;\">\u00abMediante ese mecanismo, la mayor parte de la inversi\u00f3n de Pemex, y tambi\u00e9n de la CFE, se ha efectuado recurriendo a fuentes de financiamiento privadas, registrando la deuda p\u00fablica contratada de manera \u00abdiferida\u00bb, es decir, maquillando la contabilidad de esas paraestatales, y con ello, la verdadera situaci\u00f3n de las finanzas p\u00fablicas\u00bb, explica Moreno.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con un informe de 1999 solicitado por la C\u00e1mara de Diputados al contador canadiense Michael Mackey (conocido como el\u00a0Informe Mackey), la laxa regulaci\u00f3n del sistema bancario gener\u00f3 \u00abuna amplia oportunidad para los nuevos propietarios de llevar a cabo actividades bancarias que involucraran operaciones irregulares y fraudulentas\u00bb, con lo cual, la mayor parte de las intervenciones del gobierno para rescatar a los bancos \u00abse dio debido a operaciones irregulares, fraudes potenciales o insolvencia\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00abDebido a la falta de estructura y los problemas significativos encontrados en algunos de los bancos con irregularidades, fraudes, pr\u00e9stamos con problemas, etc\u00e9tera, la efectividad del la intervenci\u00f3n y el programa de saneamiento es dif\u00edcil de evaluar\u00bb, destac\u00f3 el informe, el cual se realiz\u00f3 a pesar de que el gobierno ocult\u00f3 informaci\u00f3n clave para determinar la efectividad del rescate bancario y fincar responsabilidades a los culpables de defraudar al pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Mackey entreg\u00f3 al Congreso una lista con algunos nombres de los beneficiarios del Fobapora, misma que se mantuvo en secreto. A trav\u00e9s de unos hackers, el PRD logr\u00f3 romper el c\u00f3digo que manten\u00eda en secreto dicha lista, luego de que la clave para abrir dicha informaci\u00f3n depend\u00eda de que cada uno de los grupos parlamentarios que guardaban una parte de la contrase\u00f1a se pusieran de acuerdo para abrir dicha lista, cosa que nunca ocurri\u00f3, ante la negaci\u00f3n del PRI y el PAN.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con los nombres revelados por el partido del sol azteca, en la lista se\u00a0encontraban pol\u00edticos de alto perfil, incluyendo al\u00a0c\u00edrculo cercano\u00a0de Vicente Fox Quesada, que a la postre terminar\u00eda convertido en presidente de la Rep\u00fablica luego de que su intervenci\u00f3n fuera clave para que el PAN, cuyo dirigente nacional en aquel entonces era Felipe Calder\u00f3n, aprobara el Fobaproa.<\/p>\n<p style=\"text-align: justify;\">Muchos de los se\u00f1alamientos del informe Mackey fueron corroborados por la Auditor\u00eda Superior de la Federaci\u00f3n en\u00a02004, principalmente en lo referente a las m\u00faltiples irregularidades registradas en el Programa de Capitalizaci\u00f3n y Compra de Cartera (PCCC), el cual represent\u00f3 8.9% del costo fiscal total del rescate bancario. Dicho programa consisti\u00f3 \u00aben ayudar a las instituciones financieras a capitalizarse\u00bb, a\u00fan cuando \u00ablos bancos que participaron en el programa, presentaban \u00edndices de capitalizaci\u00f3n superiores a lo establecido en la norma vigente a esa fecha\u00bb. Es decir, que los bancos que participaron en este programa fueron intervenidos sin que legalmente hubiera necesidad de \u00abrescatarlos\u00bb.<\/p>\n<p style=\"text-align: justify;\">El informe de la Auditor\u00eda tambi\u00e9n se\u00f1al\u00f3 que 80% de los delitos del rescate bancario quedaron impunes por omisiones de las autoridades fiscales y la PGR.<\/p>\n<p style=\"text-align: justify;\">\u00abEntre las primeras observaciones que realiz\u00f3 fue la falta de elementos para determinar si los cr\u00e9ditos que hab\u00eda adquirido el Fobaproa en el PCCC exist\u00edan ilegalidades o irregularidades, por lo cual recomend\u00f3 al IPAB realizar una auditor\u00eda a los cr\u00e9ditos de la cartera originadora de los flujos\u00bb, se\u00f1al\u00f3 la ASF.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, los se\u00f1alamientos de la Auditor\u00eda provocaron que las diversas instituciones involucradas en el rescate bancario promovieran un juicio de garant\u00edas en contra de las revisiones que pretend\u00eda realizar el IPAB y demandaron a los despachos que hab\u00edan participado junto con el auditor Mackey en las revisiones ordenadas por la C\u00e1mara de Diputados. Esto con el fin de no proporcionar los papeles clave para realizar dichas auditor\u00edas. Tambi\u00e9n se entablaron acciones judiciales en contra del Banco de M\u00e9xico para no entregar la informaci\u00f3n correspondiente a los fideicomisos que administraban la cartera adquirida por el Fobaproa. A su vez, el presidente Vicente Fox \u00abpromovi\u00f3 dos controversias constitucionales en contra de la C\u00e1mara de Diputados y de la ASF por las recomendaciones a las observaciones que hab\u00eda hecho la ASF en las auditor\u00edas del PCCC\u00bb.<\/p>\n<p style=\"text-align: justify;\">Pero a pesar del proceso de rescate bancario, los bancos mexicanos terminaron siendo vendidos al capital extranjero, como la venta de Serf\u00edn a Grupo Santander a un precio de 12 mil 650 millones de pesos, aunque el costo fiscal del rescate de este fue de m\u00e1s de 172 mil millones de pesos.<\/p>\n<p style=\"text-align: justify;\">Otro caso es el de Banamex, banco que fue\u00a0intervenido\u00a0y saneado con recursos p\u00fablicos a\u00fan cuando no lo requer\u00eda. En 2001, Banamex fue vendido a Citigroup a trav\u00e9s de una\u00a0operaci\u00f3n bancaria avalada por el gobierno de Fox, que permiti\u00f3 eludir impuestos por 35 mil millones de pesos en perjuicio de los mexicanos.<\/p>\n<p style=\"text-align: justify;\">De este modo, la deuda que los mexicanos siguen pagando cada a\u00f1o por un fraude millonario, permiti\u00f3 a banqueros amasar fortunas inmensas en complicidad con el gobierno.<\/p>\n<p style=\"text-align: justify;\">\u00abNo cabe ni la menor duda de que hay muchos abusos en el manejo del Fobaproa. Desafortunadamente, esos se derivan de los incentivos que cre\u00f3 el mal llamado rescate bancario. Cuando todos los incentivos promov\u00edan la deshonestidad, mucha gente entr\u00f3 por la puerta grande y se sirvi\u00f3 sin recato\u00bb, asegur\u00f3 el polit\u00f3logo Luis Rubio, en un texto publicado por la revista\u00a0<em><u>Nexos<\/u><\/em>\u00a0en 1998.<\/p>\n<p style=\"text-align: justify;\">\u00abCiertamente hubo tratamiento diferenciado y favoritismos pero, en esencia, el problema del Fobaproa es uno de apilamiento de estupideces y su encubrimiento, circunstancias que hicieron f\u00e1cil la vida de los muchos vivales que se beneficiaron del Fobaproa. Esto ocurri\u00f3 b\u00e1sicamente por la arrogancia y falta de responsabilidad de las autoridades bancarias y hacendar\u00edas que crearon el entorno propicio para el abuso\u00bb, agregaba Rubio, actual presidente de CIDAC-M\u00e9xico Eval\u00faa.<\/p>\n<p style=\"text-align: justify;\">En 2009, el expresidente Zedillo reconoci\u00f3 que el rescate bancario en M\u00e9xico fue incluso mayor que el implementado por Estados Unidos tras la crisis financiera de 2008, la cual arranc\u00f3 con la quiebra de Lehman Brothers, el cuarto banco de inversi\u00f3n m\u00e1s grande de Estados Unidos.<\/p>\n<p style=\"text-align: justify;\">En el contexto de las campa\u00f1as electorales de 2006, el cineasta Luis Mandoki realiz\u00f3 un documental en torno a la figura de Andr\u00e9s Manuel L\u00f3pez Obrador, titulado\u00a0\u00bfQui\u00e9n es el se\u00f1or L\u00f3pez?, en el que se refleja la visi\u00f3n de un sector de la izquierda en torno al fen\u00f3meno del Fobaproa. En dicho documental, personajes como L\u00f3pez Obrador o el exlegislador perredista Pablo G\u00f3mez acusan al PRI y al PAN de pactar el rescate bancario a cambio de recibir favores del sector bancario con fines electorales.<\/p>\n<p style=\"text-align: justify;\">Pero los se\u00f1alamientos de fraude no se limitan a las acusaciones de la izquierda, ya que incluso algunos representantes del PAN, como el\u00a0exsenador Luis Alberto Rico Samaniego, se manifestaron en contra del posicionamiento de su partido y los t\u00e9rminos en que el gobierno realiz\u00f3 el rescate bancario, por lo cual, llam\u00f3 a no dejar impune el \u00abfraude\u00bb que esto represent\u00f3 para los mexicanos.<\/p>\n<p style=\"text-align: justify;\">Un millonario fraude cuyos costos siguen increment\u00e1ndose con el paso de los a\u00f1os y hasta la fecha permanece impune.<\/p>\n<p style=\"text-align: justify;\">Con informaci\u00f3n de HuffPost M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":15655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"Fobaproa; el fraude que endeud\u00f3 a los mexicanos para beneficiar a los banqueros - Opini\u00f3n P\u00fablica","description":"Ciudad de M\u00e9xico .- A principios de la d\u00e9cada de 1990, el gobierno del presidente Carlos Salinas de Gortari\u00a0privatiz\u00f3 la banca\u00a0y la entreg\u00f3 a un pu\u00f1ado de empre"},"footnotes":""},"categories":[3],"tags":[],"class_list":["post-15656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/15656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=15656"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/15656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/15655"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=15656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=15656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=15656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}