{"id":14898,"date":"2017-08-15T06:00:00","date_gmt":"2017-08-15T04:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2017\/08\/15\/mexico-esta-en-el-top-5-entre-los-paises-con-mas-flujo-de-dinero-ilicito-del-mundo\/"},"modified":"2017-08-15T06:00:00","modified_gmt":"2017-08-15T04:00:00","slug":"mexico-esta-en-el-top-5-entre-los-paises-con-mas-flujo-de-dinero-ilicito-del-mundo","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/mexico-esta-en-el-top-5-entre-los-paises-con-mas-flujo-de-dinero-ilicito-del-mundo\/","title":{"rendered":"M\u00e9xico est\u00e1 en el Top 5 entre los pa\u00edses con m\u00e1s flujo de dinero il\u00edcito del mundo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-14897\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2017\/08\/c90f9cb5b6c899b93e2212c4c36920a2.jpg\" alt=\"\" class=\"caption\" title=\"M\u00e9xico es un para\u00edso para quienes se dedican al lavado de dinero y actividades il\u00edcitas.\" width=\"494\" height=\"351\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2017\/08\/c90f9cb5b6c899b93e2212c4c36920a2.jpg 494w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2017\/08\/c90f9cb5b6c899b93e2212c4c36920a2-300x213.jpg 300w\" sizes=\"(max-width: 494px) 100vw, 494px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\"><em>Ciudad de M\u00e9xico<\/em>.- A pesar de los esfuerzos contra el lavado de dinero de la Secretar\u00eda de Hacienda, el caso del futbolista Rafael M\u00e1rquez y el cantante Juli\u00f3n \u00c1lvarez demuestra que existen flujos de dinero il\u00edcito en el sistema financiero mexicano.<\/p>\n<p style=\"text-align: justify;\">Pero, \u00bfqu\u00e9 cantidad de dinero ilegal que se mueve en M\u00e9xico? Sabemos que nuestro pa\u00eds uno de los tres con mayores flujos en el mundo.<\/p>\n<p style=\"text-align: justify;\">El capit\u00e1n de la Selecci\u00f3n Mexicana y el cantante chiapaneco aparecieron el mi\u00e9rcoles en una lista de la Oficina de Control de Bienes de Extranjeros del Departamento del Tesoro de Estados Unidos de personas que fungen como prestanombres del presunto narcotraficante Ra\u00fal Flores.<\/p>\n<p style=\"text-align: justify;\">Usar prestanombres es uno de los m\u00e9todos que utilizan los delincuentes para introducir recursos il\u00edcitos al sistema financiero mexicano -actividad mejor conocida como lavado de dinero-. Son personas que permiten que se registren bajo su nombre bienes que fueron adquiridos con dinero que proviene de una actividad ilegal.<\/p>\n<p style=\"text-align: justify;\">M\u00e9xico es el tercer pa\u00eds a nivel global con el mayor flujo de dinero il\u00edcito, solo debajo de China y Rusia, seg\u00fan un estudio de la firma Global Financial Integrity.<\/p>\n<p style=\"text-align: justify;\">En una d\u00e9cada, de 2004 a 2013, el flujo de dinero il\u00edcito fue de 52 mil 844 millones de d\u00f3lares en promedio por cada a\u00f1o. En Rusia fue en promedio 104 mil 977 mdd y en China de 139 mil 228 mdd.<\/p>\n<p style=\"text-align: justify;\">En el Top 5 de los pa\u00edses con mayores flujos de recursos il\u00edcitos tambi\u00e9n est\u00e1: India, con 51 mil 029 millones de d\u00f3lares en promedio, y Malasia, con 41 mil 854 mdd.<\/p>\n<p style=\"text-align: justify;\">El gobierno federal no ha revelado una cifra sobre el flujo de dinero il\u00edcito, pero s\u00ed reconoce que el lavo de dinero es un problema real y grande en el pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">\u00abSe considera que dicho monto es lo suficientemente significativo como para ameritar que la prevenci\u00f3n y combate al LD (Lavado de Dinero) sean una prioridad para el Estado mexicano\u00bb, se lee en el documento Evaluaci\u00f3n Nacional de Riesgos De Lavado de Dinero y Financiamiento Al Terrorismo en M\u00e9xico de 2015.<\/p>\n<p style=\"text-align: justify;\">Por tal motivo, concluye el documento, \u00abse considera que la amenaza que representan los recursos il\u00edcitos susceptibles de ser lavados en M\u00e9xico generados dentro de la jurisdicci\u00f3n es ALTA\u00bb.<\/p>\n<p style=\"text-align: justify;\">Para evitar que el dinero il\u00edcito entre al sistema financiero mexicano existe la Unidad de Inteligencia Financiera de la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico (UIF) -s\u00ed, los que se dedicaron a desentramar la red de operaciones de la maestra Elba Esther Gordillo-.<\/p>\n<p style=\"text-align: justify;\">Esta unidad recibe reportes y avisos de instituciones que conformar el sistema financiero mexicano, analiza la informaci\u00f3n recibida y detecta posibles conductas de lavado de dinero.<\/p>\n<p style=\"text-align: justify;\">Pero esta labor de investigaci\u00f3n es grand\u00edsima considerando que esta unidad revisa reportes de todas estas instituciones que conforman el sistema financiero mexicano:<\/p>\n<p style=\"text-align: justify;\">Y aunque la UIF ha revelado casos importantes de lavado de dinero, como el caso Elba Esther Gordillo, y contribuy\u00f3 a otros, como el de las empresas fantasmas de Javier Duarte, el dinero il\u00edcito sigue fluyendo en M\u00e9xico. (HuffPost M\u00e9xico)<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":14897,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"M\u00e9xico est\u00e1 en el Top 5 entre los pa\u00edses con m\u00e1s flujo de dinero il\u00edcito del mundo - Opini\u00f3n P\u00fablica","description":"Ciudad de M\u00e9xico .- A pesar de los esfuerzos contra el lavado de dinero de la Secretar\u00eda de Hacienda, el caso del futbolista Rafael M\u00e1rquez y el cantante Juli\u00f3n"},"footnotes":""},"categories":[3],"tags":[],"class_list":["post-14898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/14898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=14898"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/14898\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/14897"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=14898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=14898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=14898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}