{"id":10151,"date":"2016-12-15T07:00:00","date_gmt":"2016-12-15T06:00:00","guid":{"rendered":"https:\/\/www.opinionpublica.tv\/portada\/2016\/12\/15\/eu-reduce-condiciones-de-alianza-de-aeromexico-y-delta\/"},"modified":"2016-12-15T07:00:00","modified_gmt":"2016-12-15T06:00:00","slug":"eu-reduce-condiciones-de-alianza-de-aeromexico-y-delta","status":"publish","type":"post","link":"https:\/\/www.opinionpublica.tv\/portada\/eu-reduce-condiciones-de-alianza-de-aeromexico-y-delta\/","title":{"rendered":"EU reduce condiciones de alianza de Aerom\u00e9xico y Delta"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-10150\" src=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2016\/12\/11e67df7a25e08580ba8f841a9716bdb.jpg\" alt=\"\" width=\"1040\" height=\"528\" srcset=\"https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2016\/12\/11e67df7a25e08580ba8f841a9716bdb.jpg 1040w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2016\/12\/11e67df7a25e08580ba8f841a9716bdb-300x152.jpg 300w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2016\/12\/11e67df7a25e08580ba8f841a9716bdb-1024x520.jpg 1024w, https:\/\/www.opinionpublica.tv\/portada\/wp-content\/uploads\/2016\/12\/11e67df7a25e08580ba8f841a9716bdb-768x390.jpg 768w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/><br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\">Aerom\u00e9xico y Delta tendr\u00e1n que ceder hasta 28 horarios de vuelo a las aerol\u00edneas de bajo costo en aeropuertos de M\u00e9xico y Estados Unidos si quieren lograr su alianza, pero podr\u00e1n hacerlo en fases y con la posibilidad de que el n\u00famero de horarios a ceder se reduzca.<\/p>\n<p style=\"text-align: justify;\">En la resoluci\u00f3n final que dio el visto bueno a la alianza, el Departamento de Transporte de Estados Unidos (DOT, por sus siglas en ingl\u00e9s) solicit\u00f3 a las aerol\u00edneas socias ceder 24 horarios de aterrizaje y despegue \u2013conocidos como slots- en el Aeropuerto Internacional de la Ciudad de M\u00e9xico (AICM) y cuatro en el aeropuerto neoyorquino John F Kennedy (JFK) \u2013dos menos que en su propuesta inicial publicada en noviembre pasado-.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, de manera inmediata Aerom\u00e9xico y Delta ceder\u00e1n s\u00f3lo 14 pares de slots \u2013entre los que se incluyen los 8 pares solicitados por el regulador mexicano- y 2 pares en el JFK. Los pares restantes se requerir\u00e1n en una segunda fase si los competidores no logran tener asignaciones de horarios nuevos para la temporada de verano de 2018 en el JFK y en el AICM, que es una base de operaciones o hub para Aerom\u00e9xico pues desde ah\u00ed conecta varios de sus vuelos.<\/p>\n<p style=\"text-align: justify;\">\u201cEsto limitar\u00e1 la cesi\u00f3n requerida si el r\u00e9gimen de slots del AICM permite una competencia m\u00e1s robusta y promueve el uso eficiente, de acuerdo con las (Directrices Mundiales de Slots) WSG como lo paneado\u201d, subray\u00f3 el DOT en su resoluci\u00f3n final publicada el mi\u00e9rcoles pasado para otorgar la inmunidad antimonopolio a Delta y Aerom\u00e9xico, que les permitir\u00e1 concretar un joint venture para operar como si fueran una misma aerol\u00ednea.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, Aerom\u00e9xico, que controla alrededor de 45% de los slots en el AICM, y Delta no ser\u00e1n obligadas a ceder m\u00e1s de seis slots por hora en la franja saturada del AICM que va de las 7:00 a las 10:00 horas y podr\u00e1n elegir dos horarios que no sean consecutivos en dicha franja para que cedan no m\u00e1s de cuatro slots por hora.<\/p>\n<p style=\"text-align: justify;\">\u201cEsto permite a los competidores operar horarios que sean comercialmente viables y al mismo tiempo evita cualquier disrupci\u00f3n significativa a los horarios de los solicitantes del joint venture y la habilidad para operar un hub en el AICM\u201d, agreg\u00f3 el DOT.<\/p>\n<p style=\"text-align: justify;\">Los slots tendr\u00e1n que cederse a favor de las aerol\u00edneas de bajo costo y ser\u00e1 el AICM quien finalmente decida a que empresa otorgarlos, de acuerdo con la orden final del Departamento liderado por Anthony Foxx.<\/p>\n<p style=\"text-align: justify;\">\u201cLos remedios del Departamento en el AICM se han enfocado en la necesidad de vincular adecuadamente las redes de los competidores de bajo costo al AICM para disciplinar el joint venture en el mercado transfronterizo\u201d, puntualiz\u00f3 el regulador estadounidense.<\/p>\n<p style=\"text-align: justify;\">Esta flexibilizaci\u00f3n en las medidas ocurri\u00f3 luego de que las socias, el AICM y la Direcci\u00f3n General de Aeron\u00e1utica Civil argumentar\u00e1n en contra de la decisi\u00f3n inicial del regulador estadounidenses de pedir a las aerol\u00edneas ceder hasta 30 slots en el mercado de la Ciudad de M\u00e9xico y Nueva York \u2013JFK-.<\/p>\n<p style=\"text-align: justify;\">DOT reiter\u00f3 que la inmunidad antimonopolio otorgada ser\u00e1 limitada por un periodo de cinco a\u00f1os. Terminado este tiempo, las aerol\u00edneas podr\u00e1n renovarlo tras un an\u00e1lisis de la alianza y su beneficio al consumidor, as\u00ed como los efectos en los competidores en el AICM.<\/p>\n<p style=\"text-align: justify;\">Informaci\u00f3n de Expansi\u00f3n<\/p>\n<p style=\"text-align: justify;\">Aerom\u00e9xico y Delta tendr\u00e1n hasta el 23 de diciembre para aceptar o rechazar las condiciones de esta orden final. La aerol\u00ednea que dirige Andr\u00e9s Conesa analiza las condiciones previstas en la resoluci\u00f3n final, de acuerdo con un comunicado enviado al p\u00fablico inversionista.<\/p>\n<p style=\"text-align: justify;\">La nueva alianza, valuada en unos 1,500 millones de d\u00f3lares, les permitir\u00e1 acordar precios que resultar\u00edan m\u00e1s baratos para los usuarios \u2013seg\u00fan ha reiterado Aerom\u00e9xico-, vuelos, inversiones en instalaciones aeroportuarias y estrategias de promoci\u00f3n. Adem\u00e1s les permitir\u00e1 ampliar su red de destinos entre M\u00e9xico y Estados Unidos, esto de cara al convenio bilateral a\u00e9reo entre ambas naciones, que entr\u00f3 en vigor en agosto pasado.<\/p>\n<p style=\"text-align: justify;\">El convenio bilateral a\u00e9reo desregula al sector y permite a las empresas concentrarse de manera legal y competir en el mercado como si fueran una sola compa\u00f1\u00eda en la operaci\u00f3n \u2013una figura conocida como Inmunidad Antimonopolio o ATI, por sus siglas en ingl\u00e9s-.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con el DOT, Aerom\u00e9xico y Delta concentrar\u00edan alrededor de 81% del tr\u00e1fico de pasajeros de origen y destino en la ruta AICM-JFK. Al cierre de marzo de 2015, Aerom\u00e9xico dominaba la ruta JFK-AICM con 56% de la participaci\u00f3n del tr\u00e1fico, mientras Delta controlaba una cuarta parte. Los dos restantes participantes son la mexicana Interjet (17%) y American Arilines (2%).<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":10150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"slim_seo":{"title":"EU reduce condiciones de alianza de Aerom\u00e9xico y Delta - Opini\u00f3n P\u00fablica","description":"Aerom\u00e9xico y Delta tendr\u00e1n que ceder hasta 28 horarios de vuelo a las aerol\u00edneas de bajo costo en aeropuertos de M\u00e9xico y Estados Unidos si quieren lograr su al"},"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/10151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/comments?post=10151"}],"version-history":[{"count":0,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/posts\/10151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media\/10150"}],"wp:attachment":[{"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/media?parent=10151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/categories?post=10151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opinionpublica.tv\/portada\/wp-json\/wp\/v2\/tags?post=10151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}